{"id":527337,"date":"2024-03-04T13:50:43","date_gmt":"2024-03-04T17:50:43","guid":{"rendered":"https:\/\/casadecampoliving.com\/?p=527337"},"modified":"2024-03-04T16:55:19","modified_gmt":"2024-03-04T20:55:19","slug":"xxvi-fin-de-semana-hogar-del-nino","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","title":{"rendered":"XXVI Fin de Semana Hogar del Ni\u00f1o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se une por una buena causa. Ahora en su vig\u00e9simo s\u00e9ptimo a\u00f1o, este evento se erige como un faro de esperanza, convocando a individuos y empresas para apoyar iniciativas educativas, sociales y de salud beneficiando a miles de ni\u00f1as, ni\u00f1os y j\u00f3venes de La Romana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527326\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-25-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Celebrado en La Romana Country Club, el d\u00eda se desarroll\u00f3 con una amplia variedad de actividades atractivas que satisfac\u00edan diversos intereses. Desde los torneos tradicionales de golf y tenis hasta sesiones serenas de yoga, los invitados se deleitaron con una variedad de actividaded que inclu\u00edan animados partidos de p\u00e1del, emocionantes enfrentamientos de pickleball y un taller de reciclaje dirigido por la artista Jaqueline Severino.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527296\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-11-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Al caer la noche, el Country Club dio la bienvenida a los asistentes a una deliciosa cena meticulosamente elaborada por el equipo gastron\u00f3mico del club. La noche alcanz\u00f3 su punto culminante con los ritmos contagiosos de The Boba Band acompa\u00f1ada por Adalgisa Pantale\u00f3n, mientras los invitados pasaban a la pista de baile, transformando el ambiente en una celebraci\u00f3n electrizante del altruismo y la camarader\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xiomara Men\u00e9ndez D\u00e1jer, presidenta del PBO, extendi\u00f3 su m\u00e1s sincero agradecimiento a la comunidad, reconociendo el apoyo inquebrantable de familias, amigos y entidades patrocinadoras cuyas contribuciones alimentan la misi\u00f3n transformadora de la organizaci\u00f3n. \u00abJuntos, hemos logrado hitos profundos en la mejora de la educaci\u00f3n y el bienestar de los ni\u00f1os de La Romana\u00bb, dijo Men\u00e9ndez D\u00e1jer, enfatizando el papel crucial de la acci\u00f3n colectiva en efectuar un cambio positivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527312\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En reconocimiento a la dedicaci\u00f3n y habilidad de los participantes, se entregaron premios a los ganadores de las actividades del d\u00eda, destacando la competencia amistosa y el compromiso compartido con la filantrop\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Fue realmente una noche llena de maravillas, celebrando una causa hermosa! No podemos esperar para el Fin de Semana del Hogar del Ni\u00f1o del pr\u00f3ximo a\u00f1o y esperamos ver a m\u00e1s personas participando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Fotos tomadas durante la cena\/ceremonia de premios por Mairobi Herrera<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527294\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527294\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527286\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527286\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-27-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527332\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527332\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-24-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527328\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527328\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-23-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527334\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527334\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-22-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527292\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527292\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-20-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527310\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527310\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-19-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527280\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527280\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-18-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527306\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527306\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-17-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527300\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527300\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-16-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527302\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527302\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-15-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527314\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527314\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-14-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527298\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527298\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-13-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527324\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527324\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-12-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527330\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527330\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-10-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527308\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527308\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-9-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527288\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527288\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-8-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527304\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527304\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-7-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527282\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527282\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-6-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"527316\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-527316\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=1320%2C880&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-5-1024x682.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527322\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527322\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-4-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527290\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527290\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-3-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527320\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527320\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-2-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" data-id=\"527284\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=682%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-527284\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=682%2C1024&amp;ssl=1 682w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1.jpg?w=1333&amp;ssl=1 1333w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-1-682x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se une por una buena causa. Ahora en su vig\u00e9simo s\u00e9ptimo a\u00f1o, este evento se erige como un faro de esperanza, convocando a individuos y empresas para apoyar iniciativas educativas, sociales y de [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":527318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"large","newspack_post_subtitle":"Las comunidades de Casa de Campo y de La Romana se unen en apoyo de la educaci\u00f3n, la salud y los programas sociales en beneficio de la juventud de La Romana","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26392,2528,2522,2514,2516],"tags":[23815,3626,3375,24346,27138,23828,7701],"newspack_spnsrs_tax":[],"class_list":["post-527337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-resort-villas","category-country-club-la-romana-es","category-eventos-es","category-fundaciones-es","category-hogar-del-nino-es","tag-casa-de-campo-es-17","tag-casa-de-campo-es","tag-eventos-y-actividades","tag-featured-es","tag-hogar-del-nino-es-2","tag-patronato-benefico-oriental-es-2","tag-patronato-benefico-oriental-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T17:50:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T20:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"XXVI Fin de Semana Hogar del Ni\u00f1o\",\"datePublished\":\"2024-03-04T17:50:43+00:00\",\"dateModified\":\"2024-03-04T20:55:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/\"},\"wordCount\":382,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1\",\"keywords\":[\"Casa de Campo\",\"casa de campo @es\",\"eventos y actividades\",\"Featured\",\"Hogar del Ni\u00f1o @es\",\"patronato ben\u00e9fico oriental\",\"patronato benefico oriental @es\"],\"articleSection\":[\"Casa de Campo Resort &amp; Villas\",\"Country Club La Romana\",\"Eventos\",\"Fundaciones\",\"Hogar del Ni\u00f1o @es\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/\",\"name\":\"XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1\",\"datePublished\":\"2024-03-04T17:50:43+00:00\",\"dateModified\":\"2024-03-04T20:55:19+00:00\",\"description\":\"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/xxvi-fin-de-semana-hogar-del-nino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XXVI Fin de Semana Hogar del Ni\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living","description":"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","og_locale":"es_ES","og_type":"article","og_title":"XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living","og_description":"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se","og_url":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2024-03-04T17:50:43+00:00","article_modified_time":"2024-03-04T20:55:19+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"XXVI Fin de Semana Hogar del Ni\u00f1o","datePublished":"2024-03-04T17:50:43+00:00","dateModified":"2024-03-04T20:55:19+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/"},"wordCount":382,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1","keywords":["Casa de Campo","casa de campo @es","eventos y actividades","Featured","Hogar del Ni\u00f1o @es","patronato ben\u00e9fico oriental","patronato benefico oriental @es"],"articleSection":["Casa de Campo Resort &amp; Villas","Country Club La Romana","Eventos","Fundaciones","Hogar del Ni\u00f1o @es"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","url":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","name":"XXVI Fin de Semana Hogar del Ni\u00f1o | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1","datePublished":"2024-03-04T17:50:43+00:00","dateModified":"2024-03-04T20:55:19+00:00","description":"El 17 de febrero de 2023, el dedicado equipo del Patronato Ben\u00e9fico Oriental organiz\u00f3 otro fant\u00e1stico evento ben\u00e9fico, mostrando c\u00f3mo nuestra comunidad se","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"XXVI Fin de Semana Hogar del Ni\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"XXVI Fin de Semana Hogar del Ni\u00f1o","url":"http:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1"},"articleSection":"Casa de Campo Resort &amp; Villas","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo","casa de campo @es","eventos y actividades","featured","hogar del ni\u00f1o @es","patronato ben\u00e9fico oriental","patronato benefico oriental @es"],"dateCreated":"2024-03-04T17:50:43Z","datePublished":"2024-03-04T17:50:43Z","dateModified":"2024-03-04T20:55:19Z"},"rendered":"<meta name=\"parsely-title\" content=\"XXVI Fin de Semana Hogar del Ni\u00f1o\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/xxvi-fin-de-semana-hogar-del-nino\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2024-03-04T17:50:43Z\" \/>\n<meta name=\"parsely-section\" content=\"Casa de Campo Resort &amp; Villas\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo,casa de campo @es,eventos y actividades,featured,hogar del ni\u00f1o @es,patronato ben\u00e9fico oriental,patronato benefico oriental @es\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":525582,"url":"https:\/\/casadecampoliving.com\/es\/reserva-la-fecha-se-acerca-el-xxvii-fin-de-semana-anual-del-hogar-del-nino\/","url_meta":{"origin":527337,"position":0},"title":"\u00a1Reserva la Fecha! Se Acerca el XXVII Fin de Semana Anual del Hogar del Ni\u00f1o","author":"Casa de Campo Living","date":"3 Ene, 2024","format":false,"excerpt":"Casa de Campo se prepara para otro a\u00f1o de generosidad y diversi\u00f3n comunitaria con el muy esperado XXVII Fin de Semana Anual del Hogar del Ni\u00f1o, programado para el 17 de febrero. Un evento que combina perfectamente el entretenimiento con una noble causa, esta recaudaci\u00f3n de fondos promete un d\u00eda\u2026","rel":"","context":"En \u00abCasa de Campo Resort &amp; Villas\u00bb","block_context":{"text":"Casa de Campo Resort &amp; Villas","link":"https:\/\/casadecampoliving.com\/es\/category\/casa-de-campo-resort-villas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports16.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports16.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports16.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports16.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports16.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":354294,"url":"https:\/\/casadecampoliving.com\/es\/el-patronato-benefico-oriental-celebra-otro-exitoso-torneo-golf-solidario-hogar-del-nino-2022\/","url_meta":{"origin":527337,"position":1},"title":"El Patronato Ben\u00e9fico Oriental celebra otro exitoso torneo \u201cGolf Solidario Hogar del Ni\u00f1o 2022\u201d","author":"Casa de Campo Living","date":"28 Feb, 2022","format":false,"excerpt":"El pasado 19 de febrero, el Patronato Ben\u00e9fico Oriental, Inc. (PBO) celebr\u00f3 su tradicional evento anual de recaudaci\u00f3n de fondos, el torneo \u201cGolf Solidario Hogar del Ni\u00f1o 2022\u201d que en este a\u00f1o llega a su vigesimoquinta edici\u00f3n. Los jugadores de golf se reunieron desde la 7:30 de la ma\u00f1ana en\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_0968Bdc-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_0968Bdc-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_0968Bdc-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_0968Bdc-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":526734,"url":"https:\/\/casadecampoliving.com\/es\/el-conteo-regresivo-ha-comenzado-unase-a-nosotros-este-sabado-para-el-xxvii-fin-de-semana-anual-del-hogar-del-nino\/","url_meta":{"origin":527337,"position":2},"title":"El conteo regresivo ha comenzado: \u00danase a nosotros este s\u00e1bado para el XXVII Fin de Semana Anual del Hogar del Ni\u00f1o","author":"Casa de Campo Living","date":"12 Feb, 2024","format":false,"excerpt":"Casa de Campo y el Patronato Ben\u00e9fico Oriental (PBO) se est\u00e1n preparando para el 27\u00ba Fin de Semana Anual del Hogar del Ni\u00f1o, que se llevar\u00e1 a cabo ESTE s\u00e1bado, 17 de febrero. Este evento tan esperado combina entretenimiento con filantrop\u00eda, prometiendo un d\u00eda de camarader\u00eda y compasi\u00f3n en La\u2026","rel":"","context":"En \u00abCasa de Campo Resort &amp; Villas\u00bb","block_context":{"text":"Casa de Campo Resort &amp; Villas","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-resort-villas-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports22.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports22.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports22.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports22.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/02\/XXVI-Hogar-del-Nin%CC%83o-Weekend-Sports22.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":353660,"url":"https:\/\/casadecampoliving.com\/es\/marque-la-fecha-en-su-calendario-para-la-23a-edicion-del-fin-de-semana-hogar-del-nino\/","url_meta":{"origin":527337,"position":3},"title":"\u00a1Marque la fecha en su calendario para la 23\u00aa edici\u00f3n del Fin de Semana Hogar del Ni\u00f1o!","author":"Casa de Campo Living","date":"3 Ene, 2020","format":false,"excerpt":"\u00a1El a\u00f1o nuevo acaba de comenzar y ya tenemos eventos para anotar en nuestro calendario! El 23\u00aa fin de semana anual del Hogar del Ni\u00f1o se llevar\u00e1 a cabo los d\u00edas 14 y 15 de febrero, es la manera perfecta de pasar un buen rato y ser caritativo. Casa de\u2026","rel":"","context":"En \u00abCountry Club La Romana\u00bb","block_context":{"text":"Country Club La Romana","link":"https:\/\/casadecampoliving.com\/es\/category\/country-club-la-romana-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_2738.jpg?fit=1000%2C658&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_2738.jpg?fit=1000%2C658&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_2738.jpg?fit=1000%2C658&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_2738.jpg?fit=1000%2C658&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":537034,"url":"https:\/\/casadecampoliving.com\/es\/xxviii-hogar-del-nino-weekend-all-set-for-feb-15\/","url_meta":{"origin":527337,"position":4},"title":"XXVIII Hogar del Ni\u00f1o Weekend Listo para el 15 de Febrero","author":"Casa de Campo Living","date":"3 Feb, 2025","format":false,"excerpt":"El Patronato Ben\u00e9fico Oriental (PBO) celebrar\u00e1 la XXVIII edici\u00f3n del Hogar del Ni\u00f1o Weekend el 15 de febrero de 2025 en La Romana Country Club. Este esperado evento ben\u00e9fico recauda fondos para el Hogar del Ni\u00f1o, un centro educativo y de cuidado infantil que brinda servicios esenciales a m\u00e1s de\u2026","rel":"","context":"En \u00abCasa de Campo Resort &amp; Villas\u00bb","block_context":{"text":"Casa de Campo Resort &amp; Villas","link":"https:\/\/casadecampoliving.com\/es\/category\/casa-de-campo-resort-villas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-21.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":353968,"url":"https:\/\/casadecampoliving.com\/es\/guarde-la-fecha-para-el-xxiv-torneo-de-golf-hogar-del-nino-de-este-ano\/","url_meta":{"origin":527337,"position":5},"title":"\u00a1Guarde la fecha para el XXIV Torneo de Golf Hogar del Ni\u00f1o de este a\u00f1o!","author":"Casa de Campo Living","date":"31 Ene, 2021","format":false,"excerpt":"Los eventos deportivos relacionados con la caridad en Casa de Campo no son una rareza. El golf es de hecho un pasatiempo popular que ofrece una excelente manera de disfrutar del aire libre, es un gran deporte para practicar durante estos tiempos que requieren distanciamiento social y une a las\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3075-1.jpg?fit=1000%2C603&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3075-1.jpg?fit=1000%2C603&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3075-1.jpg?fit=1000%2C603&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3075-1.jpg?fit=1000%2C603&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/03\/2024_HogardelNinoWeeken_dinner-26.jpg?fit=2000%2C1333&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/527337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=527337"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/527337\/revisions"}],"predecessor-version":[{"id":527338,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/527337\/revisions\/527338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/527318"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=527337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=527337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=527337"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=527337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}