{"id":518228,"date":"2023-06-05T13:56:22","date_gmt":"2023-06-05T17:56:22","guid":{"rendered":"https:\/\/casadecampoliving.com\/?p=518228"},"modified":"2023-06-05T14:16:24","modified_gmt":"2023-06-05T18:16:24","slug":"wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","title":{"rendered":"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u00abUniverso Multicolor\u00bb del artista Eddie Mosler"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano Eddie Mosler, conocido por sus trazos audaces y gestuales que evocan la energ\u00eda arrolladora creada por galaxias, estrellas y planetas, a partir del 17 de junio a las 7 pm en WAO Gallery en Altos de Chav\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUniverso Multicolor\u00bb es una creaci\u00f3n \u00fanica del artista. Esta cautivadora colecci\u00f3n trasciende los l\u00edmites convencionales del arte para sumergirnos en un viaje c\u00f3smico lleno de color, energ\u00eda y misterio.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Esta exhibici\u00f3n consta de 29 piezas creadas por el artista que nos invita a sumergirnos en la magia del arte y explorar nuestro propio universo interior. Cada obra de arte es un portal hacia infinitas posibilidades, donde la imaginaci\u00f3n se desata y la belleza se encuentra en cada rinc\u00f3n. Esta colecci\u00f3n nos recuerda que el arte es un viaje personal y que, a trav\u00e9s del color y la energ\u00eda, podemos encontrar una conexi\u00f3n profunda con el cosmos que nos rodea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta exhibici\u00f3n, Mosler busca canalizar las profundidades del universo y explorar la conexi\u00f3n entre el color y el origen de nuestra existencia. \u00abCada obra de arte es una ventana hacia un vasto paisaje c\u00f3smico, donde las explosiones de pigmentos y las formas fluidas se entrelazan en una danza sinuosa de vitalidad y emoci\u00f3n\u00bb, nos cuenta el artista.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"747\" height=\"1024\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=747%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-518221 size-full\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=747%2C1024&amp;ssl=1 747w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=219%2C300&amp;ssl=1 219w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=768%2C1053&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=1120%2C1536&amp;ssl=1 1120w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=400%2C548&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?resize=150%2C206&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3.jpeg?w=1167&amp;ssl=1 1167w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-3-747x1024.jpeg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El color es el lenguaje principal de esta colecci\u00f3n, y Mosler lo maneja con maestr\u00eda. Desde tonos intensos y saturados hasta sutiles gradaciones, cada matiz es una expresi\u00f3n \u00fanica que nos recuerda emociones y sensaciones. Rojos ardientes, azules profundos, verdes radiantes y amarillos brillantes se entrelazan en un torbellino de tonalidades que nos transporta m\u00e1s all\u00e1 de nuestra realidad cotidiana hacia un plano de asombro y maravilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El artista dice: \u00abA medida que exploramos las obras, descubrimos una rica textura y una dimensi\u00f3n que desaf\u00edan nuestra percepci\u00f3n. El uso de diversos materiales y t\u00e9cnicas da vida a un universo tridimensional donde las formas emergen y se disuelven en un constante juego de luces y sombras. Las pinceladas vigorosas y los trazos expresivos capturan la esencia de la energ\u00eda en movimiento, mientras que las capas de pintura superpuestas crean profundidad y complejidad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n permanecer\u00e1 abierta del 17 de junio al 17 de julio de 2023, de mi\u00e9rcoles a s\u00e1bado de 9:00 am a 9:00 pm, domingos y martes de 9:00 am a 5:00 pm, y los lunes estar\u00e1 cerrada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Programas del Patronato Ben\u00e9fico Oriental, Inc. (PBO)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Patronato Ben\u00e9fico Oriental, Inc. (PBO) contin\u00faa su compromiso con iniciativas sostenibles de impacto social para promover la cultura. Como parte de esto, ha complementado sus programas con las iniciativas de WAO Chav\u00f3n, que incluyen WAO Innovation HUB, WAO Gallery &amp; Cultural Center y el Museo Arqueol\u00f3gico Regional de Altos de Chav\u00f3n, en Altos de Chav\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ganancias de los diferentes proyectos y actividades se destinan a nuestros programas sociales para poder replicar estas iniciativas en comunidades vulnerables a las que servimos como parte de los programas de empoderamiento comunitario del PBO, promoviendo valores que se alinean con nuestra misi\u00f3n, como el respeto, la solidaridad, la integridad y la igualdad de oportunidades.\u00e7<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sobre el artista:<\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-518225 size-full\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=400%2C500&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?resize=150%2C188&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-819x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Eddie Mosler naci\u00f3 en Quito, Ecuador, el 17 de enero de 1975. Comenz\u00f3 a hacer sus primeros bocetos a la temprana edad de cinco a\u00f1os. Como artista visual autodidacta, su visi\u00f3n art\u00edstica \u00fanica y original y su estilo abstracto le han valido reconocimiento en Ecuador, Am\u00e9rica y Europa. Sus colecciones han sido destacadas, incluyendo Armon\u00eda Infinita, Percepci\u00f3n Astral, Contemplaci\u00f3n C\u00f3smica, Expansi\u00f3n de Luz, Conciencia Dimensional, Esp\u00edritu del Oro, Pir\u00e1mide \u00c1urica, Portal 22 y Portal 33.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En 2019, inspirado por el oro, un metal apreciado por las antiguas civilizaciones, Mosler desarroll\u00f3 la colecci\u00f3n \u00abEsp\u00edritu del Oro\u00bb, incorporando su t\u00e9cnica de \u00abOro Activado\u00bb, \u00f3leo, acr\u00edlico, fuego y otros elementos. Representa un ambiente creativo donde reconoce la presencia de la divinidad y su conexi\u00f3n con los seres humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 27 de septiembre de 2020, Eddie lanz\u00f3 su colecci\u00f3n \u00abPir\u00e1mide \u00c1urica\u00bb en un evento celebrado para \u00abLa Sanaci\u00f3n del Mundo\u00bb en el monumento \u00abMitad del Mundo\u00bb en Ecuador, para todo el planeta. Fue un evento donde present\u00f3 las propiedades y beneficios de su arte en los procesos de sanaci\u00f3n y conexi\u00f3n con el universo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abA lo largo de mi carrera art\u00edstica, me he enfocado en el origen del color. Como resultado de este trabajo, se me han manifestado portales y he podido dise\u00f1ar estructuras dimensionales para tener una mejor conexi\u00f3n con el universo. Esta conexi\u00f3n me gu\u00eda para crear el dise\u00f1o de una estructura art\u00edstica para la ascensi\u00f3n astral y la frecuencia \u00e1urica para la evoluci\u00f3n de la humanidad en la luz. Esta estructura art\u00edstica se basa en un portal de creaci\u00f3n \u00e1urica compuesto por nueve colores \u00e1uricos, nueve figuras geom\u00e9tricas y nueve pilares de luz conectados con la frecuencia del Oro Astral en la 17\u00aa dimensi\u00f3n\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=576%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-518215\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=400%2C711&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?resize=150%2C267&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/IMG-20230601-WA0074-576x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano Eddie Mosler, conocido por sus trazos audaces y gestuales que evocan la energ\u00eda arrolladora creada por galaxias, estrellas y planetas, a partir del 17 de junio a las 7 pm en WAO Gallery [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":518218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","newspack_content_restriction_is_exempt":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"large","newspack_post_subtitle":"Esta exhibici\u00f3n consta de 29 piezas creadas por el artista que invita al espectador a sumergirse en la magia del arte y explorar su universo interior.","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2498],"tags":[27100,2733,2536,3469,3626,2575,24346,7701],"newspack_spnsrs_tax":[],"class_list":["post-518228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-es","tag-altos-de-chavon-es-7","tag-apertura","tag-arte","tag-arte-y-cultura","tag-casa-de-campo-es","tag-comunidad-de-casa-de-campo","tag-featured-es","tag-patronato-benefico-oriental-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WAO Galer\u00eda &amp; Centro Cultural presenta la exhibici\u00f3n &quot;Universo Multicolor&quot; del artista Eddie Mosler | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WAO Galer\u00eda &amp; Centro Cultural presenta la exhibici\u00f3n &quot;Universo Multicolor&quot; del artista Eddie Mosler | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T17:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T18:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u00abUniverso Multicolor\u00bb del artista Eddie Mosler\",\"datePublished\":\"2023-06-05T17:56:22+00:00\",\"dateModified\":\"2023-06-05T18:16:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/\"},\"wordCount\":883,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1\",\"keywords\":[\"Altos de Chav\u00f3n @es\",\"apertura\",\"arte\",\"arte y cultura\",\"casa de campo @es\",\"comunidad de casa de campo\",\"Featured\",\"patronato benefico oriental @es\"],\"articleSection\":[\"Uncategorized @es\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/\",\"name\":\"WAO Galer\u00eda & Centro Cultural presenta la exhibici\u00f3n \\\"Universo Multicolor\\\" del artista Eddie Mosler | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1\",\"datePublished\":\"2023-06-05T17:56:22+00:00\",\"dateModified\":\"2023-06-05T18:16:24+00:00\",\"description\":\"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1\",\"width\":1600,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n &#8220;Universo Multicolor&#8221; del artista Eddie Mosler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WAO Galer\u00eda & Centro Cultural presenta la exhibici\u00f3n \"Universo Multicolor\" del artista Eddie Mosler | Casa de Campo Living","description":"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","og_locale":"es_ES","og_type":"article","og_title":"WAO Galer\u00eda & Centro Cultural presenta la exhibici\u00f3n \"Universo Multicolor\" del artista Eddie Mosler | Casa de Campo Living","og_description":"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano","og_url":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2023-06-05T17:56:22+00:00","article_modified_time":"2023-06-05T18:16:24+00:00","og_image":[{"width":1600,"height":786,"url":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u00abUniverso Multicolor\u00bb del artista Eddie Mosler","datePublished":"2023-06-05T17:56:22+00:00","dateModified":"2023-06-05T18:16:24+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/"},"wordCount":883,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1","keywords":["Altos de Chav\u00f3n @es","apertura","arte","arte y cultura","casa de campo @es","comunidad de casa de campo","Featured","patronato benefico oriental @es"],"articleSection":["Uncategorized @es"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","url":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","name":"WAO Galer\u00eda & Centro Cultural presenta la exhibici\u00f3n \"Universo Multicolor\" del artista Eddie Mosler | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1","datePublished":"2023-06-05T17:56:22+00:00","dateModified":"2023-06-05T18:16:24+00:00","description":"WAO Galer\u00eda &amp; Cultural Center, en colaboraci\u00f3n con la Embajada de Ecuador en la Rep\u00fablica Dominicana, presentar\u00e1 la exhibici\u00f3n del artista ecuatoriano","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1","width":1600,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n &#8220;Universo Multicolor&#8221; del artista Eddie Mosler"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u00abUniverso Multicolor\u00bb del artista Eddie Mosler","url":"http:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1"},"articleSection":"Uncategorized @es","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["altos de chav\u00f3n @es","apertura","arte","arte y cultura","casa de campo @es","comunidad de casa de campo","featured","patronato benefico oriental @es"],"dateCreated":"2023-06-05T17:56:22Z","datePublished":"2023-06-05T17:56:22Z","dateModified":"2023-06-05T18:16:24Z"},"rendered":"<meta name=\"parsely-title\" content=\"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u00abUniverso Multicolor\u00bb del artista Eddie Mosler\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-universo-multicolor-del-artista-eddie-mosler\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2023-06-05T17:56:22Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized @es\" \/>\n<meta name=\"parsely-tags\" content=\"altos de chav\u00f3n @es,apertura,arte,arte y cultura,casa de campo @es,comunidad de casa de campo,featured,patronato benefico oriental @es\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/WAO-Gallery-Artist-Eddie-Mosler-2.jpeg?fit=1600%2C786&ssl=1","jetpack-related-posts":[{"id":519458,"url":"https:\/\/casadecampoliving.com\/es\/embajada-de-ecuador-presenta-universo-multicolor-de-eddie-mosler-en-la-galeria-wao\/","url_meta":{"origin":518228,"position":0},"title":"Embajada de Ecuador presenta &#8216;Universo Multicolor&#8217; de Eddie Mosler en la Galer\u00eda WAO","author":"Casa de Campo Living","date":"19 Jun, 2023","format":false,"excerpt":"WAO Galer\u00eda y Centro Cultural, con el patrocinio de la Embajada de Ecuador en la Rep\u00fablica Dominicana, inauguraron la exposici\u00f3n \"Universo Multicolor\" del artista ecuatoriano Eddie Mosler el 17 de junio y estar\u00e1 abierta hasta el 17 de julio. Esta exposici\u00f3n consta de un total de 29 piezas que nos\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":518988,"url":"https:\/\/casadecampoliving.com\/embassy-of-ecuador-presents-multicolored-universe-by-eddie-mosler-at-wao-gallery\/","url_meta":{"origin":518228,"position":1},"title":"Embassy Of Ecuador Presents &#8216;Multicolored Universe&#8217; by Eddie Mosler At WAO Gallery","author":"Casa de Campo Living","date":"19 Jun, 2023","format":false,"excerpt":"WAO Gallery & Cultural Center, with the sponsorship of the Embassy of Ecuador in the Dominican Republic, inaugurated the exhibition \"Multicolor Universe\" by Ecuadorian artist Eddie Mosler on June 17th and will be open until July 17th. This exhibition consists of a total of 29 pieces that invite us to\u2026","rel":"","context":"En \u00abAltos de Chavon\u00bb","block_context":{"text":"Altos de Chavon","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/06\/Eddie-Mosler-Multicolored-universe-20.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":513629,"url":"https:\/\/casadecampoliving.com\/es\/wao-galeria-centro-cultural-presenta-la-exhibicion-trabajos-recientes-del-artista-fernando-tamburini\/","url_meta":{"origin":518228,"position":2},"title":"WAO Galer\u00eda &#038; Centro Cultural presenta la exhibici\u00f3n \u201cTrabajos Recientes\u201d del artista Fern\u00e1ndo Tamburini.","author":"Casa de Campo Living","date":"24 Ene, 2023","format":false,"excerpt":"WAO Galer\u00eda & Centro Cultural presentar\u00e1 a partir del 3 de febrero la exhibici\u00f3n del artista visual oriundo de Barahona, Fern\u00e1ndo Tamburini, conocido por su colorido trabajo abstracto que oscila entre figurativo, primitivo y realista en el que captura la gran cultura del pueblo dominicano, siendo llamado el Chagall dominicano\u2026","rel":"","context":"En \u00abAltos de Chav\u00f3n\u00bb","block_context":{"text":"Altos de Chav\u00f3n","link":"https:\/\/casadecampoliving.com\/es\/category\/altos-de-chavon-6\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-26-at-1.34.00-PM-1.jpeg?fit=1024%2C833&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-26-at-1.34.00-PM-1.jpeg?fit=1024%2C833&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-26-at-1.34.00-PM-1.jpeg?fit=1024%2C833&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-26-at-1.34.00-PM-1.jpeg?fit=1024%2C833&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":518228,"position":3},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":354409,"url":"https:\/\/casadecampoliving.com\/es\/wao-galeria-en-altos-de-chavon-presenta-la-exhibicion-caida-del-artista-joaquin-basanta\/","url_meta":{"origin":518228,"position":4},"title":"WAO Galer\u00eda en Altos de Chav\u00f3n presenta la exhibici\u00f3n \u201cCa\u00edda\u201d del artista Joaqu\u00edn Basanta","author":"Casa de Campo Living","date":"11 Jun, 2022","format":false,"excerpt":"Dentro de las exhibiciones del 2022, WAO Galer\u00eda Centro Cultural ubicada en Altos de Chav\u00f3n, contin\u00faa presentando al pa\u00eds y al mundo obras y exposiciones de grandes artistas dominicanos e internacionales, adem\u00e1s de brindar la oportunidad a noveles artistas de mostrar sus obras. El pr\u00f3ximo 17 de junio se inaugurar\u00e1\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_5363.jpg?fit=1000%2C613&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_5363.jpg?fit=1000%2C613&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_5363.jpg?fit=1000%2C613&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_5363.jpg?fit=1000%2C613&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354480,"url":"https:\/\/casadecampoliving.com\/es\/el-arte-naif-engalana-wao-galeria-y-centro-cultural-en-altos-de-chavon-en-una-armonia-espiritual\/","url_meta":{"origin":518228,"position":5},"title":"El arte Naif engalana WAO Galeria y Centro Cultural en Altos de Chav\u00f3n en una Armon\u00eda Espiritual","author":"Casa de Campo Living","date":"23 Ago, 2022","format":false,"excerpt":"Wao Galeria & Centro Cultural en Altos de Chav\u00f3n di\u00f3 apertura la noche de este s\u00e1bado 20 de agosto a la exposici\u00f3n conjunta de los artistas Jos\u00e9 Morillo y Frantz Zeph\u00edrin, \"ARMON\u00cdA ESPIRITUAL\". Una noche m\u00e1gica, donde la uni\u00f3n de dos culturas llenas de un recorrido art\u00edstico y una enriquecida\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Armonia-Espiritual-WAO-Gallery-10-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Armonia-Espiritual-WAO-Gallery-10-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Armonia-Espiritual-WAO-Gallery-10-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Armonia-Espiritual-WAO-Gallery-10-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/518228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=518228"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/518228\/revisions"}],"predecessor-version":[{"id":518229,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/518228\/revisions\/518229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/518218"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=518228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=518228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=518228"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=518228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}