{"id":516304,"date":"2023-04-10T11:44:46","date_gmt":"2023-04-10T15:44:46","guid":{"rendered":"https:\/\/casadecampoliving.com\/?p=516304"},"modified":"2023-04-10T15:41:20","modified_gmt":"2023-04-10T19:41:20","slug":"el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","title":{"rendered":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \u00abFerxxo Nitro Jam\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del tradicional concierto de Semana Santa, el artista colombiano Ferxxo cerr\u00f3 su gira por Rep\u00fablica Dominicana, marcando su primera presentaci\u00f3n en suelo dominicano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=1080%2C675&#038;ssl=1\" alt=\"\" class=\"wp-image-516162\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=300%2C188&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=1024%2C640&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=768%2C480&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=400%2C250&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?resize=150%2C94&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-edited.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El escenario se encendi\u00f3 a las 10:43 pm cuando Ferxxo apareci\u00f3 detr\u00e1s de una cortina cantando \u00abNormal\u00bb, una de sus canciones m\u00e1s populares. Acompa\u00f1ado por dos DJ y un guitarrista que tambi\u00e9n sirvieron como coristas, Feid se movi\u00f3 por el escenario, interpretando \u00e9xitos como \u00abInocente\u00bb, \u00abProhibidox\u00bb, \u00abPurrito APA\u00bb, \u00abLady Mi Amor\u00bb, \u00abNea!\u00bb y \u00abTe mata\u00bb, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el escenario iluminado en verde ne\u00f3n, humo y fuegos artificiales de fondo, la energ\u00eda y la pasi\u00f3n de Feid fueron evidentes mientras interpretaba sus sencillos m\u00e1s populares. La multitud cant\u00f3 cada canci\u00f3n de principio a fin, dejando en claro que es uno de los artistas m\u00e1s destacados del momento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-516139\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1200%2C675&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1568%2C881&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=1320%2C742&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035.jpg?w=1779&amp;ssl=1 1779w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0035-1024x576.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El color verde y las gafas blancas fueron el estilo distintivo de la audiencia que se reuni\u00f3 para ver al cantante, ya que son elementos que Feid incluye t\u00edpicamente en sus atuendos. Feid expres\u00f3 su gratitud a los fan\u00e1ticos diciendo: \u00abGracias, Rep\u00fablica Dominicana. Hoy terminamos esta gira latinoamericana en este hermoso pa\u00eds\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche tom\u00f3 un giro sorprendente cuando el artista puertorrique\u00f1o Yandel se uni\u00f3 a Feid en el escenario para interpretar su popular canci\u00f3n \u00abYandel 150\u00bb. Despu\u00e9s de su dueto, Yandel se qued\u00f3 solo en el escenario para interpretar un popurr\u00ed de canciones ic\u00f3nicas que forman parte del d\u00fao Wisin y Yandel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"810\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=1080%2C810&#038;ssl=1\" alt=\"\" class=\"wp-image-516164\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=800%2C600&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-edited.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La noche continu\u00f3 en un tono alto con un espect\u00e1culo visual de rayos verdes, seguido de la eliminaci\u00f3n de las pantallas LED en el escenario, revelando un monster truck en medio de \u00e9l. Feid se par\u00f3 en una de sus llantas, simulando el videoclip donde un veh\u00edculo de este tipo tambi\u00e9n aparece haciendo maniobras.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/Cq1Q0SJLXeO\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:500px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/Cq1Q0SJLXeO\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/Cq1Q0SJLXeO\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by GAMAL\u2122\ufe0f (@gamalrd)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue producido por Gamal RD y dej\u00f3 una impresi\u00f3n duradera en todos los asistentes, convirti\u00e9ndolo en una de las noches m\u00e1s inolvidables de Altos de Chav\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Fotos cortes\u00eda de Gamal RD<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"516133\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-516133\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1200%2C675&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1568%2C881&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=1320%2C742&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049.jpg?w=1779&amp;ssl=1 1779w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0049-1024x576.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"516131\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=576%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516131\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=768%2C1366&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=863%2C1536&amp;ssl=1 863w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=400%2C712&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?resize=150%2C267&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0036-576x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"516141\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-516141\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1200%2C675&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1568%2C881&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=1320%2C742&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038.jpg?w=1779&amp;ssl=1 1779w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0038-1024x576.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"516150\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-516150\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-3-1024x576.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"516137\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-516137\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1200%2C675&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1568%2C881&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=1320%2C742&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053.jpg?w=1779&amp;ssl=1 1779w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0053-1024x576.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" data-id=\"516126\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?resize=1000%2C562&#038;ssl=1\" alt=\"\" class=\"wp-image-516126\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?resize=400%2C225&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour_DSC0052.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"516145\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516145\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=1365%2C2048&amp;ssl=1 1365w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=1568%2C2352&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00426-683x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"516160\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516160\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=400%2C500&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?resize=150%2C188&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-2-819x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"516152\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516152\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=400%2C500&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?resize=150%2C188&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam--819x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"1024\" data-id=\"516158\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=820%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516158\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=820%2C1024&amp;ssl=1 820w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=768%2C959&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=400%2C500&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?resize=150%2C187&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-1-1-820x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"516154\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516154\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=400%2C500&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?resize=150%2C188&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-2-819x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"516147\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-516147\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=1366%2C2048&amp;ssl=1 1366w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=1200%2C1800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=1568%2C2352&amp;ssl=1 1568w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=1320%2C1980&amp;ssl=1 1320w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-scaled.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC09982-683x1024.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del tradicional concierto de Semana Santa, el artista colombiano Ferxxo cerr\u00f3 su gira por Rep\u00fablica Dominicana, marcando su primera presentaci\u00f3n en suelo dominicano. El escenario se encendi\u00f3 a las 10:43 [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":516144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"large","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2513,2518,2522,14625,2521,19622],"tags":[3575,18836,14736],"newspack_spnsrs_tax":[],"class_list":["post-516304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades-es","category-conciertos-es","category-eventos-es","category-noticias-locales","category-republica-dominicana-2","category-video-es-2","tag-altos-de-chavon-es-2","tag-concert-es-2","tag-featured-topview-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira &quot;Ferxxo Nitro Jam&quot; | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira &quot;Ferxxo Nitro Jam&quot; | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T15:44:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-10T19:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1084\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \u00abFerxxo Nitro Jam\u00bb\",\"datePublished\":\"2023-04-10T15:44:46+00:00\",\"dateModified\":\"2023-04-10T19:41:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/\"},\"wordCount\":402,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1\",\"keywords\":[\"Altos de Chavon -es\",\"concert\",\"Featured-TopView @es\"],\"articleSection\":[\"Celebridades\",\"Conciertos\",\"Eventos\",\"Noticias Locales\",\"Rep\u00fablica Dominicana @es\",\"Video\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/\",\"name\":\"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \\\"Ferxxo Nitro Jam\\\" | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1\",\"datePublished\":\"2023-04-10T15:44:46+00:00\",\"dateModified\":\"2023-04-10T19:41:20+00:00\",\"description\":\"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1\",\"width\":1200,\"height\":1084},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira &#8220;Ferxxo Nitro Jam&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \"Ferxxo Nitro Jam\" | Casa de Campo Living","description":"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","og_locale":"es_ES","og_type":"article","og_title":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \"Ferxxo Nitro Jam\" | Casa de Campo Living","og_description":"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del","og_url":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2023-04-10T15:44:46+00:00","article_modified_time":"2023-04-10T19:41:20+00:00","og_image":[{"width":1200,"height":1084,"url":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \u00abFerxxo Nitro Jam\u00bb","datePublished":"2023-04-10T15:44:46+00:00","dateModified":"2023-04-10T19:41:20+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/"},"wordCount":402,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1","keywords":["Altos de Chavon -es","concert","Featured-TopView @es"],"articleSection":["Celebridades","Conciertos","Eventos","Noticias Locales","Rep\u00fablica Dominicana @es","Video"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","url":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","name":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \"Ferxxo Nitro Jam\" | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1","datePublished":"2023-04-10T15:44:46+00:00","dateModified":"2023-04-10T19:41:20+00:00","description":"Feid electrific\u00f3 a los Altos de Chav\u00f3n con su \u201cFerxxo Nitro Jam Tour\u201d en una actuaci\u00f3n que dej\u00f3 asombrados a miles de fan\u00e1ticos. Como parte del","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1","width":1200,"height":1084},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira &#8220;Ferxxo Nitro Jam&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \u00abFerxxo Nitro Jam\u00bb","url":"http:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1"},"articleSection":"Celebridades","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["altos de chavon -es","concert","featured-topview @es"],"dateCreated":"2023-04-10T15:44:46Z","datePublished":"2023-04-10T15:44:46Z","dateModified":"2023-04-10T19:41:20Z"},"rendered":"<meta name=\"parsely-title\" content=\"El artista colombiano Feid sacudi\u00f3 las piedras de Altos de Chav\u00f3n con la gira \u00abFerxxo Nitro Jam\u00bb\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/el-artista-colombiano-feid-sacudio-las-piedras-de-altos-de-chavon-con-la-gira-ferxxo-nitro-jam\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2023-04-10T15:44:46Z\" \/>\n<meta name=\"parsely-section\" content=\"Celebridades\" \/>\n<meta name=\"parsely-tags\" content=\"altos de chavon -es,concert,featured-topview @es\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":516304,"position":0},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":516123,"url":"https:\/\/casadecampoliving.com\/colombian-artist-feid-shook-altos-de-chavons-cobblestones-with-ferxxo-nitro-jam-tour\/","url_meta":{"origin":516304,"position":1},"title":"Colombian Artist Feid Shook Altos de Chav\u00f3n&#8217;s Cobblestones with \u00abFerxxo Nitro Jam\u00bb Tour","author":"Casa de Campo Living","date":"10 Abr, 2023","format":false,"excerpt":"Feid electrified the Altos de Chav\u00f3n with his \"Ferxxo Nitro Jam Tour\" in a performance that left thousands of fans in awe. As part of the traditional Semana Santa concert, Colombian artist Ferxxo brought the closing of his tour to the Dominican Republic, marking his first-ever performance on Dominican soil.\u2026","rel":"","context":"En \u00abAltos de Chavon\u00bb","block_context":{"text":"Altos de Chavon","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":526811,"url":"https:\/\/casadecampoliving.com\/es\/ozuna-regresa-a-altos-de-chavon-el-sabado-santo\/","url_meta":{"origin":516304,"position":2},"title":"Ozuna regresa a Altos de Chav\u00f3n el S\u00e1bado Santo","author":"Casa de Campo Living","date":"16 Feb, 2024","format":false,"excerpt":"En un regreso muy esperado a la Rep\u00fablica Dominicana, el \u00edcono de la m\u00fasica urbana Ozuna honrar\u00e1 las ic\u00f3nicas piedras de Altos de Chav\u00f3n este S\u00e1bado Santo. Cuatro a\u00f1os despu\u00e9s de su \u00faltima actuaci\u00f3n en suelo dominicano, Ozuna promete una noche espectacular el 30 de marzo, compartiendo sus mayores \u00e9xitos\u2026","rel":"","context":"En \u00abAltos de Chav\u00f3n\u00bb","block_context":{"text":"Altos de Chav\u00f3n","link":"https:\/\/casadecampoliving.com\/es\/category\/altos-de-chavon-6\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/02\/Ozuna-32-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/02\/Ozuna-32-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/02\/Ozuna-32-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/02\/Ozuna-32-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/02\/Ozuna-32-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":336941,"url":"https:\/\/casadecampoliving.com\/es\/franco-de-vita-presentara-por-primera-vez-en-altos-de-chavon\/","url_meta":{"origin":516304,"position":3},"title":"Franco de Vita presentar\u00e1 por primera vez en Altos de Chav\u00f3n!","author":"Rebecca Silvestri","date":"15 Ago, 2011","format":false,"excerpt":"\u00a0Franco de Vita, el afamado compositor se presentar\u00e1 por primera vez en Altos de Chav\u00f3n! De Vita es uno de los cantautores de habla hispana m\u00e1s respetados de Am\u00e9rica Latina y muchos otros pa\u00edses del mundo. A\u00f1os han transcurrido desde que el legendario artista Franco de Vita se presentara por\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/franco_de_vita_casa_de_campo_altos_de_chavon_concert-4.jpg?fit=565%2C264&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/franco_de_vita_casa_de_campo_altos_de_chavon_concert-4.jpg?fit=565%2C264&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/franco_de_vita_casa_de_campo_altos_de_chavon_concert-4.jpg?fit=565%2C264&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":533171,"url":"https:\/\/casadecampoliving.com\/es\/reserva-la-fecha-carlos-vives-se-presentara-en-altos-de-chavon-el-7-de-diciembre-de-2024\/","url_meta":{"origin":516304,"position":4},"title":"Reserva la fecha: Carlos Vives se presentar\u00e1 en Altos de Chav\u00f3n el 7 de diciembre de 2024","author":"Casa de Campo Living","date":"13 Sep, 2024","format":false,"excerpt":"El legendario m\u00fasico colombiano Carlos Vives electrificar\u00e1 el escenario de Altos de Chav\u00f3n el 7 de diciembre de 2024 como parte de su gira \"El Rock De Mi Pueblo Vive\", en celebraci\u00f3n de los 30 a\u00f1os de su incre\u00edble carrera. Se espera que el concierto atraiga a m\u00e1s de 5,000\u2026","rel":"","context":"En \u00abAltos de Chav\u00f3n\u00bb","block_context":{"text":"Altos de Chav\u00f3n","link":"https:\/\/casadecampoliving.com\/es\/category\/altos-de-chavon-6\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/09\/Carlos-vives-image0.jpeg?fit=1200%2C925&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/09\/Carlos-vives-image0.jpeg?fit=1200%2C925&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/09\/Carlos-vives-image0.jpeg?fit=1200%2C925&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/09\/Carlos-vives-image0.jpeg?fit=1200%2C925&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2024\/09\/Carlos-vives-image0.jpeg?fit=1200%2C925&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":352851,"url":"https:\/\/casadecampoliving.com\/es\/confirmado-daddy-yankee-y-bad-bunny-se-presentaran-en-altos-de-chavon\/","url_meta":{"origin":516304,"position":5},"title":"Confirmado: \u00a1Daddy Yankee y Bad Bunny se presentar\u00e1n en Altos de Chav\u00f3n!","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"3 Sep, 2018","format":false,"excerpt":"\u00a1\u00a1\u00a1Es oficial!!! \u00a1En tan solo dos meses, el s\u00e1bado, 3 de noviembre, Daddy Yankee y Bad Bunny se presentar\u00e1n en el anfiteatro Altos de Chav\u00f3n para el pr\u00f3ximo concierto de Casa de Campo! \u201cDos artistas puertorrique\u00f1os, dos estilos \u00fanicos y dos giras mundiales coincidir\u00e1n en el mismo escenario para una\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/09\/BB.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/09\/BB.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/09\/BB.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/09\/BB.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/04\/Feid-Ferxxo-Nitro-Jam-Tour-DSC00809.jpg?fit=1200%2C1084&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/516304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=516304"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/516304\/revisions"}],"predecessor-version":[{"id":516305,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/516304\/revisions\/516305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/516144"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=516304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=516304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=516304"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=516304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}