{"id":354291,"date":"2022-02-21T00:00:00","date_gmt":"2022-02-21T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/"},"modified":"2022-10-21T19:19:39","modified_gmt":"2022-10-21T23:19:39","slug":"quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","title":{"rendered":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero y Casa de Campo derrot\u00f3 a Costasur 12-6 al d\u00eda siguiente. La final de la Copa de Plata se llevar\u00e1 a cabo ESTE s\u00e1bado 26 de febrero a las 4:00 pm en Casa de Campo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera copa de la temporada vio ocho equipos incre\u00edbles que compitieron por la Copa de Plata con los mejores jugadores de polo;<strong> Casa de Campo, La Suiza, McDonalds 3J Team, La Carmelia, La Carbuccia, Costasur, La Romanza -40 Goles, La Espada- La Bienvenida, y Ganadera Nepora.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?resize=2560%2C1707&amp;ssl=1\" alt=\"\" class=\"wp-image-212510\" height=\"1707\" width=\"2560\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/casadecampoliving.com\/es\/mcd3j-gana-las-finales-subsidiarias-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/\" target=\"_blank\" rel=\"noopener\">final subsidiaria se jug\u00f3 el 12 de febrero<\/a>; Fue un partido duro y muy emocionante, con ambos equipos bastante cerca e intercambiando goles a partes iguales durante todo el partido. Al final, MCD3J derrot\u00f3 a La Romanza por 10-9, ganando el primer trofeo de la temporada de polo de este a\u00f1o, y Santos Rueda ganando el MVP del juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Casa de Campo Polo Challenge est\u00e1 siendo organizado por el Dr. Fernando Arata, Director de Polo de Casa de Campo quien ha augurado que el Casa de Campo Polo Challenge de este a\u00f1o ser\u00e1 un \u00e9xito y que se convertir\u00e1 en un evento imperdible para todos los dominicanos, extranjeros , y el p\u00fablico en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1La Copa de Plata de este a\u00f1o ha sido excepcionalmente buena, con grandes partidos por todos lados y estamos seguros de que el resto de la temporada solo mejorar\u00e1!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00a1Esperamos verlos all\u00ed disfrutando de otra de las divertidas actividades de Casa!<\/strong><\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Final Copa de Plata \u2013 <\/strong>CDC vs La Carmela<\/p><p><strong>Cu\u00e1ndo<\/strong>: s\u00e1bado 26 de febrero<\/p><p><strong>Hora<\/strong>: 16:00<\/p><p><strong>D\u00f3nde<\/strong>: Cancha de Polo, Casa de Campo<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero y Casa de Campo derrot\u00f3 a Costasur 12-6 al d\u00eda siguiente. La final de la Copa de Plata se llevar\u00e1 a cabo ESTE s\u00e1bado 26 de febrero [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":334633,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,2525,14631,2522,14625,14627,2521,26822],"tags":[23815,26880,14736,14204,2883,195],"newspack_spnsrs_tax":[],"class_list":["post-354291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-golf-deportes-es","category-estilo-de-vida","category-eventos-es","category-noticias-locales","category-proximamente","category-republica-dominicana-2","category-resort-casa-de-campo","tag-casa-de-campo-es-17","tag-casa-de-campo-polo-challenge","tag-featured-topview-es","tag-finales","tag-juegos","tag-polo","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?\",\"datePublished\":\"2022-02-21T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:19:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/\"},\"wordCount\":309,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1\",\"keywords\":[\"Casa de Campo\",\"Casa de Campo Polo Challenge\",\"Featured-TopView @es\",\"finales\",\"juegos\",\"Polo\"],\"articleSection\":[\"Casa de Campo Living @es\",\"Deportes\",\"Estilo de Vida\",\"Eventos\",\"Noticias Locales\",\"Proximamente\",\"Rep\u00fablica Dominicana @es\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/\",\"name\":\"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1\",\"datePublished\":\"2022-02-21T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:19:39+00:00\",\"description\":\"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living","description":"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living","og_description":"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero","og_url":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2022-02-21T04:00:00+00:00","article_modified_time":"2022-10-21T23:19:39+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?","datePublished":"2022-02-21T04:00:00+00:00","dateModified":"2022-10-21T23:19:39+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/"},"wordCount":309,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","keywords":["Casa de Campo","Casa de Campo Polo Challenge","Featured-TopView @es","finales","juegos","Polo"],"articleSection":["Casa de Campo Living @es","Deportes","Estilo de Vida","Eventos","Noticias Locales","Proximamente","Rep\u00fablica Dominicana @es","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","url":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","name":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022? | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","datePublished":"2022-02-21T04:00:00+00:00","dateModified":"2022-10-21T23:19:39+00:00","description":"Los finalistas de la Copa de Plata se definieron la semana pasada cuando La Carmela, gan\u00f3 la primera semifinal ante La Espada 12-9 el martes 15 de febrero","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?","url":"http:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1"},"articleSection":"Casa de Campo Living @es","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo","casa de campo polo challenge","featured-topview @es","finales","juegos","polo"],"dateCreated":"2022-02-21T04:00:00Z","datePublished":"2022-02-21T04:00:00Z","dateModified":"2022-10-21T23:19:39Z"},"rendered":"<meta name=\"parsely-title\" content=\"\u00bfQui\u00e9n ganar\u00e1 la final de la Copa de Plata del Casa de Campo Polo Challenge 2022?\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/quien-ganara-la-final-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-02-21T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Casa de Campo Living @es\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo,casa de campo polo challenge,featured-topview @es,finales,juegos,polo\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":354279,"url":"https:\/\/casadecampoliving.com\/es\/aplazado-por-lluvia-las-semifinales-de-la-copa-de-plata-2022-del-casa-de-campo-polo-challenge-comienzan-hoy\/","url_meta":{"origin":354291,"position":0},"title":"APLAZADO POR LLUVIA: \u00a1Las semifinales de la Copa de Plata 2022 del Casa de Campo Polo Challenge comienzan hoy!","author":"Casa de Campo Living","date":"3 Feb, 2022","format":false,"excerpt":"*Los juegos de la Copa Plata han sido pospuestos por las lluvias, les avisaremos en cuanto tengamos las nuevas fechas* \u00a1La Copa de Plata de este a\u00f1o ha sido excepcionalmente buena, con grandes partidos por todos lados y estamos seguros de que el resto de la temporada solo mejorar\u00e1! Durante\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-01-25-at-4.39.32-PM-1.jpeg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-01-25-at-4.39.32-PM-1.jpeg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-01-25-at-4.39.32-PM-1.jpeg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-01-25-at-4.39.32-PM-1.jpeg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354244,"url":"https:\/\/casadecampoliving.com\/es\/lo-que-los-fans-han-estado-esperando-casa-de-campo-polo-challenge-2022-regresa-este-15-de-enero\/","url_meta":{"origin":354291,"position":1},"title":"Lo que los fans han estado esperando\u2026 \u00a1Casa de Campo Polo Challenge 2022 regresa este 15 de enero!","author":"Casa de Campo Living","date":"9 Ene, 2022","format":false,"excerpt":"\u00a1Atenci\u00f3n comunidad de Casa de Campo! El Casa de Campo Polo Challenge est\u00e1 de regreso y se llevar\u00e1 a cabo del 15 de enero al 16 de abril de 2022. El primer juego ser\u00e1 este s\u00e1bado 15 de enero a partir de las 2 pm en las canchas de polo\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B0835-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B0835-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B0835-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B0835-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349178,"url":"https:\/\/casadecampoliving.com\/es\/copa-de-plata-dr-polo-challenge-casa-de-campo\/","url_meta":{"origin":354291,"position":2},"title":"La Copa de Plata del DR Polo Challenge Inicia en Casa de Campo","author":"Heather Lincoln","date":"11 Feb, 2016","format":false,"excerpt":"Ayer, jueves 11 de febrero, una serie de impresionantes partidos celebrados aqu\u00ed mismo en\u00a0Casa de Campo\u00a0dieron inicio a la Copa de Plata del Polo Challenge RD 2016. Con la Copa de Bronce habiendo terminado el\u00a030 de enero, y la Royal Salute Charity Polo Cup, el pasado 6 de febrero, ahora\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"Polo Matias Callejo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Polo-Matias-Callejo-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Polo-Matias-Callejo-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Polo-Matias-Callejo-1.jpg?fit=650%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":354288,"url":"https:\/\/casadecampoliving.com\/es\/mcd3j-gana-las-finales-subsidiarias-de-la-copa-de-plata-del-casa-de-campo-polo-challenge-2022\/","url_meta":{"origin":354291,"position":3},"title":"\u00a1MCD3J gana las Finales Subsidiarias de la Copa de Plata del Casa de Campo Polo Challenge 2022!","author":"Casa de Campo Living","date":"15 Feb, 2022","format":false,"excerpt":"Luego de algunos aplazamientos por lluvia, finalmente se llev\u00f3 a cabo la final subsidiaria de la Copa Plata en Casa de Campo con los equipos MCD3J y La Romanza jugando uno contra el otro. Fue un partido duro y muy emocionante, con ambos equipos bastante cerca e intercambiando goles a\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1769-scaled-2.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":346835,"url":"https:\/\/casadecampoliving.com\/es\/el-polo-casa-de-campo-continua-con-la-copa-plata\/","url_meta":{"origin":354291,"position":4},"title":"El polo Casa de Campo contin\u00faa con la Copa Plata","author":"Felix Guerrero","date":"18 Feb, 2015","format":false,"excerpt":"La temporada de polo Casa de Campo ha estado en su apogeo desde diciembre cuando abri\u00f3 con las semifinales\u00a0de la\u00a0Copa Mundial FIP entre M\u00e9xico, Estados Unidos, Rep\u00fablica Dominicana y Guatemala, y esta semana la emoci\u00f3n contin\u00faa con la Copa Plata. La Copa Plata empieza hoy con varios juegos de pr\u00e1ctica\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"Casa de Campo Polo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_Polo1.jpg?fit=470%2C294&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":351166,"url":"https:\/\/casadecampoliving.com\/es\/continua-la-copa-de-plata-polo-challenge\/","url_meta":{"origin":354291,"position":5},"title":"Continua la Copa de Plata en el Polo Challenge RD 2017","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"20 Feb, 2017","format":false,"excerpt":"Luego de varios d\u00edas de adversas condiciones clim\u00e1ticas, el viernes y el s\u00e1bado se disputaron los partidos pertenecientes a la categor\u00eda 12 goles de la Copa de Plata del Polo Challenge 2017 . El domingo los juegos fueron suspendidos nuevamente por lluvia. En Casa de Campo, el equipo local se\u2026","rel":"","context":"En \u00abCostasur Dominicana @es\u00bb","block_context":{"text":"Costasur Dominicana @es","link":"https:\/\/casadecampoliving.com\/es\/category\/costasur-dominicana-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/170218_MC_0301-2-e1487604860136.jpg?fit=1000%2C666&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/170218_MC_0301-2-e1487604860136.jpg?fit=1000%2C666&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/170218_MC_0301-2-e1487604860136.jpg?fit=1000%2C666&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/170218_MC_0301-2-e1487604860136.jpg?fit=1000%2C666&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/EJ4B1690-1.jpg?fit=1000%2C667&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=354291"}],"version-history":[{"count":0,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/334633"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=354291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=354291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=354291"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=354291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}