{"id":354286,"date":"2022-02-10T00:00:00","date_gmt":"2022-02-10T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/"},"modified":"2022-11-10T10:29:45","modified_gmt":"2022-11-10T14:29:45","slug":"juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","title":{"rendered":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo"},"content":{"rendered":"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el mundo!\n\nM\u00e1s recientemente, el resort celebr\u00f3 el <strong>47\u00b0 ProAm Internacional del Caribe<\/strong> y la s\u00e9ptima edici\u00f3n del <a href=\"https:\/\/casadecampoliving.com\/es\/aaron-jarvis-es-el-flamante-campeon-del-latin-america-amateur-championship-2022\/\" target=\"_blank\" rel=\"noopener\">Campeonato Latinoamericano de Aficionados (LAAC)<\/a> que se llev\u00f3 a cabo en Casa de Campo Resort &amp; Villas del 20 al 23 de enero.\n\nLo pr\u00f3ximo es el <a href=\"https:\/\/casadecampoliving.com\/es\/reserve-la-fecha-para-el-torneo-de-golf-solidario-hogar-del-nino-del-proximo-ano\/\" target=\"_blank\" rel=\"noopener\">Torneo de Golf Solidario Hogar del Ni\u00f1o<\/a> en La Romana Country Club el 19 de febrero, este evento es la manera perfecta de pasar un buen rato y ser solidario.\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-208657\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/XXIV-Hogar-del-Nin%CC%83o-Solidarity-golf-tournament26-2.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"667\">\n\nEl 27 de febrero es el <strong>34\u00b0 Aniversario del Pro-Am II Anual del Caribe Internacional;<\/strong> el evento se disputar\u00e1 en los tres campos de campeonato de Casa de Campo: The Links, Dye Fore y Teeth of the Dog. Los equipos deben estar compuestos por un (1) profesional y tres (3) amateurs.\n\nEsto ser\u00e1 seguido por la <strong>Escuela de Golf de Invierno de Casa de Campo<\/strong> organizada por el Jefe de Ense\u00f1anza Profesional Eric Lillibridge del 9 al 13 de marzo. La escuela est\u00e1 limitada a los ocho aficionados que quieren no solo mejorar su juego de golf sino tambi\u00e9n disfrutar del mejor golf del Caribe. Los aficionados pasar\u00e1n tiempo trabajando en nuestros estudios Trackman de \u00faltima generaci\u00f3n; adem\u00e1s de jugar en todos los campos, incluido el mundialmente famoso Teeth of the Dog.\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-208588\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Trackman_Night_Flyer_updated-1-1.png?resize=1000%2C636&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"636\">\n\nDel 27 de abril al 1 de mayo de 2022, la Caribbean Golf Association y Casa de Campo est\u00e1n planeando una celebraci\u00f3n hist\u00f3rica para el <strong>Caribbean Classic<\/strong> en el lugar donde todo comenz\u00f3 hace 26 a\u00f1os. Y solo unos d\u00edas despu\u00e9s, Wegolf y Casa de Campo ser\u00e1n los anfitriones de<strong> Fourball Americas, Casa de Campo<\/strong> que ofrece a los golfistas de todo el mundo la oportunidad de competir en dos excelentes campos de golf (Teeth of the Dog y Dye Fore) en un formato de pareja.\n\nAh\u00ed tiene la emocionante lista de torneos de golf para el primer trimestre del a\u00f1o aqu\u00ed en Casa de Campo; marque sus calendarios y est\u00e9 atento a la cobertura de eventos y fotos de Casa de Campo Living.\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"422205\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-422205\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=706%2C706&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/270180357_468812324876397_7822638866212662101_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"422225\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-422225\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=706%2C706&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272978922_455954532875819_1895967315116172869_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"422250\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-422250\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=706%2C706&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/272976296_1399246960520852_775876855354182645_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" data-id=\"422272\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-422272\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=706%2C706&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/273032700_625012565470844_6275042933642675096_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el mundo! M\u00e1s recientemente, el resort celebr\u00f3 el 47\u00b0 ProAm Internacional del Caribe y la s\u00e9ptima edici\u00f3n del Campeonato Latinoamericano de Aficionados (LAAC) que se llev\u00f3 a cabo en [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":331899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,2521,2522,14631,14625,26822,2525,14627],"tags":[23815,2090,178,24346,176,22617,2599],"newspack_spnsrs_tax":[],"class_list":["post-354286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-republica-dominicana-2","category-eventos-es","category-estilo-de-vida","category-noticias-locales","category-resort-casa-de-campo","category-golf-deportes-es","category-proximamente","tag-casa-de-campo-es-17","tag-diente-de-perro","tag-dye-fore","tag-featured-es","tag-golf","tag-thel-links","tag-torneo-de-golf","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-10T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo\",\"datePublished\":\"2022-02-10T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1\",\"keywords\":[\"Casa de Campo\",\"diente de perro\",\"Dye Fore\",\"Featured\",\"Golf\",\"thel links\",\"torneo de golf\"],\"articleSection\":[\"Casa de Campo Living @es\",\"Rep\u00fablica Dominicana @es\",\"Eventos\",\"Estilo de Vida\",\"Noticias Locales\",\"Resort Casa de Campo\",\"Deportes\",\"Proximamente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/\",\"name\":\"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1\",\"datePublished\":\"2022-02-10T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:29:45+00:00\",\"description\":\"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1\",\"width\":1000,\"height\":602,\"caption\":\"golf resort in the Dominican Republic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living","description":"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living","og_description":"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el","og_url":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2022-02-10T04:00:00+00:00","article_modified_time":"2022-11-10T14:29:45+00:00","og_image":[{"width":1000,"height":602,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo","datePublished":"2022-02-10T04:00:00+00:00","dateModified":"2022-11-10T14:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/"},"wordCount":376,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","keywords":["Casa de Campo","diente de perro","Dye Fore","Featured","Golf","thel links","torneo de golf"],"articleSection":["Casa de Campo Living @es","Rep\u00fablica Dominicana @es","Eventos","Estilo de Vida","Noticias Locales","Resort Casa de Campo","Deportes","Proximamente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","url":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","name":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","datePublished":"2022-02-10T04:00:00+00:00","dateModified":"2022-11-10T14:29:45+00:00","description":"\u00a1Casa de Campo es el lugar de destino para los golfistas con m\u00faltiples campos hermosos repartidos por todo el complejo que atraen a jugadores de todo el","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","width":1000,"height":602,"caption":"golf resort in the Dominican Republic"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo","url":"http:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1"},"articleSection":"Casa de Campo Living @es","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo","diente de perro","dye fore","featured","golf","thel links","torneo de golf"],"dateCreated":"2022-02-10T04:00:00Z","datePublished":"2022-02-10T04:00:00Z","dateModified":"2022-11-10T14:29:45Z"},"rendered":"<meta name=\"parsely-title\" content=\"\u00a1Juegos de golf en abundancia! Pr\u00f3ximos torneos de golf en Casa de Campo\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/juegos-de-golf-en-abundancia-proximos-torneos-de-golf-en-casa-de-campo\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-02-10T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Casa de Campo Living @es\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo,diente de perro,dye fore,featured,golf,thel links,torneo de golf\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":354286,"position":0},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":354158,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-golf-proximos-torneos-de-octubre-de-2021-a-marzo-de-2022\/","url_meta":{"origin":354286,"position":1},"title":"Casa de Campo Golf: \u00a1Pr\u00f3ximos torneos de octubre de 2021 a marzo de 2022!","author":"Casa de Campo Living","date":"21 Sep, 2021","format":false,"excerpt":"Casa de Campo es conocida mundialmente por ser uno de los resorts m\u00e1s completos y prestigiosos del Caribe\u2026 y esto se debe a varias razones; uno de los cuales es que tiene algunos de los mejores campos de golf del mundo; The Teeth of the Dog, Dye Fore y The\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"Teeth of the Dog Casa de Campo Resort","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TOD_257-e1498228553981.jpg?fit=1000%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TOD_257-e1498228553981.jpg?fit=1000%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TOD_257-e1498228553981.jpg?fit=1000%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TOD_257-e1498228553981.jpg?fit=1000%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354221,"url":"https:\/\/casadecampoliving.com\/es\/reserve-la-fecha-para-el-torneo-de-golf-solidario-hogar-del-nino-del-proximo-ano\/","url_meta":{"origin":354286,"position":2},"title":"\u00a1Reserve la fecha para el Torneo de Golf Solidario Hogar del Ni\u00f1o del pr\u00f3ximo a\u00f1o!","author":"Casa de Campo Living","date":"13 Dic, 2021","format":false,"excerpt":"\u00a1El nuevo a\u00f1o no ha comenzado y ya tenemos eventos para apuntar en nuestro calendario! El Hogar del Ni\u00f1o celebrar\u00e1 su Torneo de Golf Solidario en Las Romana Country Club el 19 de febrero, es la manera perfecta de pasar un buen rato y ser caritativo. El golf es de\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/XXIV-Hogar-del-Nin%CC%83o-Solidarity-golf-tournament38-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/XXIV-Hogar-del-Nin%CC%83o-Solidarity-golf-tournament38-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/XXIV-Hogar-del-Nin%CC%83o-Solidarity-golf-tournament38-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/XXIV-Hogar-del-Nin%CC%83o-Solidarity-golf-tournament38-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354058,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-golf-proximos-torneos-de-mayo-a-diciembre-de-2021\/","url_meta":{"origin":354286,"position":3},"title":"Casa de Campo Golf: pr\u00f3ximos torneos de mayo a diciembre de 2021","author":"Casa de Campo Living","date":"11 May, 2021","format":false,"excerpt":"Casa de Campo es conocida mundialmente por ser uno de los resorts m\u00e1s completos y prestigiosos del Caribe\u2026 y esto se debe a varias razones; uno de los cuales es que tiene algunos de los mejores campos de golf del mundo; The Teeth of the Dog, Dye Fore y The\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8181-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8181-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8181-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8181-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":341917,"url":"https:\/\/casadecampoliving.com\/es\/enterese-de-los-proximos-torneos-de-golf-que-se-realizaran-en-casa-de-campo\/","url_meta":{"origin":354286,"position":4},"title":"\u00a1Ent\u00e9rese de los pr\u00f3ximos torneos de golf que se realizar\u00e1n en Casa de Campo!","author":"Mairobi Herrera","date":"15 Jun, 2013","format":false,"excerpt":"Casa de Campo, el Golf Resort L\u00edder del Mundo con sus tres campos de golf dise\u00f1ados por Pete Dye, \u00a0el arquitecto de campos de golf m\u00e1s influyente en los \u00faltimos 60 a\u00f1os, hace de este un lugar inolvidable para los amantes de Golf que lo visitan de todo el mundo.\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"golf tournamets","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/golf_tournament-1.jpg?fit=650%2C424&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/golf_tournament-1.jpg?fit=650%2C424&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/golf_tournament-1.jpg?fit=650%2C424&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":353955,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-golf-proximos-torneos-2021\/","url_meta":{"origin":354286,"position":5},"title":"Casa de Campo Golf: \u00a1Pr\u00f3ximos torneos 2021!","author":"Casa de Campo Living","date":"6 Ene, 2021","format":false,"excerpt":"El golf nunca se detiene en Casa de Campo, \u00a1y nos gusta as\u00ed! Casa de Campo es conocida mundialmente por ser uno de los resorts m\u00e1s completos y prestigiosos del Caribe\u2026 y esto se debe a varias razones; uno de los cuales es que tiene algunos de los mejores campos\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer-1.jpg?fit=1000%2C599&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer-1.jpg?fit=1000%2C599&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer-1.jpg?fit=1000%2C599&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer-1.jpg?fit=1000%2C599&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/21-Golf_-Teeth-of-the-Dog_-Golfer2-copy-1.jpg?fit=1000%2C602&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=354286"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354286\/revisions"}],"predecessor-version":[{"id":506408,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354286\/revisions\/506408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/331899"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=354286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=354286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=354286"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=354286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}