{"id":354118,"date":"2021-07-29T00:00:00","date_gmt":"2021-07-29T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/"},"modified":"2022-10-21T19:09:13","modified_gmt":"2022-10-21T23:09:13","slug":"marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","title":{"rendered":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares. En su pr\u00f3xima visita al teatro, notar\u00e1 que se han tomado medidas para garantizar la salud y seguridad de sus invitados, incluyendo filas m\u00e1s cortas en las concesiones y aforo reducido del auditorio para el distanciamiento social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas son algunas de las pol\u00edticas clave que han implementado. Las temperaturas se tomar\u00e1n a la llegada; se requieren m\u00e1scaras para los invitados y el equipo en todo el teatro; en el auditorio, todav\u00eda se requieren m\u00e1scaras, pero se pueden quitar mientras se disfruta de la comida y la bebida. Prot\u00e9jase y proteja a los dem\u00e1s usando una m\u00e1scara antes, durante y despu\u00e9s de su pel\u00edcula; recuerde mantener la distancia antes, durante y despu\u00e9s de la pel\u00edcula; y los auditorios se desinfectan antes de cada espect\u00e1culo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dada nuestra pasi\u00f3n por las pel\u00edculas, nos enorgullece presentarles un resumen de los nuevos estrenos de esta semana.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ESTRENOS<\/h3>\n\n\n\n<blockquote><h3>Jungle Cruise<\/h3><p><strong>Synopsis:<\/strong><\/p><p>Based on Disneyland\u2019s theme park ride where a small riverboat takes a group of travelers through a jungle filled with dangerous animals and reptiles but with a supernatural element.<\/p><p><strong>Showing:<\/strong><\/p><p>Monday \u2013 Friday 6:05 pm, 8:40 pm (ENG)<\/p><p>Saturday \u2013 Sunday 3:30 pm, 5:45 pm, 8:40 pm (ENG)<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/f_HvoipFcA8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3>OLD<\/h3><p><strong>Synopsis:<\/strong><\/p><p>A family on a tropical holiday discovers that the secluded beach where they are relaxing for a few hours is somehow causing them to age rapidly reducing their entire lives into a single day.<\/p><p><strong>Showing:<\/strong><\/p><p>Monday \u2013 Sunday 9:05 pm (ENG)<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/A4U2pMRV9_k\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">TODAV\u00cdA PROYECT\u00c1NDOSE<\/h3>\n\n\n\n<blockquote><h3>The Boss Baby: Family Business<\/h3><p><strong>Synopsis:<\/strong><\/p><p>The Templeton brothers have become adults and drifted away from each other, but a new boss baby with a cutting-edge approach is about to bring them together again \u2013 and inspire a new family business.<\/p><p><strong>Showing:<\/strong><\/p><p>Monday \u2013 Friday 6:40 pm (ENG)<\/p><p>Saturday \u2013 Sunday 4:15 pm, 6:40 pm (ENG)<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/QPzy8Ckza08\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3>SNAKE EYES<\/h3><p><strong>Synopsis:<\/strong><\/p><p>A G.I. Joe spin-off centered around the character of Snake Eyes.<\/p><p><strong>Showing:<\/strong><\/p><p>Monday \u2013 Sunday 8:45 pm (ENG)<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/VHg_UAfUgjA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3>SPACE JAM: A NEW LEGACY<\/h3><p><strong>Synopsis:<\/strong><\/p><p>A rogue artificial intelligence kidnaps the son of famed basketball player LeBron James, who then has to work with Bugs Bunny to win a basketball game.<\/p><p><strong>Showing:<\/strong><\/p><p>Monday \u2013 Friday 6:05 pm (ENG)<\/p><p>Saturday \u2013 Sunday 3:30 pm, 6:05 pm (ENG)<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/RCsEKvz2mxs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">PROXIMAMENTE<\/h3>\n\n\n\n<blockquote><h3>The Suicide Squad<\/h3><p><strong>Synopsis:<\/strong><\/p><p>Supervillains Harley Quinn, Bloodsport, Peacemaker, and a collection of nutty cons at Belle Reve prison join the super-secret, super-shady Task Force X as they are dropped off at the remote, enemy-infused island of Corto Maltese.<\/p><p><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/eg5ciqQzmK0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3>CARIBBEAN CINEMAS LA MARINA<\/h3><p><strong>Where:<\/strong>&nbsp;Coconut Mall, La Marina Casa de Campo<br>\n<strong>Tickets prices:<\/strong>&nbsp;Adults: RD$ 425.00, Kids (2-10 years old, only applies to films with age restriction) RD$ 300.00<br>\n<strong>Phone number:<\/strong>&nbsp;809-523-2351<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares. En su pr\u00f3xima visita al teatro, notar\u00e1 que se han tomado medidas para garantizar la salud y seguridad de sus invitados, incluyendo filas m\u00e1s cortas en las concesiones y [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":332646,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","newspack_content_restriction_is_exempt":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,3126,14631,2522,26581,14625,14627,2521,26822,19622],"tags":[25994,679,2780,26011,23815,26010,25835,25995,26005,2590,26007,26006,2558,26009,26003,26004,25993,26008],"newspack_spnsrs_tax":[],"class_list":["post-354118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-cine-3","category-estilo-de-vida","category-eventos-es","category-la-marina-casa-de-campo","category-noticias-locales","category-proximamente","category-republica-dominicana-2","category-resort-casa-de-campo","category-video-es-2","tag-black-widow","tag-caribbean-cinemas","tag-cartelera","tag-cartelera-la-marina-casa-de-campo","tag-casa-de-campo-es-17","tag-cine-en-la-marina-casa-de-campo","tag-cruella","tag-f9","tag-gi-joe","tag-la-marina-casa-de-campo","tag-la-saga-rapida","tag-new-estrenos","tag-peliculas","tag-peliculas-en-la-marina","tag-snake-eyes","tag-snake-eyes-movie","tag-space-jam","tag-todavia-en-cartelera","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-29T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:09:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto\",\"datePublished\":\"2021-07-29T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:09:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/\"},\"wordCount\":483,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1\",\"keywords\":[\"black widow\",\"Caribbean Cinemas\",\"cartelera\",\"cartelera la marina casa de campo\",\"Casa de Campo\",\"cine en la marina casa de campo\",\"cruella\",\"f9\",\"gi joe\",\"la marina casa de campo\",\"LA SAGA R\u00c1PIDA\",\"NEW ESTRENOS\",\"peliculas\",\"peliculas en la marina\",\"snake eyes\",\"snake eyes movie\",\"space jam\",\"TODAV\u00cdA en cartelera\"],\"articleSection\":[\"Casa de Campo Living @es\",\"Cine @es\",\"Estilo de Vida\",\"Eventos\",\"La Marina Casa de Campo\",\"Noticias Locales\",\"Proximamente\",\"Rep\u00fablica Dominicana @es\",\"Resort Casa de Campo\",\"Video\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/\",\"name\":\"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1\",\"datePublished\":\"2021-07-29T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:09:13+00:00\",\"description\":\"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living","description":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","og_locale":"es_ES","og_type":"article","og_title":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living","og_description":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.","og_url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2021-07-29T04:00:00+00:00","article_modified_time":"2022-10-21T23:09:13+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","type":"image\/png"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto","datePublished":"2021-07-29T04:00:00+00:00","dateModified":"2022-10-21T23:09:13+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/"},"wordCount":483,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","keywords":["black widow","Caribbean Cinemas","cartelera","cartelera la marina casa de campo","Casa de Campo","cine en la marina casa de campo","cruella","f9","gi joe","la marina casa de campo","LA SAGA R\u00c1PIDA","NEW ESTRENOS","peliculas","peliculas en la marina","snake eyes","snake eyes movie","space jam","TODAV\u00cdA en cartelera"],"articleSection":["Casa de Campo Living @es","Cine @es","Estilo de Vida","Eventos","La Marina Casa de Campo","Noticias Locales","Proximamente","Rep\u00fablica Dominicana @es","Resort Casa de Campo","Video"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","name":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio - 4 de agosto | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","datePublished":"2021-07-29T04:00:00+00:00","dateModified":"2022-10-21T23:09:13+00:00","description":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares.","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto","url":"http:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1"},"articleSection":"Casa de Campo Living @es","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["black widow","caribbean cinemas","cartelera","cartelera la marina casa de campo","casa de campo","cine en la marina casa de campo","cruella","f9","gi joe","la marina casa de campo","la saga r\u00e1pida","new estrenos","peliculas","peliculas en la marina","snake eyes","snake eyes movie","space jam","todav\u00eda en cartelera"],"dateCreated":"2021-07-29T04:00:00Z","datePublished":"2021-07-29T04:00:00Z","dateModified":"2022-10-21T23:09:13Z"},"rendered":"<meta name=\"parsely-title\" content=\"Marina Casa de Campo Cartelera de pel\u00edculas: 29 de julio &#8211; 4 de agosto\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-29-de-julio-4-de-agosto\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2021-07-29T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Casa de Campo Living @es\" \/>\n<meta name=\"parsely-tags\" content=\"black widow,caribbean cinemas,cartelera,cartelera la marina casa de campo,casa de campo,cine en la marina casa de campo,cruella,f9,gi joe,la marina casa de campo,la saga r\u00e1pida,new estrenos,peliculas,peliculas en la marina,snake eyes,snake eyes movie,space jam,todav\u00eda en cartelera\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1","jetpack-related-posts":[{"id":354102,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-15-al-21-de-julio\/","url_meta":{"origin":354118,"position":0},"title":"Marina Casa de Campo Cartelera de pel\u00edculas: 15 al 21 de julio","author":"Casa de Campo Living","date":"15 Jul, 2021","format":false,"excerpt":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares. En su pr\u00f3xima visita al teatro, notar\u00e1 que se han tomado medidas para garantizar la salud y seguridad de sus invitados, incluyendo filas m\u00e1s\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354113,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-22-28-de-julio\/","url_meta":{"origin":354118,"position":1},"title":"Marina Casa de Campo Cartelera de pel\u00edculas: 22-28 de julio","author":"Casa de Campo Living","date":"23 Jul, 2021","format":false,"excerpt":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares. En su pr\u00f3xima visita al teatro, notar\u00e1 que se han tomado medidas para garantizar la salud y seguridad de sus invitados, incluyendo filas m\u00e1s\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354122,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-peliculas-5-11-de-agosto\/","url_meta":{"origin":354118,"position":2},"title":"Marina Casa de Campo Cartelera de pel\u00edculas: 5-11 de agosto","author":"Casa de Campo Living","date":"5 Ago, 2021","format":false,"excerpt":"No hay nada como sentarse con unas palomitas de ma\u00edz calientes y una buena pel\u00edcula para disfrutar solo, con alguien especial o con amigos y familiares. En su pr\u00f3xima visita al teatro, notar\u00e1 que se han tomado medidas para garantizar la salud y seguridad de sus invitados, incluyendo filas m\u00e1s\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/cc_lamaricacdc_banner2048x1365-e1605895844463-1.png?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349335,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-3-9-de-marzo\/","url_meta":{"origin":354118,"position":3},"title":"Marina Casa de Campo cartelera de cine: 3 &#8211; 9 de marzo","author":"Felix Guerrero","date":"3 Mar, 2016","format":false,"excerpt":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos\u00a0nuevas pel\u00edculas: \u201c13 Horas\u201d y\u00a0\u201cFreeheld\u201d\u00a0\u201cSecret In Their Eyes\u201d,\u00a0\u201cLa Verdad Duele\u201d y\u00a0\u201cSteve Jobs\u201d.\u00a0Mientras todav\u00eda en sala tenemos:\u00a0\u201cZootopia\u201d. \u201c13 Horas\u201dProyecciones: Lunes \u2013 Viernes, 6:50pm & 9:25pm S\u00e1bado \u2013 Domingo,\u00a04:20pm, 6:50pm & 9:25pm Sinopsis: Cuando el\u00a0embajador estadounidense es asesinado durante\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"Cartelera 3 de Marzo 2016","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Marzo-2016.jpg?fit=796%2C347&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Marzo-2016.jpg?fit=796%2C347&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Marzo-2016.jpg?fit=796%2C347&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Marzo-2016.jpg?fit=796%2C347&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":350134,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-7-13-de-julio\/","url_meta":{"origin":354118,"position":4},"title":"Marina Casa de Campo cartelera de cine: 7 &#8211; 13 de Julio","author":"Felix Guerrero","date":"6 Jul, 2016","format":false,"excerpt":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos\u00a0nuevas pel\u00edculas: \u201cWarcraft\u201d y \u201cLa Era del Hielo 5: Choque de Mundos\u201d.\u00a0Mientras que en sala todav\u00eda tenemos:\u00a0\u201cBuscando a Dory\u201d y \u201cTe Amar\u00e9 Eternamente\u201d. \u201cWarcraft\u201cProyecciones: Lunes \u2013 Viernes, 6:55pm & 9:25pm S\u00e1bado \u2013 Domingo,\u00a04:20pm, 6:55pm & 9:25pm Sinopsis:\u00a0Mientras\u00a0una\u2026","rel":"","context":"En \u00abCine @es\u00bb","block_context":{"text":"Cine @es","link":"https:\/\/casadecampoliving.com\/es\/category\/cine-3\/"},"img":{"alt_text":"Cartelera 7 de Julio 2016","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-7-de-Julio-2016-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-7-de-Julio-2016-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-7-de-Julio-2016-1.jpg?fit=800%2C348&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-7-de-Julio-2016-1.jpg?fit=800%2C348&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349990,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-16-22-de-junio\/","url_meta":{"origin":354118,"position":5},"title":"Marina Casa de Campo cartelera de cine: 16 &#8211; 22 de junio","author":"Felix Guerrero","date":"16 Jun, 2016","format":false,"excerpt":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos\u00a0nuevas pel\u00edculas: \u201cEye In The Sky\u201d y\u00a0\u201cBuscando a Dory\u201d.\u00a0Mientras que en sala todav\u00eda tenemos:\u00a0\u201cAlicia A Trav\u00e9s del Espejo\u201d,\u00a0\u201cLos Ilusionistas 2\u201d y\u00a0\u201cMe Before You\u201d \u201cAlicia A Trav\u00e9s del Espejo\u201dProyecciones: Lunes \u2013 Viernes,\u00a07:00pm S\u00e1bado \u2013 Domingo, 4:35pm &\u00a07:00pm Sinopsis:\u00a0Alicia\u2026","rel":"","context":"En \u00abCine @es\u00bb","block_context":{"text":"Cine @es","link":"https:\/\/casadecampoliving.com\/es\/category\/cine-3\/"},"img":{"alt_text":"Cartelera 16 de Junio 2016","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-16-de-Junio-2016-1.jpg?fit=800%2C347&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-16-de-Junio-2016-1.jpg?fit=800%2C347&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-16-de-Junio-2016-1.jpg?fit=800%2C347&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-16-de-Junio-2016-1.jpg?fit=800%2C347&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=354118"}],"version-history":[{"count":0,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/354118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/332646"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=354118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=354118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=354118"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=354118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}