{"id":353569,"date":"2019-10-07T00:00:00","date_gmt":"2019-10-07T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/"},"modified":"2022-11-10T10:03:32","modified_gmt":"2022-11-10T14:03:32","slug":"flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","title":{"rendered":"Flavors by Casa de Campo \u00abSin desperdicios\u00bb demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada"},"content":{"rendered":"<p>Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s alto contenido gastron\u00f3mico reduciendo el desperdicio al m\u00ednimo absoluto, y tuvieron un \u00e9xito maravilloso. Se sirvieron dos cenas memorables, con preparativos que fueron muy elogiados por los asistentes que se fueron con un compromiso en mente, haciendo del mundo uno mejor.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"201759\" data-permalink=\"https:\/\/casadecampoliving.com\/es\/img_2467-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/IMG_2467.jpg?fit=1000%2C751&amp;ssl=1\" data-orig-size=\"1000,751\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 6D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570224088&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;28&quot;,&quot;iso&quot;:&quot;12800&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2467\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/IMG_2467.jpg?fit=1000%2C751&amp;ssl=1\" class=\"aligncenter size-full wp-image-201759\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2467.jpg?resize=1000%2C751&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"751\"><\/p>\n<p>Seg\u00fan una<a href=\"http:\/\/www.worldfooddayusa.org\/food_%20waste_the_facts\" target=\"_blank\" rel=\"noopener noreferrer\"> investigaci\u00f3n reciente,<\/a> cada a\u00f1o, un tercio de la producci\u00f3n mundial de alimentos se desecha literalmente: esto significa que aproximadamente 222 millones de toneladas de alimentos son desechados, una cantidad que es aproximadamente equivalente a la producci\u00f3n de alimentos del \u00c1frica subsahariana. Esta es la raz\u00f3n por la cual un n\u00famero cada vez mayor de personas se dedica a combatir el desperdicio en todos los niveles de la industria alimentaria incluido nuestro resort y su departamento culinario quienes han asumido la tarea de reducir el desperdicio de alimentos.<\/p>\n<p>En \u00abDon&#8217;t Waste\u00bb el Chef Anthony Masas elabor\u00f3 un men\u00fa <strong>aceptando<\/strong>&nbsp;productos que tradicionalmente no tienen un lugar en la cocina,&nbsp;<strong>aprovechando<\/strong>&nbsp;los ingredientes en su totalidad, de una manera integral,&nbsp;<strong>reaprovechando<\/strong>&nbsp;en favor de una segunda vida \u00fatil y deliciosa,&nbsp;<strong>reciclando<\/strong>&nbsp;para dotar a un preparado de nuevas y sabrosas formas,&nbsp;<strong>reeditando<\/strong>&nbsp;para cambiar el foco de visi\u00f3n, de una manera m\u00e1s imaginativa y&nbsp;<strong>utilizando<\/strong>&nbsp;lo que tradicionalmente se desestima. Todo ello bajo la convicci\u00f3n de que el protagonismo en la Alta Cocina no es monopolio estanco de unos pocos.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"201788\" data-permalink=\"https:\/\/casadecampoliving.com\/es\/sny00084-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/SNY00084.jpg?fit=1000%2C667&amp;ssl=1\" data-orig-size=\"1000,667\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;ILCE-7M3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570210676&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;44&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"SNY00084\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/SNY00084.jpg?fit=1000%2C667&amp;ssl=1\" class=\"aligncenter wp-image-201788 size-full\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/SNY00084.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"667\"><\/p>\n<p>Estructurado en diez platos y comprometido con el tema, pudimos ver bacalao, la espuma de huevo con sales arom\u00e1ticas y aceite de oliva, pan tostado con tomate y sardina, sopa de cebolla, el \u00abguiso de descartes\u00bb hecho con mariscos y pescados, entre otras creaciones deliciosas dando una demostraci\u00f3n de la habilidad, la creatividad y la sensibilidad de un chef capaz de enfrentar con \u00e9xito cualquier desaf\u00edo. (\u00a1fotos pronto!)<\/p>\n<p>El evento tuvo lugar en el recientemente renovado restaurante La Piazzetta. En la entrada, los invitados pudieron ver una instalaci\u00f3n de arte bastante \u00fanica del artista Argenis Lebron llamada \u00abOla de la Mar\u00bb creada usando botellas y bolsas de pl\u00e1stico reciclado, con luces iluminadas el camino y el sonido del oc\u00e9ano como tel\u00f3n de fondo. Una vez dentro, los invitados tambi\u00e9n pudieron las novedades del restaurante junto con incre\u00edbles piezas de arte reciclado de los estudiantes de Bellas Artes de primer a\u00f1o de la Chav\u00f3n Escuela de Dise\u00f1o.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"201761\" data-permalink=\"https:\/\/casadecampoliving.com\/es\/img_2475-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/IMG_2475.jpg?fit=1000%2C751&amp;ssl=1\" data-orig-size=\"1000,751\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 6D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1570225202&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;57&quot;,&quot;iso&quot;:&quot;1600&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2475\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2019\/10\/IMG_2475.jpg?fit=1000%2C751&amp;ssl=1\" class=\"aligncenter size-full wp-image-201761\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2475.jpg?resize=1000%2C751&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"751\"><\/p>\n<p>Un compromiso con la comida, el medio ambiente y la imaginaci\u00f3n tuvo lugar el pasado fin de semana, en el cual se present\u00f3 una forma reflexiva y responsable de cocinar a cada uno de los invitados de una manera espectacular. Lo invitamos a comprometerse con nosotros a adoptar una forma de vida m\u00e1s ecol\u00f3gica y sostenible \u00abSin desperdicios\u00bb como una forma de continuar lo que comenz\u00f3 esta edici\u00f3n de Flavors by Casa de Campo.<\/p>\n<p>Debajo algunos de los platos servidos durante la cena:<\/p>\n<p>[nggallery id=3272]<\/p>\n<p>Y una galer\u00eda de fotos tomada por Yafranny Melo durante la cena \u00abSin desperdicios\u00bb de Flavors by Casa de Campo el viernes 4 de octubre:<\/p>\n<p>[nggallery id=3271]<\/p>\n<p>Y por Mairobi Herrera:<\/p>\n<p>[nggallery id=3273]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s alto contenido gastron\u00f3mico reduciendo el desperdicio al m\u00ednimo absoluto, y tuvieron un \u00e9xito maravilloso. Se sirvieron dos cenas memorables, con preparativos que fueron muy elogiados [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":308480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26819,26820,2520,2521,2522,14629,14631,14625,26822],"tags":[12718,24319,14736,23931,11026],"newspack_spnsrs_tax":[],"class_list":["post-353569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altos-de-chavon-es","category-casa-de-campo-resort","category-restaurantes-es","category-republica-dominicana-2","category-eventos-es","category-comidas-bebidas","category-estilo-de-vida","category-noticias-locales","category-resort-casa-de-campo","tag-anthony-masas","tag-dont-waste","tag-featured-topview-es","tag-flavors-by-casa-de-campo","tag-gastronomia","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flavors by Casa de Campo &quot;Sin desperdicios&quot; demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flavors by Casa de Campo &quot;Sin desperdicios&quot; demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-07T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"Flavors by Casa de Campo \u00abSin desperdicios\u00bb demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada\",\"datePublished\":\"2019-10-07T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?fit=1000%2C751&ssl=1\",\"keywords\":[\"Anthony Masas\",\"Dont waste\",\"Featured-TopView @es\",\"Flavors by Casa de Campo\",\"gastronom\u00eda\"],\"articleSection\":[\"Altos de Chavon @es\",\"Casa de Campo Resort\",\"Restaurantes\",\"Rep\u00fablica Dominicana @es\",\"Eventos\",\"Comidas &amp; Bebidas\",\"Estilo de Vida\",\"Noticias Locales\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\",\"name\":\"Flavors by Casa de Campo \\\"Sin desperdicios\\\" demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?fit=1000%2C751&ssl=1\",\"datePublished\":\"2019-10-07T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:03:32+00:00\",\"description\":\"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?fit=1000%2C751&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?fit=1000%2C751&ssl=1\",\"width\":1000,\"height\":751},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flavors by Casa de Campo &#8220;Sin desperdicios&#8221; demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flavors by Casa de Campo \"Sin desperdicios\" demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living","description":"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","og_locale":"es_ES","og_type":"article","og_title":"Flavors by Casa de Campo \"Sin desperdicios\" demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living","og_description":"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s","og_url":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2019-10-07T04:00:00+00:00","article_modified_time":"2022-11-10T14:03:32+00:00","og_image":[{"width":1000,"height":751,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"Flavors by Casa de Campo \u00abSin desperdicios\u00bb demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada","datePublished":"2019-10-07T04:00:00+00:00","dateModified":"2022-11-10T14:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/"},"wordCount":583,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","keywords":["Anthony Masas","Dont waste","Featured-TopView @es","Flavors by Casa de Campo","gastronom\u00eda"],"articleSection":["Altos de Chavon @es","Casa de Campo Resort","Restaurantes","Rep\u00fablica Dominicana @es","Eventos","Comidas &amp; Bebidas","Estilo de Vida","Noticias Locales","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","url":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","name":"Flavors by Casa de Campo \"Sin desperdicios\" demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","datePublished":"2019-10-07T04:00:00+00:00","dateModified":"2022-11-10T14:03:32+00:00","description":"Los d\u00edas 4 y 5 de octubre, Casa de Campo Resort &amp; Villas y su departamento de Alimentos y Bebidas asumieron el desaf\u00edo de crear un men\u00fa con el m\u00e1s","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","width":1000,"height":751},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Flavors by Casa de Campo &#8220;Sin desperdicios&#8221; demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Flavors by Casa de Campo \u00abSin desperdicios\u00bb demostr\u00f3 que es posible una alta cocina ecol\u00f3gica y reformulada","url":"http:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1"},"articleSection":"Altos de Chavon @es","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["anthony masas","dont waste","featured-topview @es","flavors by casa de campo","gastronom\u00eda"],"dateCreated":"2019-10-07T04:00:00Z","datePublished":"2019-10-07T04:00:00Z","dateModified":"2022-11-10T14:03:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Flavors by Casa de Campo \\u00abSin desperdicios\\u00bb demostr\\u00f3 que es posible una alta cocina ecol\\u00f3gica y reformulada\",\"url\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/flavors-by-casa-de-campo-sin-desperdicios-demostro-que-es-posible-una-alta-cocina-ecologica-y-reformulada\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?resize=150%2C150&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_2460.jpg?fit=1000%2C751&ssl=1\"},\"articleSection\":\"Altos de Chavon @es\",\"author\":[{\"@type\":\"Person\",\"name\":\"Casa de Campo Living\"}],\"creator\":[\"Casa de Campo Living\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Casa de Campo Living\",\"logo\":\"https:\\\/\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png\"},\"keywords\":[\"anthony masas\",\"dont waste\",\"featured-topview @es\",\"flavors by casa de campo\",\"gastronom\\u00eda\"],\"dateCreated\":\"2019-10-07T04:00:00Z\",\"datePublished\":\"2019-10-07T04:00:00Z\",\"dateModified\":\"2022-11-10T14:03:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_2460.jpg?fit=1000%2C751&ssl=1","jetpack-related-posts":[{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":353569,"position":0},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":353560,"url":"https:\/\/casadecampoliving.com\/es\/flavors-by-casa-de-campo-sin-desperdicios-este-fin-de-semana\/","url_meta":{"origin":353569,"position":1},"title":"Flavors by Casa de Campo \u00abSin desperdicios\u00bb ESTE fin de semana","author":"Casa de Campo Resort","date":"30 Sep, 2019","format":false,"excerpt":"No exageramos cuando decimos que el desperdicio de comida es un problema de escala mundial. Algunas estimaciones dicen que arrojamos a la basura en torno a la mitad de los productos alimentarios que podr\u00edamos consumir. Esta terrible ineficiencia impone un estr\u00e9s adicional sobre nuestro planeta y repercute en toda la\u2026","rel":"","context":"En \u00abCasa de Campo Resort\u00bb","block_context":{"text":"Casa de Campo Resort","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-resort\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/2-1-1.jpg?fit=1000%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/2-1-1.jpg?fit=1000%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/2-1-1.jpg?fit=1000%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/2-1-1.jpg?fit=1000%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":353516,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-se-llena-de-hogueras-en-fire-la-tercera-cita-flavors-del-2019\/","url_meta":{"origin":353569,"position":2},"title":"Casa de Campo se llena de hogueras en Fire, la tercera cita Flavors del 2019","author":"Casa de Campo Resort","date":"8 Ago, 2019","format":false,"excerpt":"El pasado 2 y 3 de Agosto disciplinas tan complejas como la primatolog\u00eda, la prehistoria o la antropolog\u00eda se vistieron de alta cocina en Casa de Campo Resort & Villas. En esta ocasi\u00f3n el reto consisti\u00f3 en crear un men\u00fa del m\u00e1s alto contenido gastron\u00f3mico con tan solo una hoguera.\u2026","rel":"","context":"En \u00abCasa de Campo Resort\u00bb","block_context":{"text":"Casa de Campo Resort","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-resort\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Jorge-Rodriguez-Annie-Paniagua-Alfonso-Paniagua-Manuel-Rodriguez.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Jorge-Rodriguez-Annie-Paniagua-Alfonso-Paniagua-Manuel-Rodriguez.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Jorge-Rodriguez-Annie-Paniagua-Alfonso-Paniagua-Manuel-Rodriguez.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Jorge-Rodriguez-Annie-Paniagua-Alfonso-Paniagua-Manuel-Rodriguez.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":353619,"url":"https:\/\/casadecampoliving.com\/es\/reserve-la-fecha-para-el-ultimo-flavors-by-casa-de-campo-del-ano\/","url_meta":{"origin":353569,"position":3},"title":"Reserve la fecha para el \u00faltimo Flavors by Casa de Campo del a\u00f1o!","author":"Casa de Campo Resort","date":"2 Dic, 2019","format":false,"excerpt":"De una manera absolutamente creativa y novedosa, Casa de Campo Resort and Villas pone el foco en una de las much\u00edsimas dimensiones del acto alimentario y lo lleva a la mesa. As\u00ed nace el Flavors by Casa de Campo, que bajo un prisma social, hist\u00f3rico, antropol\u00f3gico, medioambiental o biol\u00f3gico plantea\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/SNY00029-2.jpg?fit=1000%2C601&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/SNY00029-2.jpg?fit=1000%2C601&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/SNY00029-2.jpg?fit=1000%2C601&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/SNY00029-2.jpg?fit=1000%2C601&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":337442,"url":"https:\/\/casadecampoliving.com\/es\/servicio-externo-de-catering-trae-colera-a-la-boda-2\/","url_meta":{"origin":353569,"position":4},"title":"Servicio externo de catering trae Colera a la boda!","author":"Rebecca Silvestri","date":"28 Ene, 2011","format":false,"excerpt":"El Hotel Casa de Campo y Costasur Dominicana, S.A., lamentan profundamente los casos de intoxicaci\u00f3n por alimentos sucedidos en una fiesta de bodas privada, realizada en una de las residencias privadas dentro de nuestro Resort. Siendo as\u00ed los hechos, debemos aclarar que los servicios de tal fiesta, no fueron provistos\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":337475,"url":"https:\/\/casadecampoliving.com\/es\/el-supermercado-de-casa-de-campo-2\/","url_meta":{"origin":353569,"position":5},"title":"El Supermercado de Casa de Campo!","author":"Rebecca Silvestri","date":"22 Jul, 2011","format":false,"excerpt":"\u00bfSab\u00eda usted que Casa de Campo tiene su propio supermercado y servicio de delivery? Para los que desean, ellos mandan alimentos frescos y de alta calidad directamente a su Casa de Campo villa! El Supermercado de Casa de Campo \u00a0y servicio de delivery ofrece una extensa variedad de productos alimenticios,\u2026","rel":"","context":"En \u00abComidas &amp; Bebidas\u00bb","block_context":{"text":"Comidas &amp; Bebidas","link":"https:\/\/casadecampoliving.com\/es\/category\/comidas-bebidas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_supermarket_catering-1.jpg?fit=565%2C673&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_supermarket_catering-1.jpg?fit=565%2C673&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_supermarket_catering-1.jpg?fit=565%2C673&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/353569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=353569"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/353569\/revisions"}],"predecessor-version":[{"id":504500,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/353569\/revisions\/504500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/308480"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=353569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=353569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=353569"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=353569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}