{"id":352922,"date":"2018-10-08T00:00:00","date_gmt":"2018-10-08T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/"},"modified":"2022-10-21T19:05:56","modified_gmt":"2022-10-21T23:05:56","slug":"casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","title":{"rendered":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el <a href=\"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/\">LAAC 2019 se jugar\u00eda nuevamente en Teeth of the Dog, Rep\u00fablica Dominicana.<\/a><br>\n<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Dise\u00f1ado por Pete Dye, considerado uno de los mejores arquitectos de golf del mundo, \u201cDientes de Perro\u201d (Par 72 de m\u00e1s de 7400 yardas) se inaugur\u00f3 en 1971 y en poco tiempo se convirti\u00f3 en una gema del Caribe. Fue una visi\u00f3n pionera la de Dye, quien crey\u00f3 que podr\u00eda crear algo verdaderamente extraordinario con vistas al Mar Caribe. As\u00ed, molde\u00f3 una obra maestra. En un principio, el campo de golf fue bautizado como \u201cCajuiles\u201d, en referencia a los \u00e1rboles que crec\u00edan en las monta\u00f1as. M\u00e1s tarde, el dise\u00f1ador lo cambi\u00f3 a \u201cDientes de Perro\u201d luego de escuchar a los nativos referirse a la roca de coral con ese nombre por la apariencia afilada. \u201cLa oportunidad de construir este campo desde el inicio es una experiencia que se vive una sola vez en la vida\u201d, se\u00f1alaba Dye, que tambi\u00e9n dise\u00f1\u00f3, junto a su esposa Alicia, Dye Fore y The Links, ambos campos de golf de los que tambi\u00e9n se enorgullece Casa de Campo (la cuarta cancha se llama Romana Country Club).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando empec\u00e9 a dise\u00f1arlo en 1970 no hab\u00eda en la zona ni siquiera 100 kil\u00f3metros de caminos pavimentados. Ahora puedes encontrar en Casa de Campo 3,500 hogares, un aeropuerto internacional y 50,000 personas trabajando. Voy a ser un poco ego\u00edsta con esto, pero ese campo inici\u00f3 todo el proceso de golf que hoy se vive en el pa\u00eds\u201d, enfatiz\u00f3 el afamado dise\u00f1ador. El campo est\u00e1 catalogado como el mejor del Caribe y se ubica en el Top-50 entre las canchas de todo el planeta.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1\" alt=\"\" class=\"wp-image-163326\" height=\"667\" width=\"1000\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?w=370 370w, https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?w=400 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cNos da un gran placer darle la bienvenida a nuestro pa\u00eds y a Casa de Campo al Latin America Amateur Championship. Este campeonato es un evento verdaderamente especial que est\u00e1 ayudando a que el golf crezca en toda nuestra regi\u00f3n y est\u00e1 abriendo un camino cada vez m\u00e1s grande para las futuras estrellas de golf de Am\u00e9rica Latina. Nos sentimos honrados de desempe\u00f1ar un papel y de compartir el apoyo a esta misi\u00f3n como anfitriones, y esperamos ver a los jugadores amateurs m\u00e1s talentosos una vez m\u00e1s a la altura de los desaf\u00edos que ofrece nuestro campo\u201d, indic\u00f3 Andr\u00e9s Pichardo Rosenberg, Presidente de Casa de Campo Resort &amp; Villas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por estos paradis\u00edacos fairways pasaron varios de los mejores golfistas del mundo y no hay un solo jugador que no haya elogiado la cancha. Adem\u00e1s de haber recibido al Latin America Amateur Championship en 2016, Teeth of the Dog fue sede del World Amateur Team Championships (Eisenhower Trophy y Espirito Santo Trophy) en 1974. Aquella edici\u00f3n la gan\u00f3 Estados Unidos, equipo que tuvo como integrantes a Jerry Pate y Curtis Strange, ganadores de tres U.S. Open entre ambos. De hecho, Pate fue una de las personalidades que se acerc\u00f3 a Casa de Campo a ver jugar a los mejores aficionados de la regi\u00f3n en la segunda edici\u00f3n del LAAC. \u201cLa cancha sigue estando en excelentes condiciones, not\u00e9 que se ha cambiado el c\u00e9sped de Bermuda a Paspalum. En mi opini\u00f3n, lo mejor es que sigue siendo una magn\u00edfica prueba de golf, es realmente un desaf\u00edo para estos j\u00f3venes\u201d, coment\u00f3 Pate durante el campeonato.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/654406hoyo-8-b-e1539005863463.jpg?resize=1000%2C665&amp;ssl=1\" alt=\"\" class=\"wp-image-163327\" height=\"665\" width=\"1000\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/654406hoyo-8-b-e1539005863463.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/654406hoyo-8-b-e1539005863463.jpg?w=370 370w, https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/654406hoyo-8-b-e1539005863463.jpg?w=400 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cDientes de Perro\u201d tambi\u00e9n recibi\u00f3 al PGA TOUR Latinoam\u00e9rica en dos ocasiones, en 2015 el mexicano Rodolfo Cazaub\u00f3n se qued\u00f3 con el t\u00edtulo y en 2016 la victoria fue para el estadounidense Timothy O\u00b4Neal. \u201cEs una cancha que hay que respetar, no es f\u00e1cil jugar bajo par y menos a\u00fan en los d\u00edas de torneos con la presi\u00f3n. Sin dudas ganar en una cancha de Pete Dye es un orgullo\u201d, se\u00f1alaba el mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fundado por el Masters Tournament, The R&amp;A y la United States Golf Association (USGA), el LAAC fue creado para desarrollar a\u00fan m\u00e1s el golf amateur en toda la regi\u00f3n, y en forma espec\u00edfica en Am\u00e9rica del Sur, Central, M\u00e9xico y el Caribe. Cada a\u00f1o, el campe\u00f3n del LAAC recibe una invitaci\u00f3n para competir en el Masters Tournament en Augusta National. Adem\u00e1s, el ganador y el jugador o jugadores que terminen en el segundo lugar ingresan en forma directa a las fases finales de clasificaci\u00f3n para ingresar a The Open y al U.S. Open Championship. Por \u00faltimo, el campe\u00f3n recibe exenciones completas para disputar The Amateur, el U.S. Amateur Championship y todo otro campeonato amateur de la USGA para el cual sea elegible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El LAAC regresa a uno de los resorts m\u00e1s afamados del mundo y, sin dudas, no ser\u00e1 la \u00faltima vez que los mejores jugadores aficionados de la regi\u00f3n intenten descubrir el tesoro m\u00e1s preciado en Teeth of The Dog.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Informaci\u00f3n y fotos cortes\u00eda de<a href=\"http:\/\/www.laacgolf.com\/\" target=\"_blank\" rel=\"noopener\">&nbsp;LAAC<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el LAAC 2019 se jugar\u00eda nuevamente en Teeth of the Dog, Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":36791,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","newspack_content_restriction_is_exempt":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2525,14631,2522,14627,2521,26822],"tags":[22456,23815,22371,18629,14736,22455,18932,22454,22457,14777,177],"newspack_spnsrs_tax":[],"class_list":["post-352922","post","type-post","status-publish","format-standard","hentry","category-golf-deportes-es","category-estilo-de-vida","category-eventos-es","category-proximamente","category-republica-dominicana-2","category-resort-casa-de-campo","tag-campeonato-de-amateur-latinoamericano","tag-casa-de-campo-es-17","tag-dientes-del-perro","tag-dominican-republic-es-5","tag-featured-topview-es","tag-ganador-de-laac","tag-la-romana-es-4","tag-laac-republica-dominicana","tag-pabellon-de-pablo","tag-republica-dominicana-es-18","tag-teeth-of-the-dog","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-08T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019\",\"datePublished\":\"2018-10-08T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/\"},\"wordCount\":869,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving-wp.s3-accelerate.amazonaws.com\\\/2018\\\/10\\\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1\",\"keywords\":[\"CAMPEONATO DE AMATEUR LATINOAMERICANO\",\"Casa de Campo\",\"DIENTES DEL PERRO\",\"Dominican Republic\",\"Featured-TopView @es\",\"GANADOR DE LAAC\",\"La Romana\",\"LAAC REP\u00daBLICA DOMINICANA\",\"PABELL\u00d3N DE PABLO\",\"Republica Dominicana\",\"Teeth of the Dog\"],\"articleSection\":[\"Deportes\",\"Estilo de Vida\",\"Eventos\",\"Proximamente\",\"Rep\u00fablica Dominicana @es\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/\",\"name\":\"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving-wp.s3-accelerate.amazonaws.com\\\/2018\\\/10\\\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1\",\"datePublished\":\"2018-10-08T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:05:56+00:00\",\"description\":\"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving-wp.s3-accelerate.amazonaws.com\\\/2018\\\/10\\\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving-wp.s3-accelerate.amazonaws.com\\\/2018\\\/10\\\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living","description":"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living","og_description":"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el","og_url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2018-10-08T04:00:00+00:00","article_modified_time":"2022-10-21T23:05:56+00:00","og_image":[{"url":"https:\/\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg","type":"","width":"","height":""}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019","datePublished":"2018-10-08T04:00:00+00:00","dateModified":"2022-10-21T23:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/"},"wordCount":869,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1","keywords":["CAMPEONATO DE AMATEUR LATINOAMERICANO","Casa de Campo","DIENTES DEL PERRO","Dominican Republic","Featured-TopView @es","GANADOR DE LAAC","La Romana","LAAC REP\u00daBLICA DOMINICANA","PABELL\u00d3N DE PABLO","Republica Dominicana","Teeth of the Dog"],"articleSection":["Deportes","Estilo de Vida","Eventos","Proximamente","Rep\u00fablica Dominicana @es","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","name":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019 | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1","datePublished":"2018-10-08T04:00:00+00:00","dateModified":"2022-10-21T23:05:56+00:00","description":"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving-wp.s3-accelerate.amazonaws.com\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=1000%2C667&amp;ssl=1"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019","url":"http:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Deportes","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["campeonato de amateur latinoamericano","casa de campo","dientes del perro","dominican republic","featured-topview @es","ganador de laac","la romana","laac rep\u00fablica dominicana","pabell\u00f3n de pablo","republica dominicana","teeth of the dog"],"dateCreated":"2018-10-08T04:00:00Z","datePublished":"2018-10-08T04:00:00Z","dateModified":"2022-10-21T23:05:56Z"},"rendered":"<meta name=\"parsely-title\" content=\"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-pub-date\" content=\"2018-10-08T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Deportes\" \/>\n<meta name=\"parsely-tags\" content=\"campeonato de amateur latinoamericano,casa de campo,dientes del perro,dominican republic,featured-topview @es,ganador de laac,la romana,laac rep\u00fablica dominicana,pabell\u00f3n de pablo,republica dominicana,teeth of the dog\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":352407,"url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","url_meta":{"origin":352922,"position":0},"title":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas","author":"Casa de Campo Resort","date":"22 Ene, 2018","format":false,"excerpt":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort & Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se llevar\u00e1 a cabo del 17 al 20 de enero de 2019, en el afamado campo Teeth of the Dog \/Diente de Perro. El anuncio fue realizado\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":353065,"url":"https:\/\/casadecampoliving.com\/es\/laac-2019-se-confirmo-el-field-de-jugadores\/","url_meta":{"origin":352922,"position":1},"title":"LAAC 2019: Se confirm\u00f3 el field de jugadores","author":"Casa de Campo Living","date":"20 Dic, 2018","format":false,"excerpt":"Los mejores 108 aficionados de 28 pa\u00edses de la regi\u00f3n estar\u00e1n del 17 al 20 de enero de 2019 en Casa de Campo, Rep\u00fablica Dominicana para disputar la quinta edici\u00f3n del Latin America Amateur Championship, el torneo al que los propios jugadores denominaron el \u201cMajor\u201d de los amateurs. During the\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":352966,"url":"https:\/\/casadecampoliving.com\/es\/el-laac-2019-se-presento-ante-la-prensa-de-republica-dominicana\/","url_meta":{"origin":352922,"position":2},"title":"El LAAC 2019 se present\u00f3 ante la prensa de Rep\u00fablica Dominicana","author":"Casa de Campo Living","date":"29 Oct, 2018","format":false,"excerpt":"Se realiz\u00f3 la presentaci\u00f3n del Latin America Amateur Championship (LAAC) ante los medios de comunicaci\u00f3n m\u00e1s importantes de Rep\u00fablica Dominicana, que ser\u00e1 la sede del campeonato m\u00e1s importante de la regi\u00f3n del 17 al 20 de enero de 2019 en la cancha de Teeth of the Dog en Casa de\u2026","rel":"","context":"En \u00abM\u00e1s all\u00e1 de Casa\u00bb","block_context":{"text":"M\u00e1s all\u00e1 de Casa","link":"https:\/\/casadecampoliving.com\/es\/category\/mas-alla-de-casa-es\/"},"img":{"alt_text":"IMG_1507","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":354153,"url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-2022-regresa-a-casa-de-campo-en-republica-dominicana\/","url_meta":{"origin":352922,"position":3},"title":"El Latin America Amateur Championship 2022 regresa a Casa de Campo en Rep\u00fablica Dominicana","author":"Casa de Campo Living","date":"17 Sep, 2021","format":false,"excerpt":"La s\u00e9ptima edici\u00f3n del Latin America Amateur Championship (LAAC) se llevar\u00e1 a cabo en Casa de Campo Resort & Villas, Rep\u00fablica Dominicana, del 20 al 23 de Enero de 2022. El LAAC 2021, originalmente programado del 14 al 17 de enero en el Lima Golf Club en Per\u00fa, fue cancelado\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354190,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-el-marco-perfecto-para-el-regreso-del-latin-america-amateur-championship-2022\/","url_meta":{"origin":352922,"position":4},"title":"Casa de Campo, el marco perfecto para el regreso del Latin America Amateur Championship 2022","author":"Casa de Campo Living","date":"2 Nov, 2021","format":false,"excerpt":"Casa de Campo Resort & Villas y el Latin America Amateur Championship forjaron una relaci\u00f3n fuerte e irrompible desde el mismo instante en que sus caminos se cruzaron all\u00e1 por 2016 cuando el resort de golf de La Romana, Rep\u00fablica Dominicana, recibi\u00f3 por primera vez al \u201cMajor\u201d de los aficionados.\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354253,"url":"https:\/\/casadecampoliving.com\/es\/el-torito-alento-a-los-jugadores-locales-y-recibio-consejos-de-golf-en-la-previa-del-laac-2022\/","url_meta":{"origin":352922,"position":5},"title":"El Torito alent\u00f3 a los jugadores locales y recibi\u00f3 consejos de golf en la previa del LAAC 2022","author":"Casa de Campo Living","date":"19 Ene, 2022","format":false,"excerpt":"La mascota de los Toros del Este, el tradicional equipo de b\u00e9isbol de La Romana, Rep\u00fablica Dominicana, fue invitado por la organizaci\u00f3n del Latin America Amateur Championship (LAAC) para alentar a los jugadores locales que participar\u00e1n a partir de este jueves del campeonato de golf para aficionados m\u00e1s importante de\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/6408363EB5_5465-1-1-1.jpg?fit=1000%2C607&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/6408363EB5_5465-1-1-1.jpg?fit=1000%2C607&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/6408363EB5_5465-1-1-1.jpg?fit=1000%2C607&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/6408363EB5_5465-1-1-1.jpg?fit=1000%2C607&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=352922"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352922\/revisions"}],"predecessor-version":[{"id":352923,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352922\/revisions\/352923"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=352922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=352922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=352922"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=352922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}