{"id":352407,"date":"2018-01-22T00:00:00","date_gmt":"2018-01-22T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/"},"modified":"2022-10-21T19:06:58","modified_gmt":"2022-10-21T23:06:58","slug":"el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","title":{"rendered":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se llevar\u00e1 a cabo del 17 al 20 de enero de 2019, en el afamado campo Teeth of the Dog \/Diente de Perro. El anuncio fue realizado este s\u00e1bado durante el LAAC 2018 que se est\u00e1 disputando en Santiago de Chile, uno de los eventos m\u00e1s importantes para los jugadores Amateurs de Am\u00e9rica Latina.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Fundado por el Masters Tournament, The R&amp;A y la United States Golf Association (USGA), el LAAC fue creado para desarrollar a\u00fan m\u00e1s el golf amateur en toda la regi\u00f3n, y en forma espec\u00edfica en Am\u00e9rica del Sur, Central, M\u00e9xico y el Caribe. Cada a\u00f1o, el campe\u00f3n del LAAC recibe una invitaci\u00f3n para competir en el Masters Tournament en Augusta National. Adem\u00e1s, el ganador y el jugador o jugadores que terminen en el segundo lugar ingresan en forma directa a las fases finales de clasificaci\u00f3n para ingresar a The Open y al U.S. Open Championship.<\/p>\n\n\n<div class=\"wp-block-image wp-image-116242\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?resize=900%2C562&amp;ssl=1\" alt=\"\" class=\"wp-image-116242\" height=\"562\" width=\"900\"\/><figcaption>Paul Chaplet de Costa Rica y Jorge Garcia de Venezuela con el trofeo del Lat\u00edn Am\u00e9rica Amateur Championship 2016 en Casa de Campo el domingo 17 de enero, 2016. Enrique Berardi\/LAAC<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El LAAC 2019 marcar\u00e1 el regreso del campeonato a Casa de Campo Resort, que fue sede del evento en 2016. El espectacular campo de Teeth of the Dog\/Diente de Perro tendr\u00e1 el privilegio de volver a ser la sede del LAAC. Esta cancha dise\u00f1ada por Pete Dye est\u00e1 considerada como una de las m\u00e1s prestigiosas de la regi\u00f3n. &nbsp;\u201cNos sentimos muy honrados en tener el honor y ser elegidos nuevamente como anfitri\u00f3n del Campeonato Amateur Am\u00e9rica Latina para el a\u00f1o 2019\u201d, dijo Robert Robert Birtel, director de golf de Casa de Campo. Agreg\u00f3 que: \u201cLes esperamos&nbsp; para trabajar junto con la Federaci\u00f3n de Golf de Rep\u00fablica Dominicana y&nbsp; organizar nuevamente este prestigioso evento.&nbsp; Nuestro \u201cTeeth of the Dog\u201d o \u201cDiente de Perro\u201d obra maestra del afamado Pete Dye es un&nbsp; muy conocido en el mundo del golf; ciertamente les ser\u00e1 una maravillosa prueba de golf este pr\u00f3ximo a\u00f1o\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento inaugural del LAAC se jug\u00f3 en 2015 en Pilar Golf, Buenos Aires, Argentina y tuvo como ganador al chileno Mat\u00edas Dom\u00ednguez. En 2016, el costarricense Paul Chaplet triunf\u00f3 en la segunda edici\u00f3n del LAAC en Teeth of The Dog en Casa de Campo, Rep\u00fablica Dominicana. Y en 2017, el chileno Toto Gana levant\u00f3 la copa en el Club de Golf de Panam\u00e1. Esta semana, el LAAC 2018 se est\u00e1 desarrollando en el Prince of Wales Country Club y cuenta con un gran field integrado por los mejores 105 aficionados de Latinoam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Pie de foto principal: Robert Birtel director de golf de Casa de Campo junto a los representantes de la Royal and Ancient (R&amp;A), The United States Golf Association (USGA), y The Masters Tournament al momento del anuncio.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se llevar\u00e1 a cabo del 17 al 20 de enero de 2019, en el afamado campo Teeth of the Dog \/Diente de Perro. El anuncio fue realizado este s\u00e1bado durante el LAAC [&hellip;]<\/p>\n","protected":false},"author":36675,"featured_media":279426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2525,14631,2522,14625,14627,2521,26822],"tags":[22456,23815,22371,22455,176,18932,13994,22453,22454,22457,14777,15833,177],"newspack_spnsrs_tax":[],"class_list":["post-352407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-golf-deportes-es","category-estilo-de-vida","category-eventos-es","category-noticias-locales","category-proximamente","category-republica-dominicana-2","category-resort-casa-de-campo","tag-campeonato-de-amateur-latinoamericano","tag-casa-de-campo-es-17","tag-dientes-del-perro","tag-ganador-de-laac","tag-golf","tag-la-romana-es-4","tag-laac","tag-laac-2019","tag-laac-republica-dominicana","tag-pabellon-de-pablo","tag-republica-dominicana-es-18","tag-robert-birtel","tag-teeth-of-the-dog","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-22T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:06:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Resort\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Resort\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/\"},\"author\":{\"name\":\"Casa de Campo Resort\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/52642ac476979f209529cc58bb6c9787\"},\"headline\":\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas\",\"datePublished\":\"2018-01-22T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:06:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/\"},\"wordCount\":523,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1\",\"keywords\":[\"CAMPEONATO DE AMATEUR LATINOAMERICANO\",\"Casa de Campo\",\"DIENTES DEL PERRO\",\"GANADOR DE LAAC\",\"Golf\",\"La Romana\",\"LAAC\",\"Laac 2019\",\"LAAC REP\u00daBLICA DOMINICANA\",\"PABELL\u00d3N DE PABLO\",\"Republica Dominicana\",\"Robert Birtel\",\"Teeth of the Dog\"],\"articleSection\":[\"Deportes\",\"Estilo de Vida\",\"Eventos\",\"Noticias Locales\",\"Proximamente\",\"Rep\u00fablica Dominicana @es\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/\",\"name\":\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort & Villas | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1\",\"datePublished\":\"2018-01-22T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:06:58+00:00\",\"description\":\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1\",\"width\":650,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/52642ac476979f209529cc58bb6c9787\",\"name\":\"Casa de Campo Resort\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Resort\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/cdc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort & Villas | Casa de Campo Living","description":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","og_locale":"es_ES","og_type":"article","og_title":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort & Villas | Casa de Campo Living","og_description":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se","og_url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2018-01-22T04:00:00+00:00","article_modified_time":"2022-10-21T23:06:58+00:00","og_image":[{"width":650,"height":406,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","type":"image\/jpeg"}],"author":"Casa de Campo Resort","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Resort","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/"},"author":{"name":"Casa de Campo Resort","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/52642ac476979f209529cc58bb6c9787"},"headline":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas","datePublished":"2018-01-22T04:00:00+00:00","dateModified":"2022-10-21T23:06:58+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/"},"wordCount":523,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","keywords":["CAMPEONATO DE AMATEUR LATINOAMERICANO","Casa de Campo","DIENTES DEL PERRO","GANADOR DE LAAC","Golf","La Romana","LAAC","Laac 2019","LAAC REP\u00daBLICA DOMINICANA","PABELL\u00d3N DE PABLO","Republica Dominicana","Robert Birtel","Teeth of the Dog"],"articleSection":["Deportes","Estilo de Vida","Eventos","Noticias Locales","Proximamente","Rep\u00fablica Dominicana @es","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","name":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort & Villas | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","datePublished":"2018-01-22T04:00:00+00:00","dateModified":"2022-10-21T23:06:58+00:00","description":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &amp; Villas en Rep\u00fablica Dominicana para celebrar la quinta edici\u00f3n, que se","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","width":650,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/52642ac476979f209529cc58bb6c9787","name":"Casa de Campo Resort","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/630e193f5d6de4142cc28292ac77a3b7ec1b8b66d948ac83f36a80720ef224d5?s=96&d=mm&r=g","caption":"Casa de Campo Resort"},"url":"https:\/\/casadecampoliving.com\/es\/author\/cdc\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas","url":"http:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1"},"articleSection":"Deportes","author":[{"@type":"Person","name":"Casa de Campo Resort"}],"creator":["Casa de Campo Resort"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["campeonato de amateur latinoamericano","casa de campo","dientes del perro","ganador de laac","golf","la romana","laac","laac 2019","laac rep\u00fablica dominicana","pabell\u00f3n de pablo","republica dominicana","robert birtel","teeth of the dog"],"dateCreated":"2018-01-22T04:00:00Z","datePublished":"2018-01-22T04:00:00Z","dateModified":"2022-10-21T23:06:58Z"},"rendered":"<meta name=\"parsely-title\" content=\"El Latin America Amateur Championship (LAAC) regresar\u00e1 a Casa de Campo Resort &#038; Villas\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-laac-regresara-casa-de-campo-resort-villas\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2018-01-22T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Deportes\" \/>\n<meta name=\"parsely-tags\" content=\"campeonato de amateur latinoamericano,casa de campo,dientes del perro,ganador de laac,golf,la romana,laac,laac 2019,laac rep\u00fablica dominicana,pabell\u00f3n de pablo,republica dominicana,robert birtel,teeth of the dog\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Resort\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":352966,"url":"https:\/\/casadecampoliving.com\/es\/el-laac-2019-se-presento-ante-la-prensa-de-republica-dominicana\/","url_meta":{"origin":352407,"position":0},"title":"El LAAC 2019 se present\u00f3 ante la prensa de Rep\u00fablica Dominicana","author":"Casa de Campo Living","date":"29 Oct, 2018","format":false,"excerpt":"Se realiz\u00f3 la presentaci\u00f3n del Latin America Amateur Championship (LAAC) ante los medios de comunicaci\u00f3n m\u00e1s importantes de Rep\u00fablica Dominicana, que ser\u00e1 la sede del campeonato m\u00e1s importante de la regi\u00f3n del 17 al 20 de enero de 2019 en la cancha de Teeth of the Dog en Casa de\u2026","rel":"","context":"En \u00abM\u00e1s all\u00e1 de Casa\u00bb","block_context":{"text":"M\u00e1s all\u00e1 de Casa","link":"https:\/\/casadecampoliving.com\/es\/category\/mas-alla-de-casa-es\/"},"img":{"alt_text":"IMG_1507","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_1507.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":353065,"url":"https:\/\/casadecampoliving.com\/es\/laac-2019-se-confirmo-el-field-de-jugadores\/","url_meta":{"origin":352407,"position":1},"title":"LAAC 2019: Se confirm\u00f3 el field de jugadores","author":"Casa de Campo Living","date":"20 Dic, 2018","format":false,"excerpt":"Los mejores 108 aficionados de 28 pa\u00edses de la regi\u00f3n estar\u00e1n del 17 al 20 de enero de 2019 en Casa de Campo, Rep\u00fablica Dominicana para disputar la quinta edici\u00f3n del Latin America Amateur Championship, el torneo al que los propios jugadores denominaron el \u201cMajor\u201d de los amateurs. During the\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":354153,"url":"https:\/\/casadecampoliving.com\/es\/el-latin-america-amateur-championship-2022-regresa-a-casa-de-campo-en-republica-dominicana\/","url_meta":{"origin":352407,"position":2},"title":"El Latin America Amateur Championship 2022 regresa a Casa de Campo en Rep\u00fablica Dominicana","author":"Casa de Campo Living","date":"17 Sep, 2021","format":false,"excerpt":"La s\u00e9ptima edici\u00f3n del Latin America Amateur Championship (LAAC) se llevar\u00e1 a cabo en Casa de Campo Resort & Villas, Rep\u00fablica Dominicana, del 20 al 23 de Enero de 2022. El LAAC 2021, originalmente programado del 14 al 17 de enero en el Lima Golf Club en Per\u00fa, fue cancelado\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/24367955851_f2d1b71676_o-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":352922,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-sera-sede-del-campeonato-amateur-de-america-latina-laac-en-2019\/","url_meta":{"origin":352407,"position":3},"title":"Casa de Campo ser\u00e1 sede del Campeonato Amateur de Am\u00e9rica Latina (LAAC) en 2019","author":"Casa de Campo Living","date":"8 Oct, 2018","format":false,"excerpt":"La confirmaci\u00f3n oficial lleg\u00f3 el 20 de enero de 2018 cuando las tres instituciones que organizan el campeonato anunciaron en el Prince of Wales CC que el LAAC 2019 se jugar\u00eda nuevamente en Teeth of the Dog, Rep\u00fablica Dominicana. Dise\u00f1ado por Pete Dye, considerado uno de los mejores arquitectos de\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/10\/5110317Pete_Dye_20160111_001717_P-e1539005763821.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":330353,"url":"https:\/\/casadecampoliving.com\/laac-2019-se-confirmo-el-field-de-jugadores\/","url_meta":{"origin":352407,"position":4},"title":"LAAC 2019: Confirmed players entries","author":"Casa de Campo Living","date":"20 Dic, 2018","format":false,"excerpt":"The best 108 amateurs from 28 countries in the region will be in Casa de Campo from January 17 to 20, 2019 to participate in the fifth edition of the Latin American Amateur Championship, the tournament that the players themselves called the amateurs \u201cMayor\u201d. During the final round of the\u2026","rel":"","context":"En \u00abDominican Republic\u00bb","block_context":{"text":"Dominican Republic","link":"https:\/\/casadecampoliving.com\/category\/dominican-republic\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/24154839720_3e0323c02b_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":354190,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-el-marco-perfecto-para-el-regreso-del-latin-america-amateur-championship-2022\/","url_meta":{"origin":352407,"position":5},"title":"Casa de Campo, el marco perfecto para el regreso del Latin America Amateur Championship 2022","author":"Casa de Campo Living","date":"2 Nov, 2021","format":false,"excerpt":"Casa de Campo Resort & Villas y el Latin America Amateur Championship forjaron una relaci\u00f3n fuerte e irrompible desde el mismo instante en que sus caminos se cruzaron all\u00e1 por 2016 cuando el resort de golf de La Romana, Rep\u00fablica Dominicana, recibi\u00f3 por primera vez al \u201cMajor\u201d de los aficionados.\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Alvaro-Ortiz-1024x683-1-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/LAAC_Final_Round_es-e1453149758713.jpg?fit=650%2C406&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36675"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=352407"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352407\/revisions"}],"predecessor-version":[{"id":352408,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352407\/revisions\/352408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/279426"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=352407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=352407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=352407"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=352407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}