{"id":352338,"date":"2017-12-26T00:00:00","date_gmt":"2017-12-26T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/"},"modified":"2022-12-19T10:24:25","modified_gmt":"2022-12-19T14:24:25","slug":"hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","title":{"rendered":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR"},"content":{"rendered":"\n<p>On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the \u201cNacimiento Viviente\u201d) performed by the children of the Fundaci\u00f3n MIR on the Altos de Chav\u00f3n\u2019s main plaza in front of the St Stanislaus church.\u00a0<span id=\"more-41912\"><\/span><\/p>\n\n<!--more-->\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3498.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-152106\"\/><\/figure>\n<\/div>\n<p>This activity has become a tradition and it is part of the holiday program prepared by Altos de Chav\u00f3n and Casa de Campo. Continuing more than 2 weeks of continuous Christmas celebrations in Altos de Chav\u00f3n including the <a href=\"https:\/\/casadecampoliving.com\/christmas-tree-lighting-ceremony-perfect-start-to-a-magical-season\/\" target=\"_blank\" rel=\"noopener\">Christmas Tree Lighting Ceremony,<\/a>\u00a0<a href=\"https:\/\/casadecampoliving.com\/spreading-christmas-cheer-around-altos-de-chavon\/\" target=\"_blank\" rel=\"noopener\">Maracas workshop and traditional aguinaldo,<\/a>\u00a0<a href=\"https:\/\/casadecampoliving.com\/dolls-come-to-life-in-elizabeth-p-de-zellers-christmas-performance-in-altos-de-chavon\/\" target=\"_blank\" rel=\"noopener\">a ballet presentation by the\u00a0Elizabeth P. de Zeller\u2019s<\/a>, and the opening of the photographic exhibition <a href=\"https:\/\/casadecampoliving.com\/dont-miss-photographic-exhibition-los-almendrones-gallery\/\" target=\"_blank\" rel=\"noopener\">\u00abLos Almendrone<\/a><a href=\"https:\/\/casadecampoliving.com\/dont-miss-photographic-exhibition-los-almendrones-gallery\/\" target=\"_blank\" rel=\"noopener\">s\u00bb ,\u00a0<\/a>the talented\u00a0children of the Fundaci\u00f3n MIR brought the real Christmas story alive with their annual performance the \u201cNacimiento Viviente MIR.\u201d Taking part in the lyrical show were children of all ages, from the Primaria MIR (infant school), the MIR Esperanza (the boys\u2019 school) and the Polit\u00e9cnico MIR\u00a0(the girls\u2019 school).<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3593.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-152108\"\/><\/figure>\n<\/div>\n<p>With the majestic\u00a0St. Stanislaus church creating a magical backdrop the Christmas story was narrated by senior students of the Fundaci\u00f3n MIR, while the rest of the boys and girls dressed as angels, farmers, the Three Kings, Joseph, Mary, and many other characters \u2013 thrilled the audience with their impressive articulation and acting, complimented by dancing and the beautiful singing of the Fundaci\u00f3n MIR choir (consisting of an older group of students), who throughout the story interpreted various holiday songs. Even our local donkey, Margarito, had a special part in the presentation!<\/p>\n\n<p>Congratulations to all of the children who took part in this wonderful event, and many thanks to those involved in the organization!<\/p>\n\n<p>See below a collection of photos taken by Alejandro Heredia of the live nativity that took place last Friday, December 22nd:<\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417129\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417129\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3490.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417160\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417160\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3499.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417182\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417182\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3506.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417208\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417208\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3509.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417229\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417229\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3513.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417258\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417258\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3518.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417289\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417289\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3524.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417309\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417309\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3527.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417338\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417338\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3529.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417353\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417353\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3531.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417386\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417386\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3537.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417412\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417412\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3539.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417437\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417437\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3541.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417463\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417463\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3543.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417486\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417486\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3550.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417515\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417515\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3555.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417547\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417547\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3566.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417575\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417575\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3567.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" data-id=\"417607\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?resize=667%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-417607\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?w=667&amp;ssl=1 667w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3581.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417630\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417630\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3587.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417657\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417657\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3600.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417682\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417682\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3608-2.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417709\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417709\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3620.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417733\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417733\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3624.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417759\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417759\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3632.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"417791\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-417791\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3636.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the \u201cNacimiento Viviente\u201d) performed by the children of the Fundaci\u00f3n MIR on the Altos de Chav\u00f3n\u2019s main plaza in front of the St Stanislaus church.\u00a0<\/p>\n","protected":false},"author":36682,"featured_media":302784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26819,26823,2521,2522,2515,14631,14625,2514,2498],"tags":[3058,3575,7406,2535,14736,24715,3577,3577,13947,19616,3145,1662,14159],"newspack_spnsrs_tax":[],"class_list":{"0":"post-352338","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-altos-de-chavon-es","8":"category-arte-y-cultura","9":"category-republica-dominicana-2","10":"category-eventos-es","11":"category-fundacion-mir-es","12":"category-estilo-de-vida","13":"category-noticias-locales","14":"category-fundaciones-es","15":"category-uncategorized-es","16":"tag-actividades","17":"tag-altos-de-chavon-es-2","18":"tag-comunidad-casa-de-campo","19":"tag-estudiantes","20":"tag-featured-topview-es","21":"tag-fundacion-mir-es","22":"tag-fundacion-mir-es-2","24":"tag-jesus","25":"tag-juego","26":"tag-mir","27":"tag-navidad","28":"tag-presentacion","29":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-26T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-19T14:24:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marlenys Guzm\u00e1n Casta\u00f1os\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marlenys Guzm\u00e1n Casta\u00f1os\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\"},\"author\":{\"name\":\"Marlenys Guzm\u00e1n Casta\u00f1os\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/b6606bd87f9cec8f5903e2141cafda24\"},\"headline\":\"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR\",\"datePublished\":\"2017-12-26T04:00:00+00:00\",\"dateModified\":\"2022-12-19T14:24:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?fit=1000%2C667&ssl=1\",\"keywords\":[\"actividades\",\"Altos de Chavon -es\",\"comunidad casa de campo\",\"estudiantes\",\"Featured-TopView @es\",\"Fundacion MIR\",\"Fundacion MIR @es\",\"Fundacion MIR @es\",\"Jesus\",\"juego\",\"MIR\",\"navidad\",\"Presentaci\u00f3n\"],\"articleSection\":[\"Altos de Chavon @es\",\"Arte y cultura\",\"Rep\u00fablica Dominicana @es\",\"Eventos\",\"Fundaci\u00f3n MIR @es\",\"Estilo de Vida\",\"Noticias Locales\",\"Fundaciones\",\"Uncategorized @es\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\",\"name\":\"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?fit=1000%2C667&ssl=1\",\"datePublished\":\"2017-12-26T04:00:00+00:00\",\"dateModified\":\"2022-12-19T14:24:25+00:00\",\"description\":\"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/b6606bd87f9cec8f5903e2141cafda24\",\"name\":\"Marlenys Guzm\u00e1n Casta\u00f1os\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"caption\":\"Marlenys Guzm\u00e1n Casta\u00f1os\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/mguzman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living","description":"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","og_locale":"es_ES","og_type":"article","og_title":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living","og_description":"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the","og_url":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2017-12-26T04:00:00+00:00","article_modified_time":"2022-12-19T14:24:25+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg","type":"image\/jpeg"}],"author":"Marlenys Guzm\u00e1n Casta\u00f1os","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Marlenys Guzm\u00e1n Casta\u00f1os","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/"},"author":{"name":"Marlenys Guzm\u00e1n Casta\u00f1os","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/b6606bd87f9cec8f5903e2141cafda24"},"headline":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR","datePublished":"2017-12-26T04:00:00+00:00","dateModified":"2022-12-19T14:24:25+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/"},"wordCount":323,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1","keywords":["actividades","Altos de Chavon -es","comunidad casa de campo","estudiantes","Featured-TopView @es","Fundacion MIR","Fundacion MIR @es","Fundacion MIR @es","Jesus","juego","MIR","navidad","Presentaci\u00f3n"],"articleSection":["Altos de Chavon @es","Arte y cultura","Rep\u00fablica Dominicana @es","Eventos","Fundaci\u00f3n MIR @es","Estilo de Vida","Noticias Locales","Fundaciones","Uncategorized @es"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","url":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","name":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1","datePublished":"2017-12-26T04:00:00+00:00","dateModified":"2022-12-19T14:24:25+00:00","description":"On Friday, December 22nd a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical live nativity (the","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/b6606bd87f9cec8f5903e2141cafda24","name":"Marlenys Guzm\u00e1n Casta\u00f1os","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","caption":"Marlenys Guzm\u00e1n Casta\u00f1os"},"url":"https:\/\/casadecampoliving.com\/es\/author\/mguzman\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hermosa presentaci\u00f3n del nacimiento viviente de los alumnos de la Fundaci\u00f3n MIR","url":"http:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1"},"articleSection":"Altos de Chavon @es","author":[{"@type":"Person","name":"Marlenys Guzm\u00e1n Casta\u00f1os"}],"creator":["Marlenys Guzm\u00e1n Casta\u00f1os"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["actividades","altos de chavon -es","comunidad casa de campo","estudiantes","featured-topview @es","fundacion mir @es","fundacion mir","jesus","juego","mir","navidad","presentaci\u00f3n"],"dateCreated":"2017-12-26T04:00:00Z","datePublished":"2017-12-26T04:00:00Z","dateModified":"2022-12-19T14:24:25Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hermosa presentaci\\u00f3n del nacimiento viviente de los alumnos de la Fundaci\\u00f3n MIR\",\"url\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/hermosa-presentacion-del-nacimiento-viviente-de-los-alumnos-de-la-fundacion-mir\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?resize=150%2C150&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_3510.jpg?fit=1000%2C667&ssl=1\"},\"articleSection\":\"Altos de Chavon @es\",\"author\":[{\"@type\":\"Person\",\"name\":\"Marlenys Guzm\\u00e1n Casta\\u00f1os\"}],\"creator\":[\"Marlenys Guzm\\u00e1n Casta\\u00f1os\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Casa de Campo Living\",\"logo\":\"https:\\\/\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png\"},\"keywords\":[\"actividades\",\"altos de chavon -es\",\"comunidad casa de campo\",\"estudiantes\",\"featured-topview @es\",\"fundacion mir @es\",\"fundacion mir\",\"jesus\",\"juego\",\"mir\",\"navidad\",\"presentaci\\u00f3n\"],\"dateCreated\":\"2017-12-26T04:00:00Z\",\"datePublished\":\"2017-12-26T04:00:00Z\",\"dateModified\":\"2022-12-19T14:24:25Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3510.jpg?fit=1000%2C667&ssl=1","jetpack-related-posts":[{"id":348927,"url":"https:\/\/casadecampoliving.com\/es\/mir-trae-belen-a-altos-de-chavon-con-el-nacimiento-viviente\/","url_meta":{"origin":352338,"position":0},"title":"MIR trae Bel\u00e9n a Altos de Chav\u00f3n con el Nacimiento Viviente","author":"Perkin Agramonte","date":"31 Dic, 2015","format":false,"excerpt":"\u00a1Y los talentosos estudiantes de la Fundaci\u00f3n MIR vuelven a brillar en Altos de Chav\u00f3n! El viernes, 12 de diciembre trasladamos la ciudad de Bel\u00e9n a Altos de Chav\u00f3n y viajamos 2,000 a\u00f1os al pasado con el maravilloso Nacimiento Viviente. Muchas familias reunidas en frente de la iglesia St. Stanislaus\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"Fundaci\u00f3n MIR Live Nativity","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0663-e1451527464850-1.jpg?fit=650%2C426&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0663-e1451527464850-1.jpg?fit=650%2C426&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0663-e1451527464850-1.jpg?fit=650%2C426&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":338003,"url":"https:\/\/casadecampoliving.com\/es\/la-fundacion-mir-celebra-una-magica-representacion-del-nacimiento-viviente-en-la-plaza-de-altos-de-chavon\/","url_meta":{"origin":352338,"position":1},"title":"La Fundaci\u00f3n MIR celebra una m\u00e1gica representaci\u00f3n del Nacimiento Viviente en la plaza de Altos de Chav\u00f3n!","author":"","date":"4 Ene, 2012","format":false,"excerpt":"El pasado martes 27 de diciembre los residentes, visitantes y due\u00f1os de villa de Casa de Campo fueron testigos de una m\u00e1gica representaci\u00f3n del Nacimiento Viviente, interpretada por los ni\u00f1os y ni\u00f1as de las escuelas de la Fundaci\u00f3n MIR.\u00a0 Como parte de las celebraciones de Navidad, la plaza principal vibr\u00f3\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"nacimiento viviente fundacion MIR","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":340330,"url":"https:\/\/casadecampoliving.com\/es\/nacimiento-viviente-presentado-por-los-ninos-de-la-fundacion-mir-dic-27\/","url_meta":{"origin":352338,"position":2},"title":"Nacimiento Viviente presentado por los ni\u00f1os de la Fundaci\u00f3n MIR: Dic. 27","author":"lperdomo","date":"19 Dic, 2012","format":false,"excerpt":"Cada \u00e9poca festiva, los talentoso ni\u00f1os de fundaci\u00f3n MIR \u00a0preparan una interpretaci\u00f3n musical de una historia de navidad, la cual realizan en Altos de Chav\u00f3n \u2013 una magica ocasi\u00f3n que recuerda a todos nosotros el verdadero significado de la navidad. Todo el mundo esta invitado a disfrutar de esta hermosa\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"fundacion MIR","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_mir1-3.jpg?fit=650%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_mir1-3.jpg?fit=650%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_mir1-3.jpg?fit=650%2C405&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":353060,"url":"https:\/\/casadecampoliving.com\/es\/la-magia-de-la-navidad-nacimiento-viviente-de-los-ninos-de-la-fundacion-mir-este-viernes\/","url_meta":{"origin":352338,"position":3},"title":"\u00a1La magia de la navidad! Nacimiento viviente de los ni\u00f1os de la Fundaci\u00f3n MIR este viernes","author":"Casa de Campo Living","date":"19 Dic, 2018","format":false,"excerpt":"El pr\u00f3ximo 21 de diciembre tendremos la oportunidad de presenciar la escena del nacimiento en vivo y el desempe\u00f1o talentoso de los ni\u00f1os de la Fundaci\u00f3n MIR. Todos est\u00e1n invitados a disfrutar de esta hermosa presentaci\u00f3n de la historia de la Navidad, animada con villancicos tradicionales. El espect\u00e1culo se llevar\u00e1\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_3567.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_3567.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_3567.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_3567.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":320900,"url":"https:\/\/casadecampoliving.com\/the-fundacion-mir-brings-the-real-meaning-of-christmas-alive-in-altos-de-chavon-with-the-nacimiento-viviente-mir\/","url_meta":{"origin":352338,"position":4},"title":"The Fundaci\u00f3n MIR brings the real meaning of Christmas alive in Altos de Chav\u00f3n with the \u00abNacimiento Viviente MIR\u00bb","author":"","date":"4 Ene, 2012","format":false,"excerpt":"On Tuesday the 27th of December, a group of the Casa de Campo villa owners,\u00a0residents and visitors enjoyed an interpretation of the magical Christmas Story (the \u201cNacimiento Viviente\u201d) performed by the children of the Fundaci\u00f3n MIR on the Altos de Chav\u00f3n\u2019s main plaza in front of the St Stanislaus church.\u00a0\u2026","rel":"","context":"En \u00abAltos de Chavon\u00bb","block_context":{"text":"Altos de Chavon","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon\/"},"img":{"alt_text":"nacimiento viviente fundacion MIR","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/nacimiento_viviente_fundacion_MIR1-1.jpg?fit=650%2C436&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":320786,"url":"https:\/\/casadecampoliving.com\/the-nacimiento-viviente-2011-by-the-fundacion-mir-will-take-place-on-december-the-27th\/","url_meta":{"origin":352338,"position":5},"title":"The \u00abNacimiento Viviente 2011\u00bb by the Fundaci\u00f3n MIR will take place on December the 27th!","author":"","date":"20 Dic, 2011","format":false,"excerpt":"This Christmas season,\u00a0the Fundacion MIR, with the Politecnico MIR Esperanza School (for boys) and the Politecnico Fundacion MIR School (for girls) invite you to enjoy a magical Christmas presentation in Altos de Chav\u00f3n. The \u2018Nacimiento Viviente\u2019 or the traditional \u2018Nativity play,\u2019 will be held on Tuesday the 27th of December\u2026","rel":"","context":"En \u00abAltos de Chavon\u00bb","block_context":{"text":"Altos de Chavon","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon\/"},"img":{"alt_text":"fundacion MIR nacimiento viviente","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_MIR_nacimiento_viviente-1.jpg?fit=650%2C488&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_MIR_nacimiento_viviente-1.jpg?fit=650%2C488&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_MIR_nacimiento_viviente-1.jpg?fit=650%2C488&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36682"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=352338"}],"version-history":[{"count":3,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352338\/revisions"}],"predecessor-version":[{"id":511943,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352338\/revisions\/511943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/302784"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=352338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=352338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=352338"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=352338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}