{"id":352284,"date":"2017-12-11T00:00:00","date_gmt":"2017-12-11T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/"},"modified":"2022-11-10T10:39:57","modified_gmt":"2022-11-10T14:39:57","slug":"las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","title":{"rendered":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n"},"content":{"rendered":"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de diciembre para su recital navide\u00f1o. Las familias de las bailarinas y residentes, as\u00ed como los visitantes en la ciudad, entraron al gran anfiteatro el s\u00e1bado pasado para ver \u00abLa casa de las mu\u00f1ecas\u00bb.&nbsp;\n\n<!--more-->\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-151355\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0776.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"667\">\n\nEl cielo nocturno era un tel\u00f3n de fondo perfecto para disfrutar de los v\u00edvidos colores y las luces que emerg\u00edan del dormitorio femenino rosado y azul de Martina, el escenario de un cuento de hadas m\u00e1gico donde las mu\u00f1ecas cobran vida. Lindas mu\u00f1ecas de todos los tama\u00f1os, algunas con cabello color rosa, medias de rayas y sombreros de copa, estaban dispuestas en el centro del escenario. Poco despu\u00e9s, dos bailarinas vestidas de camareras desempolvaron a las mu\u00f1ecas y se sentaron expectantes ante la llegada de algo maravilloso. La bailarina solista, Daniela Hern\u00e1ndez, vestida como un hada con un tut\u00fa morado y verde con alas, agit\u00f3 su varita m\u00e1gica sobre las cada una de las mu\u00f1ecas y las llev\u00f3 al centro del escenario para distintos n\u00fameros de baile.\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-151360\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0969.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"667\">\n\nNos encant\u00f3 ver transpirar la creatividad del ballet; la actuaci\u00f3n dirigida por Ivonne Zeller dio vida a dos <em>Jack in the Box<\/em>, arlequines, damas con sombrillas, bailarinas de flamenco, una genio, un \u00e1ngel, una mu\u00f1eca de cuerda y m\u00e1s. La mu\u00f1eca de cuerda que era muy r\u00edgida al principio y con frecuencia perd\u00eda moviemiento, para gran consternaci\u00f3n de los ni\u00f1os en la audiencia, incluso escuche a una gritar \u00ab\u00a1Oh, no!\u00bb &#8211; eventualmente afloj\u00f3 sus r\u00edgidas extremidades y bail\u00f3 un d\u00fao con el hada. Fue entonces cuando los m\u00e1s peque\u00f1os de la academia de baile subieron al escenario, vestidos como mini elfos, y siguieron los pasos de su instructora.\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-151370\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3109.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"667\">\n\nEste evento anual tiene un significado muy especial ya que las ganancias de las ventas de entradas son donadas al \u00abHogar de Ancianos Padre Abreu\u00bb en La Romana. Durante los \u00faltimos 48 a\u00f1os desde que la apertura de la academia se le ha dado esta contribuci\u00f3n al hogar, y es una que verdaderamente aprecian y con la que cuentan cada a\u00f1o. As\u00ed que mientras planifica su calendario de Navidad y su asistencia a los eventos navide\u00f1os de Casa de Campo, recuerde c\u00f3mo puede marcar la diferencia en esta \u00e9poca del a\u00f1o y alegrar a los necesitados.\n\n\u00a1Felicitaciones a todas las bailarinas por un recital encantador! Vea m\u00e1s fotos en la galer\u00eda a continuaci\u00f3n, tomadas por Mariana Heredia el s\u00e1bado, 9 de diciembre:\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410262\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410262\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0768.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410294\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410294\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0781.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410313\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410313\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0787-2.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410334\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410334\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0801-1.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410358\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410358\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0821.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410378\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410378\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0861.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410406\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410406\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0883.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410426\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410426\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0891.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410451\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410451\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0902.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410476\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410476\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0908-1.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" data-id=\"410499\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?resize=600%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-410499\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0948.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" data-id=\"410529\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?resize=600%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-410529\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0957.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" data-id=\"410553\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?resize=600%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-410553\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0962.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410577\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410577\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0994.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410605\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410605\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1079.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410627\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410627\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1088.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410656\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410656\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1100.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" data-id=\"410681\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?resize=600%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-410681\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?resize=400%2C600&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?resize=150%2C225&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1164.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410706\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410706\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3081.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410729\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410729\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3084.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410757\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410757\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3088.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410781\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410781\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3090.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410804\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410804\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3092.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410831\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410831\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3096.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410847\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410847\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3097-1.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410875\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410875\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3103.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410904\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410904\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3104.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" data-id=\"410931\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"\" class=\"wp-image-410931\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=400%2C267&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=706%2C471&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_3112.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n&nbsp;","protected":false},"excerpt":{"rendered":"<p>Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de diciembre para su recital navide\u00f1o. Las familias de las bailarinas y residentes, as\u00ed como los visitantes en la ciudad, entraron al gran anfiteatro el s\u00e1bado pasado para ver [&hellip;]<\/p>\n","protected":false},"author":36681,"featured_media":300242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26819,26823,51,12567],"tags":[15387,3575,8111,1617,14736,1662],"newspack_spnsrs_tax":[],"class_list":["post-352284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altos-de-chavon-es","category-arte-y-cultura","category-events-and-activities","category-philanthrophy","tag-altos-de-chavon-es","tag-altos-de-chavon-es-2","tag-ballet-es","tag-academia-de-baile-elizabeth-zeller","tag-featured-topview-es","tag-navidad","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-11T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:39:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heather Lincoln\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heather Lincoln\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/\"},\"author\":{\"name\":\"Heather Lincoln\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/e3abfc63c1478fd703266a6f33a3145d\"},\"headline\":\"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n\",\"datePublished\":\"2017-12-11T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:39:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_1031.jpg?fit=1000%2C601&ssl=1\",\"keywords\":[\"Altos de Chavon\",\"Altos de Chavon -es\",\"ballet @es\",\"Elizabeth Zeller Ballet Academy\",\"Featured-TopView @es\",\"navidad\"],\"articleSection\":[\"Altos de Chavon @es\",\"Arte y cultura\",\"Events and Activities\",\"Philanthrophy\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/\",\"name\":\"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_1031.jpg?fit=1000%2C601&ssl=1\",\"datePublished\":\"2017-12-11T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:39:57+00:00\",\"description\":\"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_1031.jpg?fit=1000%2C601&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSC_1031.jpg?fit=1000%2C601&ssl=1\",\"width\":1000,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/e3abfc63c1478fd703266a6f33a3145d\",\"name\":\"Heather Lincoln\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g\",\"caption\":\"Heather Lincoln\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/hcastillo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living","description":"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","og_locale":"es_ES","og_type":"article","og_title":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living","og_description":"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de","og_url":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2017-12-11T04:00:00+00:00","article_modified_time":"2022-11-10T14:39:57+00:00","og_image":[{"width":1000,"height":601,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","type":"image\/jpeg"}],"author":"Heather Lincoln","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Heather Lincoln","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/"},"author":{"name":"Heather Lincoln","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/e3abfc63c1478fd703266a6f33a3145d"},"headline":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n","datePublished":"2017-12-11T04:00:00+00:00","dateModified":"2022-11-10T14:39:57+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/"},"wordCount":477,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","keywords":["Altos de Chavon","Altos de Chavon -es","ballet @es","Elizabeth Zeller Ballet Academy","Featured-TopView @es","navidad"],"articleSection":["Altos de Chavon @es","Arte y cultura","Events and Activities","Philanthrophy"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","url":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","name":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","datePublished":"2017-12-11T04:00:00+00:00","dateModified":"2022-11-10T14:39:57+00:00","description":"Como es tradici\u00f3n anual, las bailarinas de la Academia de Ballet Elizabeth P. de Zeller de La Romana subieron al escenario el segundo fin de semana de","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","width":1000,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/e3abfc63c1478fd703266a6f33a3145d","name":"Heather Lincoln","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8fc1ce4ad50385675908137b0d8d66be281d034bf072b4700460237638ea6d0?s=96&d=mm&r=g","caption":"Heather Lincoln"},"url":"https:\/\/casadecampoliving.com\/es\/author\/hcastillo\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n","url":"http:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1"},"articleSection":"Altos de Chavon @es","author":[{"@type":"Person","name":"Heather Lincoln"}],"creator":["Heather Lincoln"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["altos de chavon","altos de chavon -es","ballet @es","elizabeth zeller ballet academy","featured-topview @es","navidad"],"dateCreated":"2017-12-11T04:00:00Z","datePublished":"2017-12-11T04:00:00Z","dateModified":"2022-11-10T14:39:57Z"},"rendered":"<meta name=\"parsely-title\" content=\"Las mu\u00f1ecas cobran vida en la presentaci\u00f3n navide\u00f1a de Elizabeth P. de Zeller en Altos de Chav\u00f3n\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/las-munecas-cobran-vida-en-la-presentacion-navidena-de-elizabeth-p-de-zeller-en-altos-de-chavon\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-12-11T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Altos de Chavon @es\" \/>\n<meta name=\"parsely-tags\" content=\"altos de chavon,altos de chavon -es,ballet @es,elizabeth zeller ballet academy,featured-topview @es,navidad\" \/>\n<meta name=\"parsely-author\" content=\"Heather Lincoln\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":352266,"url":"https:\/\/casadecampoliving.com\/es\/academia-de-ballet-elizabeth-p-de-zeller-la-casa-de-las-munecas\/","url_meta":{"origin":352284,"position":0},"title":"Bailarinas de la Academia de Ballet Elizabeth P. de Zeller interpretar\u00e1n \u00abLa casa de las mu\u00f1ecas\u00bb este s\u00e1bado en Chav\u00f3n","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"7 Dic, 2017","format":false,"excerpt":"Este s\u00e1bado, 9 de diciembre, como parte del programa navide\u00f1o de este a\u00f1o, la Academia de Ballet Elizabeth de Zeller presentar\u00e1 su tradicional espect\u00e1culo anual de ballet en el anfiteatro de Altos de Chav\u00f3n. En el show de este a\u00f1o, interpretar\u00e1n \u201cLa casa de las mu\u00f1ecas\u201d, una historia de magia\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0778.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0778.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0778.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0778.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":352284,"position":1},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":353032,"url":"https:\/\/casadecampoliving.com\/es\/the-greatest-show-de-la-escuela-de-ballet-elizabeth-p-de-zeller-en-altos-de-chavon\/","url_meta":{"origin":352284,"position":2},"title":"\u00abThe greatest show\u00bb de la Escuela de Ballet Elizabeth P. de Zeller en Altos de Chav\u00f3n","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"3 Dic, 2018","format":false,"excerpt":"Uno de los eventos m\u00e1s esperados cada a\u00f1o durante el programa de Navidad en Altos de Chav\u00f3n es la presentaci\u00f3n de ballet de la academia Elizabeth P. de Zeller y este a\u00f1o, Ivonne Zeller (Directora de la academia), presentar\u00e1\u00a0\u201cThe greatest show\u201d (El espect\u00e1culo m\u00e1s grande) inspirado por la muy popular\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_0994.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_0994.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_0994.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2018\/12\/DSC_0994.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":350884,"url":"https:\/\/casadecampoliving.com\/es\/la-beyadere-en-altos-de-chavon-por-la-academia-de-ballet-elizabeth-zeller\/","url_meta":{"origin":352284,"position":3},"title":"Una espectacular interpretaci\u00f3n de \u201cLa Bayad\u00e8re\u201d en Altos de Chav\u00f3n por la Academia de Ballet Elizabeth Zeller","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"6 Dic, 2016","format":false,"excerpt":"El pasado s\u00e1bado 9 de diciembre tuvo\u00a0lugar el primer evento del calendario de vacaciones de Altos de Chav\u00f3n donde Renata So\u00f1\u00e9 fue la encargada de presentar \"La Bayad\u00e8re\" de la Academia de Ballet Elizabeth Zeller. \u00a1Esto fue sin duda alguna una gran manera de comenzar las celebraciones de Navidad! Esta\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"\u201cLa Beyad\u00e8re\u201d by the Elizabeth Zeller Academy","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0871-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0871-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0871-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0871-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":340038,"url":"https:\/\/casadecampoliving.com\/es\/reserve-la-fecha-presentacion-simplemente-lo-mejor-del-ballet-sabado-1-de-diciembre\/","url_meta":{"origin":352284,"position":4},"title":"Reserve la fecha: Presentaci\u00f3n \u00abSimplemente lo Mejor del Ballet\u00bb &#8211; s\u00e1bado 1 de diciembre!","author":"","date":"5 Nov, 2012","format":false,"excerpt":"Reserve la fecha! La funci\u00f3n anual realizada por la Academia de Ballet Elizabeth de Zeller, se llevar\u00e1 a cabo el s\u00e1bado 1 de diciembre en el Anfiteatro Altos de Chav\u00f3n. La presentaci\u00f3n, este a\u00f1o denominada \u201cSimplemente lo Mejor del Ballet\u201d, contar\u00e1 con la participaci\u00f3n de j\u00f3venes y talentosas bailarinas de\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"ballet","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ballet-1.gif?fit=650%2C511&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ballet-1.gif?fit=650%2C511&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ballet-1.gif?fit=650%2C511&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":346142,"url":"https:\/\/casadecampoliving.com\/es\/ballet-don-quijote-por-la-escuela-de-ballet-elizabeth-p-de-zeller-en-altos-de-chavon\/","url_meta":{"origin":352284,"position":5},"title":"Ballet Don Quijote por la Escuela de Ballet Elizabeth P. de Zeller en Altos de Chav\u00f3n","author":"Daniela Medina","date":"3 Dic, 2014","format":false,"excerpt":"Ya est\u00e1 a la vuelta de la esquina, Ivonne Zeller (Directora de la academia de Ballet Elizabeth P. de Zeller), presentar\u00e1 \u201cDon Quijote\u201d!! Este fin de semana el anfiteatro de Altos de Chav\u00f3n trae a su deleite una presentaci\u00f3n de danza que muestra todo el esfuerzo y la pasi\u00f3n que\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/don_quijote_ivonne_zeller-e1417545148284.png?fit=648%2C531&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/don_quijote_ivonne_zeller-e1417545148284.png?fit=648%2C531&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/don_quijote_ivonne_zeller-e1417545148284.png?fit=648%2C531&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_1031.jpg?fit=1000%2C601&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36681"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=352284"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352284\/revisions"}],"predecessor-version":[{"id":508745,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352284\/revisions\/508745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/300242"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=352284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=352284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=352284"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=352284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}