{"id":352050,"date":"2017-10-04T00:00:00","date_gmt":"2017-10-04T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/"},"modified":"2022-10-21T19:08:22","modified_gmt":"2022-10-21T23:08:22","slug":"el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","title":{"rendered":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de su pr\u00f3ximo torneo. El Torneo PQ se llevar\u00e1 a cabo el s\u00e1bado 4 de Noviembre del 2017, en Casa de Campo, La Romana, con el objetivo de recaudar fondos para varias fundaciones necesitadas de nuestro pa\u00eds.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Este torneo se jugar\u00e1 como siempre, en el exclusivo campo de golf de La Romana Country Club y es considerado un torneo propio de este club (house tournament). En la versi\u00f3n pasada se lleg\u00f3 a recaudar la suma de RD$1 mill\u00f3n de pesos, que fue donado a cuatro fundaciones; Pedri\u00e1tica por un Ma\u00f1ana, C\u00e1ncer Infantil, Matrimonio Feliz, y Heartcare. Para esta nueva versi\u00f3n 2017, se espera recaudar m\u00e1s de RD$2 millones de pesos que puedan servir de ayuda nueva vez, a causas necesitadas y de importancia para nuestro pa\u00eds, llevando en alto y cumpliendo la misi\u00f3n principal de este evento.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL2_Detra\u0301s-Antonio-Ca\u0301ceres-Francisco-Caro-Miguel-Roig-y-Juan-Francisco-Mayol-Delante-Andre\u0301s-Marranzini-Omar-Eli\u0301as-Ferdinando-Lamarche-So\u0301crates-Cuello-y-Luis-Arturo.-e1507145811738-6.jpg?resize=1000%2C694&amp;ssl=1\" alt=\"\" class=\"wp-image-147944\" height=\"694\" width=\"1000\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El Torneo PQ (Palos Quitados) que se iniciara en el 1991, es la marca mas prestigiosa de torneos de golf en la Rep\u00fablica Dominicana. Fue fundado con el objetivo de ayudar a los m\u00e1s necesitados, por un grupo de empresarios que ten\u00edan como tradici\u00f3n jugar juntos al golf y que se identificaron y sensibilizaron por las muchas causas que necesitan ayuda urgente en la Rep\u00fablica Dominicana. En el 2016, se elige una nueva directiva formada por los hijos de los fundadores y algunos amigos mas. Entre ellos: Miguel Roig, Antonio C\u00e1ceres Ricart, Francisco Caro, Carlos Jos\u00e9 Mart\u00ed, Omar El\u00edas, Domingo Berm\u00fadez, Andr\u00e9s Marranzini, Ferdinando Lamarche, Juan Francisco Mayol, Rodolfo Dietsch, Julio Zeller, S\u00f3crates Cuello y Luis Arturo Carbuccia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los interesados en inscribirse, patrocinar y\/o saber mas sobre este torneo, pueden comunicarse al 809. 732.8912 o al email: <a href=\"mailto:torneopq@gmail.com\" target=\"_blank\" rel=\"noopener\">torneopq@gmail.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Art\u00edculo contribuido por&nbsp;Asociaci\u00f3n Palos Quitao<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de su pr\u00f3ximo torneo. El Torneo PQ se llevar\u00e1 a cabo el s\u00e1bado 4 de Noviembre del 2017, en Casa de Campo, La Romana, con el objetivo de recaudar fondos para varias fundaciones [&hellip;]<\/p>\n","protected":false},"author":36791,"featured_media":311628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[148,12568,51,14626,75],"tags":[21815,18209,7825,2727,176,3734,14568,20026,7830],"newspack_spnsrs_tax":[],"class_list":["post-352050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-romana-country-club","category-sports","category-events-and-activities","category-upcoming","category-dominican-republic","tag-asociacion-palos-quitao","tag-ayuda","tag-fondos","tag-fundacion","tag-golf","tag-la-romana-country-club-es","tag-lrcc-es","tag-recaudacion","tag-torneo","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-04T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:08:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre\u0301s-Marranzini-Miguel-Roig-Antonio-Ca\u0301ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Casa de Campo Living\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Casa de Campo Living\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/\"},\"author\":{\"name\":\"Casa de Campo Living\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\"},\"headline\":\"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC\",\"datePublished\":\"2017-10-04T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:08:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/\"},\"wordCount\":340,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1\",\"keywords\":[\"Asociaci\u00f3n Palos Quitao\",\"Ayuda\",\"fondos\",\"Fundacion\",\"Golf\",\"la romana country club @es\",\"LRCC @es\",\"recaudacion\",\"torneo\"],\"articleSection\":[\"La Romana Country Club\",\"Sports\",\"Events and Activities\",\"Upcoming\",\"Dominican Republic\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/\",\"name\":\"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1\",\"datePublished\":\"2017-10-04T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:08:22+00:00\",\"description\":\"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1\",\"width\":1000,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/5d2171637a9d11e0e43ce6b8555f9422\",\"name\":\"Casa de Campo Living\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g\",\"caption\":\"Casa de Campo Living\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/casa-de-campo-living\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living","description":"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","og_locale":"es_ES","og_type":"article","og_title":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living","og_description":"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de","og_url":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2017-10-04T04:00:00+00:00","article_modified_time":"2022-10-21T23:08:22+00:00","og_image":[{"width":1000,"height":612,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre\u0301s-Marranzini-Miguel-Roig-Antonio-Ca\u0301ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","type":"image\/jpeg"}],"author":"Casa de Campo Living","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Casa de Campo Living","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/"},"author":{"name":"Casa de Campo Living","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422"},"headline":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC","datePublished":"2017-10-04T04:00:00+00:00","dateModified":"2022-10-21T23:08:22+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/"},"wordCount":340,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","keywords":["Asociaci\u00f3n Palos Quitao","Ayuda","fondos","Fundacion","Golf","la romana country club @es","LRCC @es","recaudacion","torneo"],"articleSection":["La Romana Country Club","Sports","Events and Activities","Upcoming","Dominican Republic"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","url":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","name":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","datePublished":"2017-10-04T04:00:00+00:00","dateModified":"2022-10-21T23:08:22+00:00","description":"La Directiva de la Asociaci\u00f3n Palos Quitao, anunci\u00f3 recientemente durante un encuentro con sus miembros, en el restaurante La Cassina, la celebraci\u00f3n de","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","width":1000,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/5d2171637a9d11e0e43ce6b8555f9422","name":"Casa de Campo Living","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04101fa4a9fd431e939953b1500fdc7a73cd35029f86d98712fd8ccdaebaf9a?s=96&d=mm&r=g","caption":"Casa de Campo Living"},"url":"https:\/\/casadecampoliving.com\/es\/author\/casa-de-campo-living\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC","url":"http:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1"},"articleSection":"La Romana Country Club","author":[{"@type":"Person","name":"Casa de Campo Living"}],"creator":["Casa de Campo Living"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["asociaci\u00f3n palos quitao","ayuda","fondos","fundacion","golf","la romana country club @es","lrcc @es","recaudacion","torneo"],"dateCreated":"2017-10-04T04:00:00Z","datePublished":"2017-10-04T04:00:00Z","dateModified":"2022-10-21T23:08:22Z"},"rendered":"<meta name=\"parsely-title\" content=\"El Torneo de Golf Palos Quitados tendr\u00e1 lugar el pr\u00f3ximo mes en LRCC\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/el-torneo-de-golf-palos-quitao-tendra-lugar-el-proximo-mes-en-lrcc\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-10-04T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"La Romana Country Club\" \/>\n<meta name=\"parsely-tags\" content=\"asociaci\u00f3n palos quitao,ayuda,fondos,fundacion,golf,la romana country club @es,lrcc @es,recaudacion,torneo\" \/>\n<meta name=\"parsely-author\" content=\"Casa de Campo Living\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":502261,"url":"https:\/\/casadecampoliving.com\/es\/asociacion-pq-anuncia-18avo-torneo-de-golf-a-celebrarse-en-la-romana-country-club\/","url_meta":{"origin":352050,"position":0},"title":"Asociaci\u00f3n PQ anuncia 18avo. torneo de golf a celebrarse en La Romana Country Club","author":"Casa de Campo Living","date":"18 Oct, 2022","format":false,"excerpt":"La directiva de la Asociaci\u00f3n Palos Quitao anunci\u00f3 que la edici\u00f3n n\u00famero 18 de su torneo de golf se celebrar\u00e1 el 12 de noviembre, en La Romana Country Club, Casa de Campo. \u201cComo cada an\u0303o, nos complace reencontrarnos nuevamente en el campo de golf para celebrar juntos una edicio\u0301n ma\u0301s.\u2026","rel":"","context":"En \u00abCountry Club La Romana\u00bb","block_context":{"text":"Country Club La Romana","link":"https:\/\/casadecampoliving.com\/es\/category\/country-club-la-romana-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354648,"url":"https:\/\/casadecampoliving.com\/asociacion-pq-anuncia-18avo-torneo-de-golf-a-celebrarse-en-la-romana-country-club\/","url_meta":{"origin":352050,"position":1},"title":"Asociaci\u00f3n PQ announces 18th Golf Tournament to be held at La Romana Country Club","author":"Casa de Campo Living","date":"18 Oct, 2022","format":false,"excerpt":"The directors of the Palos Quitao Association announced that the 18th edition of their golf tournament will be held on November 12, at La Romana Country Club, Casa de Campo. \u201cLike every year, we are pleased to meet again on the golf course to celebrate another edition together. We assure\u2026","rel":"","context":"En \u00abCasa de Campo Living\u00bb","block_context":{"text":"Casa de Campo Living","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310980598_764681964604259_8319568616021850149_n-e1666102529366.jpg?fit=1000%2C663&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":352960,"url":"https:\/\/casadecampoliving.com\/es\/celebran-con-rotundo-exito-14vo-torneo-de-golf-pq\/","url_meta":{"origin":352050,"position":2},"title":"Golfistas celebran con rotundo \u00e9xito 14vo. Torneo de Golf PQ","author":"Casa de Campo Living","date":"2 Nov, 2018","format":false,"excerpt":"La reconocida Asociaci\u00f3n PQ celebr\u00f3 con rotundo \u00e9xito el 14\u00ba Torneo de Golf PQ (Palos Quitao) el cual se llev\u00f3 a cabo en La Romana Country Club a beneficio de las Fundaciones: FACCI, Instituto Ayuda al Sordo Santa Rosa, Matrimonio Feliz y Heart Care Dominicana. Franco Schiffino y Miguel Ramos\u2026","rel":"","context":"En \u00abDominican Republic\u00bb","block_context":{"text":"Dominican Republic","link":"https:\/\/casadecampoliving.com\/category\/dominican-republic\/"},"img":{"alt_text":"DSC_0963 a","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0963-a.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0963-a.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0963-a.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0963-a.jpg?resize=700%2C400 2x"},"classes":[]},{"id":354103,"url":"https:\/\/casadecampoliving.com\/es\/roberto-herrera-y-roberto-andres-herrera-sosa-ganan-la-primera-edicion-del-torneo-de-golf-pq-padres-e-hijos\/","url_meta":{"origin":352050,"position":3},"title":"Roberto Herrera y Roberto Andr\u00e9s Herrera Sosa ganan la primera edici\u00f3n del \u00abTorneo de golf PQ Padres e Hijos\u00bb","author":"Casa de Campo Living","date":"17 Jul, 2021","format":false,"excerpt":"La Asociaci\u00f3n PQ celebr\u00f3 con rotundo \u00e9xito la primera versi\u00f3n del \u201cTorneo PQ Padres e Hijos\u201d, un compartir sin igual entre amigos, padres e hijos, en donde se adoptaron todas las medidas sanitarias recomendadas por las autoridades. Con escenario en La Romana Country Club, Casa de Campo, resultaron como ganadores\u2026","rel":"","context":"En \u00abM\u00e1s all\u00e1 de Casa\u00bb","block_context":{"text":"M\u00e1s all\u00e1 de Casa","link":"https:\/\/casadecampoliving.com\/es\/category\/mas-alla-de-casa-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/1-1.jpeg?fit=1000%2C764&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/1-1.jpeg?fit=1000%2C764&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/1-1.jpeg?fit=1000%2C764&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/1-1.jpeg?fit=1000%2C764&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354219,"url":"https:\/\/casadecampoliving.com\/es\/torneo-de-golf-pq-celebra-30-anos-con-exitosa-version-2021\/","url_meta":{"origin":352050,"position":4},"title":"Fundaci\u00f3n PQ celebra 30 a\u00f1os con exitosa versi\u00f3n 2021Torneo de Golf PQ","author":"Casa de Campo Living","date":"8 Dic, 2021","format":false,"excerpt":"Bajo el lema \u201cJugando por ellos\u201d, la Fundaci\u00f3n PQ celebr\u00f3 30 a\u00f1os de su exitoso Torneo de Golf PQ con una entrega que cont\u00f3 con la participaci\u00f3n de 128 jugadores y un reconocimiento a Kalil Hach\u00e9 como parte de la ceremonia.\u00a0 Los ganadores del torneo con el mejor Score Bruto\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ganadores-Mejor-Score-Bruto-1.jpg?fit=1000%2C652&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ganadores-Mejor-Score-Bruto-1.jpg?fit=1000%2C652&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ganadores-Mejor-Score-Bruto-1.jpg?fit=1000%2C652&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Ganadores-Mejor-Score-Bruto-1.jpg?fit=1000%2C652&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":524343,"url":"https:\/\/casadecampoliving.com\/es\/la-asociacion-pq-celebra-exitoso-19avo-torneo-de-golf\/","url_meta":{"origin":352050,"position":5},"title":"La Asociaci\u00f3n PQ celebra exitoso 19avo. Torneo de Golf","author":"Casa de Campo Living","date":"15 Nov, 2023","format":false,"excerpt":"En el majestuoso escenario de La Romana Country Club, Casa de Campo, la Asociaci\u00f3n Palos Quitao (PQ) celebr\u00f3 con \u00e9xito su tradicional 19vo. Torneo de Golf Ben\u00e9fico, en el marco de un inolvidable fin de semana lleno de camarader\u00eda y sorpresas. Este a\u00f1o la justa deportiva estuvo dedicada al se\u00f1or\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/11\/PQ-Palos-Quitao-Association.jpg?fit=1200%2C1028&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/11\/PQ-Palos-Quitao-Association.jpg?fit=1200%2C1028&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/11\/PQ-Palos-Quitao-Association.jpg?fit=1200%2C1028&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/11\/PQ-Palos-Quitao-Association.jpg?fit=1200%2C1028&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2023\/11\/PQ-Palos-Quitao-Association.jpg?fit=1200%2C1028&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/PRINCIPAL_1_Andre%CC%81s-Marranzini-Miguel-Roig-Antonio-Ca%CC%81ceres-Juan-Francisco-Mayol.-1.jpg?fit=1000%2C612&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36791"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=352050"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352050\/revisions"}],"predecessor-version":[{"id":352051,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/352050\/revisions\/352051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/311628"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=352050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=352050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=352050"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=352050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}