{"id":351293,"date":"2017-03-27T00:00:00","date_gmt":"2017-03-27T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/"},"modified":"2022-11-10T10:06:43","modified_gmt":"2022-11-10T14:06:43","slug":"una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","title":{"rendered":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba"},"content":{"rendered":"<p style=\"text-align: justify;\">El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge Demyttenaere organiz\u00f3 una hermosa reuni\u00f3n en Toronjas # 7 en Casa de Campo, mezclando la cultura espa\u00f1ola con una gran causa.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">En cuanto entramos en la encantadora casa de Inge, fuimos envueltos por los ritmos de la m\u00fasica tradicional espa\u00f1ola y nos dio la bienvenida por la propia anfitriona. Una mesa con deliciosos aperitivos como tortillas de huevo espa\u00f1ola, nachos, queso, camarones picantes, y mucho m\u00e1s. Muchos de los maravillosos miembros de la comunidad de Casa de Campo disfrutaron de su merienda en la terraza acompa\u00f1ada de sangr\u00eda, vino o un refrescante c\u00f3ctel mientras aprend\u00edan m\u00e1s sobre la organizaci\u00f3n. Villa Caoba es una peque\u00f1a comunidad dentro de La Romana donde Fundaci\u00f3n Lirio del Valle ayuda a educar y alimentar a ni\u00f1os de 3 a 13 a\u00f1os, contribuyendo a su desarrollo f\u00edsico e intelectual.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-137552\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8958.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"IMG_8958\" width=\"1000\" height=\"667\" \/><\/p>\n<p style=\"text-align: justify;\">Encontramos a Anna Maria Pl\u00e0, la fundadora de la fundaci\u00f3n, cocinando la paella en la terraza donde los invitados pasaban a saludarla y ver c\u00f3mo se hace este tradicional plato espa\u00f1ol. Una vez que estuvo lista, invit\u00f3 a todos a tomar un plato y a comer. \u00a1La paella de marisco estaba deliciosa! Llena de camarones frescos, almejas, mejillones, pulpo, que estaba cocinado a la perfecci\u00f3n. El postre tambi\u00e9n se coloc\u00f3 en la mesa principal: tres-leche de Crema, flan, y una exquisito volteado de pi\u00f1a hecho por Dolly Esteban, una de los patrocinadores de la fundaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-137551\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_9042.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"IMG_9042\" width=\"1000\" height=\"667\" \/><\/p>\n<p style=\"text-align: justify;\">Dolly tambi\u00e9n trajo entretenimiento musical para el evento &#8211; Camilo Rijo Fulcar es un joven y talentoso m\u00fasico que se ha dedicado a inspirar a los ni\u00f1os pobres con su arte. Ense\u00f1a clases de guitarra todos los domingos en la calle El Conde de la Zona Colonial de Santo Domingo. Camilo fue diagnosticado con c\u00e1ncer el a\u00f1o pasado, pero esto no le ha impedido ayudar a otros y trabajar hacia sus sue\u00f1os. A pesar de que su tratamiento es muy caro, no ha disminuido su deseo de tener un impacto positivo en los dem\u00e1s. Con su campa\u00f1a \u00abRiete conmigo\u00bb el promueve hacer frente a las adversidades de manera positiva, evitando a toda costa la depresi\u00f3n y el pesimismo. Fue realmente inspirador verlo actuar y conocer m\u00e1s sobre su vida.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-137550 size-full\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955.jpg?resize=1000%2C667&#038;ssl=1\" alt=\"IMG_8955\" width=\"1000\" height=\"667\" \/><\/p>\n<p style=\"text-align: justify;\">Durante la tarde, los invitados tambi\u00e9n tuvieron la oportunidad de ver y comprar la nueva l\u00ednea de<i>\u00a0<\/i>ropa para resort\u00a0de Klaudia Becker, que incluye kaftans coloridos, largos y cortos. Adem\u00e1s, se realiz\u00f3 una rifa de exquisitas barras de chocolate y productos de belleza de Halka, una compa\u00f1\u00eda dominicana que ha sido un fiel seguidor de la causa y que patrocina a varios ni\u00f1os. El aire se llen\u00f3 r\u00e1pidamente con las risas y la emoci\u00f3n de las se\u00f1oras de Casa de Campo, ya que ganaron varias de las bolsas llenas de productos, \u00a1y los quienes no ganamos premios no nos fuimos con las manos vac\u00edas! Nos regalaron bolsas de cosm\u00e9ticos hechos a mano y esmaltes de u\u00f1as.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-137549 size-full\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8947.jpg?resize=1000%2C610&#038;ssl=1\" alt=\"IMG_8947\" width=\"1000\" height=\"610\" \/><\/p>\n<p style=\"text-align: justify;\">Todos los fondos para la organizaci\u00f3n se recaudan a trav\u00e9s de contribuciones de patrocinadores, donaciones voluntarias, subastas de caridad, conciertos y m\u00e1s, y se usan enteramente para actividades escolares y educativas. Si quieres donar, conocer m\u00e1s de la fundaci\u00f3n o incluso conocer a los ni\u00f1os de Villa Caoba, puede ponerse en contacto con Anna Maria, Dolly o Evangelina para ir con ellas los s\u00e1bados donde pasan tiempo con los ni\u00f1os, preparan el almuerzo con los voluntarios y realizan divertidad actividades para todos.<\/p>\n<p style=\"text-align: justify;\">La siguiente galer\u00eda de fotos fue tomada por Laura Perdomo durante el evento para los ni\u00f1os de Villa Caoba, organizado por Inge Demyttenaere, el pasado viernes 24 de marzo:<\/p>\n<p style=\"text-align: justify;\">[nggallery id = 2847]<\/p>\n<blockquote>\n<h3><b>CONOZCA M\u00c1S DE LA FUNDACI\u00d3N LIRIO DEL VALLE<\/b><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-118104\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacio%CC%81n-Lirio-del-Valle-6.png?resize=200%2C200&#038;ssl=1\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" srcset=\"http:\/\/4536t5285udz1dgg85o8bdfj.wpengine.netdna-cdn.com\/wp-content\/uploads\/2016\/03\/Fundacio\u0301n-Lirio-del-Valle.png 300w, http:\/\/4536t5285udz1dgg85o8bdfj.wpengine.netdna-cdn.com\/wp-content\/uploads\/2016\/03\/Fundacio\u0301n-Lirio-del-Valle-150x150.png 150w, http:\/\/4536t5285udz1dgg85o8bdfj.wpengine.netdna-cdn.com\/wp-content\/uploads\/2016\/03\/Fundacio\u0301n-Lirio-del-Valle-80x80.png 80w\" alt=\"Fundacio\u0301n Lirio del Valle Logo\" width=\"200\" height=\"200\" \/>La Fundaci\u00f3n Lirios del Valle tiene como objetivo educar a los ni\u00f1os de Villa Caoba, proporcionarles ropa, alimentos, \u00fatiles escolares y juguetes. La fundaci\u00f3n cuenta actualmente con 120 ni\u00f1as y ni\u00f1os matriculados en su programa. Algunos de estos ni\u00f1os han sido patrocinados por los amables donantes, que pagan entre USD $ 29 y USD $ 43 al mes para proporcionar comidas, asistencia despu\u00e9s de la escuela y actividades recreativas, as\u00ed como materiales escolares, instrucci\u00f3n y uniformes.<\/p>\n<p><b>Contactos:<\/b><\/p>\n<p>Anna Maria Pl\u00e0 Pujal, Fundadora (809) 742-7247<\/p>\n<p>Dolly Esteban: (809) 330-7644<\/p>\n<p>Evangelina Uckert: (809) 523-8015<\/p>\n<p><b>Email:<\/b> <a href=\"mailto:presidenta@villacaoba.com\" target=\"_blank\" rel=\"noopener\">presidenta@villacaoba.com<\/a><\/p>\n<p><b>Webpage:<\/b> <a href=\"http:\/\/www.villacaoba.com\/eng\/index.htm\" target=\"_blank\" rel=\"noopener\">www.villacaoba.com<\/a><\/p>\n<p><b>Facebook: <\/b><a href=\"https:\/\/www.facebook.com\/Amics-de-VillaCaoba-Amigos-de-VillaCaoba-190276144325258\/\" target=\"_blank\" rel=\"noopener\">Amigos de villa Caoba<\/a><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge Demyttenaere organiz\u00f3 una hermosa reuni\u00f3n en Toronjas # 7 en Casa de Campo, mezclando la cultura espa\u00f1ola con una gran causa.<\/p>\n","protected":false},"author":36682,"featured_media":284654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2521,2522,14631,14625,2514],"tags":[10192,14736,11927,15840,18932,14542,15233,8676,11928],"newspack_spnsrs_tax":[],"class_list":["post-351293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-republica-dominicana-2","category-eventos-es","category-estilo-de-vida","category-noticias-locales","category-fundaciones-es","tag-donaciones","tag-featured-topview-es","tag-fundacion-lirio-del-valle-es","tag-halka-ers","tag-la-romana-es-4","tag-la-romana-es","tag-merienda","tag-ninos","tag-villa-caoba-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-27T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marlenys Guzm\u00e1n Casta\u00f1os\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marlenys Guzm\u00e1n Casta\u00f1os\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\"},\"author\":{\"name\":\"Marlenys Guzm\u00e1n Casta\u00f1os\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/b6606bd87f9cec8f5903e2141cafda24\"},\"headline\":\"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba\",\"datePublished\":\"2017-03-27T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\"},\"wordCount\":798,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?fit=1000%2C667&ssl=1\",\"keywords\":[\"donaciones\",\"Featured-TopView @es\",\"Fundaci\u00f3n Lirio del Valle @es\",\"Halka @ers\",\"La Romana\",\"La Romana @es\",\"Merienda\",\"ni\u00f1os\",\"Villa Caoba @es\"],\"articleSection\":[\"Rep\u00fablica Dominicana @es\",\"Eventos\",\"Estilo de Vida\",\"Noticias Locales\",\"Fundaciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\",\"name\":\"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?fit=1000%2C667&ssl=1\",\"datePublished\":\"2017-03-27T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:06:43+00:00\",\"description\":\"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/b6606bd87f9cec8f5903e2141cafda24\",\"name\":\"Marlenys Guzm\u00e1n Casta\u00f1os\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g\",\"caption\":\"Marlenys Guzm\u00e1n Casta\u00f1os\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/mguzman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living","description":"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","og_locale":"es_ES","og_type":"article","og_title":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living","og_description":"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge","og_url":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2017-03-27T04:00:00+00:00","article_modified_time":"2022-11-10T14:06:43+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","type":"image\/jpeg"}],"author":"Marlenys Guzm\u00e1n Casta\u00f1os","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Marlenys Guzm\u00e1n Casta\u00f1os","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/"},"author":{"name":"Marlenys Guzm\u00e1n Casta\u00f1os","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/b6606bd87f9cec8f5903e2141cafda24"},"headline":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba","datePublished":"2017-03-27T04:00:00+00:00","dateModified":"2022-11-10T14:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/"},"wordCount":798,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","keywords":["donaciones","Featured-TopView @es","Fundaci\u00f3n Lirio del Valle @es","Halka @ers","La Romana","La Romana @es","Merienda","ni\u00f1os","Villa Caoba @es"],"articleSection":["Rep\u00fablica Dominicana @es","Eventos","Estilo de Vida","Noticias Locales","Fundaciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","url":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","name":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","datePublished":"2017-03-27T04:00:00+00:00","dateModified":"2022-11-10T14:06:43+00:00","description":"El viernes 25 de marzo, los amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/b6606bd87f9cec8f5903e2141cafda24","name":"Marlenys Guzm\u00e1n Casta\u00f1os","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72f3f86b8e6b3ec744201aeadf11d4a6055e8af194aecd9ad30ffff4437878ee?s=96&d=mm&r=g","caption":"Marlenys Guzm\u00e1n Casta\u00f1os"},"url":"https:\/\/casadecampoliving.com\/es\/author\/mguzman\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una tarde de paella, meriendas y sangrias a beneficio de los ni\u00f1os de Villa Caoba","url":"http:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1"},"articleSection":"Rep\u00fablica Dominicana @es","author":[{"@type":"Person","name":"Marlenys Guzm\u00e1n Casta\u00f1os"}],"creator":["Marlenys Guzm\u00e1n Casta\u00f1os"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["donaciones","featured-topview @es","fundaci\u00f3n lirio del valle @es","halka @ers","la romana","la romana @es","merienda","ni\u00f1os","villa caoba @es"],"dateCreated":"2017-03-27T04:00:00Z","datePublished":"2017-03-27T04:00:00Z","dateModified":"2022-11-10T14:06:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una tarde de paella, meriendas y sangrias a beneficio de los ni\\u00f1os de Villa Caoba\",\"url\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/una-tarde-de-paella-merienda-y-sangrias-en-nombre-de-los-ninos-de-villa-caoba\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?resize=150%2C150&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IMG_8939.jpg?fit=1000%2C667&ssl=1\"},\"articleSection\":\"Rep\\u00fablica Dominicana @es\",\"author\":[{\"@type\":\"Person\",\"name\":\"Marlenys Guzm\\u00e1n Casta\\u00f1os\"}],\"creator\":[\"Marlenys Guzm\\u00e1n Casta\\u00f1os\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Casa de Campo Living\",\"logo\":\"https:\\\/\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png\"},\"keywords\":[\"donaciones\",\"featured-topview @es\",\"fundaci\\u00f3n lirio del valle @es\",\"halka @ers\",\"la romana\",\"la romana @es\",\"merienda\",\"ni\\u00f1os\",\"villa caoba @es\"],\"dateCreated\":\"2017-03-27T04:00:00Z\",\"datePublished\":\"2017-03-27T04:00:00Z\",\"dateModified\":\"2022-11-10T14:06:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8939.jpg?fit=1000%2C667&ssl=1","jetpack-related-posts":[{"id":353307,"url":"https:\/\/casadecampoliving.com\/es\/paella-aperitivos-sangrias-y-flamenco-en-nombre-de-los-ninos-de-villa-caoba\/","url_meta":{"origin":351293,"position":0},"title":"Paella, aperitivos, sangr\u00edas y flamenco en nombre de los ni\u00f1os de Villa Caoba","author":"Casa de Campo Living","date":"20 Mar, 2019","format":false,"excerpt":"El viernes 15 de marzo, amigos de la Fundaci\u00f3n Lirio del Valle se reunieron para una tarde maravillosa en nombre de los ni\u00f1os de Villa Caoba. Inge Demyttenaere organiz\u00f3 una hermosa reuni\u00f3n en Toronjas # 7 en Casa de Campo, mezclando la cultura espa\u00f1ola con una gran causa. Tan pronto\u2026","rel":"","context":"En \u00abDominican Republic\u00bb","block_context":{"text":"Dominican Republic","link":"https:\/\/casadecampoliving.com\/category\/dominican-republic\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_9316.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_9316.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_9316.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_9316.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349509,"url":"https:\/\/casadecampoliving.com\/es\/tarde-a-favor-de-ninos-de-villa-caoba\/","url_meta":{"origin":351293,"position":1},"title":"Hermosa tarde a favor de los ni\u00f1os de Villa Caoba","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"29 Mar, 2016","format":false,"excerpt":"La tarde del viernes 18 de marzo fue perfecta para reunirse con amigos en nombre de los ni\u00f1os de Villa Caoba. Fundaci\u00f3n Lirio del Valle organiz\u00f3 una hermosa reuni\u00f3n en Toronjas # 7 Casa de Campo, hogar de nuestra querida amiga, Inge Demyttenaere. A lo largo de la tarde soleada,\u2026","rel":"","context":"En \u00abRep\u00fablica Dominicana @es\u00bb","block_context":{"text":"Rep\u00fablica Dominicana @es","link":"https:\/\/casadecampoliving.com\/es\/category\/republica-dominicana-2\/"},"img":{"alt_text":"New_Afternoon_VillaCaoba_07","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/New_Afternoon_VillaCaoba_07.jpg?fit=800%2C533&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/New_Afternoon_VillaCaoba_07.jpg?fit=800%2C533&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/New_Afternoon_VillaCaoba_07.jpg?fit=800%2C533&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/New_Afternoon_VillaCaoba_07.jpg?fit=800%2C533&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":353285,"url":"https:\/\/casadecampoliving.com\/es\/fundacion-lirio-del-valle-te-invita-una-tarde-de-paella-sangria-y-flamenco-beneficio-de-los-ninos-de-villa-caoba\/","url_meta":{"origin":351293,"position":2},"title":"Fundaci\u00f3n Lirio del Valle te invita a una tarde de paella, sangr\u00eda y flamenco a beneficio de los ni\u00f1os de Villa Caoba.","author":"Casa de Campo Living","date":"11 Mar, 2019","format":false,"excerpt":"La Fundaci\u00f3n Lirio del Valle le invita este viernes 15 de marzo a compartir una picadera, paella, sangr\u00eda espa\u00f1ola y una presentaci\u00f3n de flamenco en nombre de los ni\u00f1os de Villa Caoba. Esta iniciativa de recaudaci\u00f3n de fondos, auspiciada por Inge Demyttenaere, se llevar\u00e1 a cabo en la villa Tornojas\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":351272,"url":"https:\/\/casadecampoliving.com\/es\/unete-fundacion-lirio-del-valle-y-inge-demyttenaere-este-viernes-para-apoyar-los-ninos-de-villa-caoba\/","url_meta":{"origin":351293,"position":3},"title":"\u00danete a Fundaci\u00f3n Lirio del Valle y Inge Demyttenaere este viernes para apoyar a los ni\u00f1os de Villa Caoba","author":"Heather Lincoln","date":"20 Mar, 2017","format":false,"excerpt":"La Fundaci\u00f3n Lirio del Valle le invita este viernes 24 de marzo a compartir una picadera, paella y sangr\u00eda espa\u00f1ola en nombre de los ni\u00f1os de Villa Caoba. Esta iniciativa de recaudaci\u00f3n de fondos, auspiciada por Inge Demyttenaere, se llevar\u00e1 a cabo en la villa Tornojas #7 de 5 a\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"Fundaci\u00f3n Lirio del Valle","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion_Lirio_del_Valle04-e1490034887139.jpg?fit=1000%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion_Lirio_del_Valle04-e1490034887139.jpg?fit=1000%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion_Lirio_del_Valle04-e1490034887139.jpg?fit=1000%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion_Lirio_del_Valle04-e1490034887139.jpg?fit=1000%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349412,"url":"https:\/\/casadecampoliving.com\/es\/fundacion-lirio-del-valle-los-invita-un-evento-beneficio-de-los-ninos-de-villa-caoba\/","url_meta":{"origin":351293,"position":4},"title":"Fundaci\u00f3n Lirio del Valle los invita a un evento a beneficio de los ni\u00f1os de Villa Caoba","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"14 Mar, 2016","format":false,"excerpt":"Fundaci\u00f3n Lirio del Valle le invita a una peque\u00f1a merienda en nombre de los hijos de Villa Caoba este viernes 18 de marzo de 5-7 pm en Toronjas # 7 en Casa de Campo, villa de nuestra querida Inge Demyttenaere. La comunidad de Casa de Campo se caracteriza por la\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/casadecampoliving.com\/es\/category\/destacados\/"},"img":{"alt_text":"Fundaci\u00f3n Lirio del Valle","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":350919,"url":"https:\/\/casadecampoliving.com\/es\/un-mensaje-navideno-de-la-fundacion-lirio-del-valle\/","url_meta":{"origin":351293,"position":5},"title":"Un mensaje navide\u00f1o de la Fundaci\u00f3n Lirio del Valle","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"15 Dic, 2016","format":false,"excerpt":"La Fundaci\u00f3n Lirio del Valle es un proyecto de caridad que se inici\u00f3 hace siete a\u00f1os y que ha trabajado arduamente\u00a0para mejorar la vida de muchos ni\u00f1os pobres en La Romana. La fundaci\u00f3n fue fundada por Anna Maria Pla y Rosario Volquez, quienes con un grupo de voluntarios dominicanos y\u2026","rel":"","context":"En \u00abFundaciones\u00bb","block_context":{"text":"Fundaciones","link":"https:\/\/casadecampoliving.com\/es\/category\/fundaciones-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/351293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/36682"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=351293"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/351293\/revisions"}],"predecessor-version":[{"id":351296,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/351293\/revisions\/351296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/284654"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=351293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=351293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=351293"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=351293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}