{"id":348965,"date":"2016-01-07T00:00:00","date_gmt":"2016-01-07T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/gala-esplendor-magicofundacion-mir-2016\/"},"modified":"2022-10-21T19:03:23","modified_gmt":"2022-10-21T23:03:23","slug":"gala-esplendor-magicofundacion-mir-2016","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","title":{"rendered":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015.jpg?resize=650%2C400&amp;ssl=1\" alt=\"Fundaci\u00f3n MIR Magical Splendor Gala 2015\" class=\"wp-image-116056\" height=\"400\" width=\"650\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de Modas&nbsp;anual, con&nbsp;Raysa y&nbsp;Alfy Fanjul como anfitriones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/wp.me\/p1kvEy-rQT\">El a\u00f1o pasado, como&nbsp;en ocasiones anteriores,&nbsp;la Gala Esplendor M\u00e1gico de la Fundaci\u00f3n MIR fue sin duda alguna un evento maravilloso&nbsp;lleno de m\u00fasica, baile y mucho m\u00e1s.<\/a> Y ya que cada a\u00f1o&nbsp;los organizadores del evento se superan a s\u00ed mismos brind\u00e1ndonos un evento m\u00e1s incre\u00edble,&nbsp;te recomendamos que no te pierdas el evento que toda la Comunidad de Casa de Campo ha estado esperando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o la Gala Esplendor M\u00e1gico se llevar\u00e1 a cabo como es tradici\u00f3n en&nbsp;Casa Grande, y es patrocinada por la tienda de lujo &nbsp;<em>Saks 5th Avenue San Juan<\/em> en conjunto con la dise\u00f1adora de joyas americana, <em>Coomi<\/em>. Este a\u00f1o, el desfile de modas de este a\u00f1o presentar\u00e1&nbsp;piezas del dise\u00f1ador de modas indio-americano Naeem Khan, adem\u00e1s del&nbsp;\u201cMystery Shopping Wall\u201d de Saks 5th Avenue, en donde&nbsp;tendr\u00e1n la oportunidad de adquirir art\u00edculos exclusivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de los eventos de la noche del s\u00e1bado, la Gala Esplendor M\u00e1gico de la Fundaci\u00f3n MIR tambi\u00e9n incluir\u00e1 un torneo de golf en formato <em>scramble<\/em>&nbsp;que se llevar\u00e1 a cabo&nbsp;en La Romana Country Club el mismo d\u00eda, como tambi\u00e9n la Boutique de Saks 5th Avenue con las joyas de Coomi, la cual estar\u00e1 abierta en La Romana Country Club desde el viernes 22 al domingo 24 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u201cAgradecemos su apoyo y esperamos darle la bienvenida personalmente en nuestra casa para conmemorar esta organizaci\u00f3n que tiene un lugar muy especial en nuestros corazones.\u201d<\/strong><\/em>&nbsp;Raysa y&nbsp;Alfy Fanjul expresaron a&nbsp;Casa de Campo Living.<\/p>\n\n\n\n<blockquote><h3 style=\"text-align: justify;\">Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR<\/h3><p><strong>Cena Bailable y Desfile de Modas:<\/strong><\/p><p><em>Cuando<\/em>: S\u00e1bado, 23 de enero, 8pm<\/p><p><em>Donde<\/em>: Casa Grande<\/p><p><strong>Torneo de Golf:<\/strong><\/p><p><em>Cuando<\/em>: S\u00e1bado, 23 de enero, 1pm<\/p><p><em>Donde<\/em>:&nbsp;La Romana Country Club<\/p><p><strong>Boutique de Saks 5th Avenue:<\/strong><\/p><p><em>Cuando:&nbsp;<\/em><\/p><p>Viernes, 22 de enero, 3pm \u2013 5pm<\/p><p>S\u00e1bado 23 de enero, 10am \u2013 5pm<\/p><p>Domingo&nbsp;24 de enero,&nbsp;10am \u2013 5pm<\/p><p><em>Donde:<\/em> La Romana Country Club<\/p><p><strong>Contacto:<\/strong>&nbsp;USA (561) 366-5092, RD (809) 523-8270, info@fundacionmir.org<\/p><figure><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-116081\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Invitacion-Gala-Espanol-2.jpg?resize=650%2C650&amp;ssl=1\" alt=\"Invitaci\u00f3n Gala Espa\u00f1ol\" width=\"650\" height=\"650\"><\/figure><figure><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-116083\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Splendor-Gala-Golf-Tournament.jpg?resize=650%2C1005&amp;ssl=1\" alt=\"Splendor Gala Golf Tournament\" width=\"650\" height=\"1005\"><\/figure><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de Modas&nbsp;anual, con&nbsp;Raysa y&nbsp;Alfy Fanjul como anfitriones.<\/p>\n","protected":false},"author":34707,"featured_media":277791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26823,26936,26951,2524,14631,2522,2515,2514,2523,14625,14627,26822],"tags":[3626,24387,2575,4183,24715,11884,7694,3229,2561],"newspack_spnsrs_tax":[],"class_list":["post-348965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-cultura","category-casa-de-campo-living-es","category-ccl-presenta","category-destacados","category-estilo-de-vida","category-eventos-es","category-fundacion-mir-es","category-fundaciones-es","category-moda-es","category-noticias-locales","category-proximamente","category-resort-casa-de-campo","tag-casa-de-campo-es","tag-casa-de-campo-living-es","tag-comunidad-de-casa-de-campo","tag-desfile-de-modas","tag-fundacion-mir-es","tag-gala-esplendor-magico","tag-mir-es","tag-moda","tag-resort-casa-de-campo","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:03:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felix Guerrero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felix Guerrero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/\"},\"author\":{\"name\":\"Felix Guerrero\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/0d45cfc6e376a2f15ac9a92421bd4451\"},\"headline\":\"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!\",\"datePublished\":\"2016-01-07T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:03:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/\"},\"wordCount\":423,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1\",\"keywords\":[\"casa de campo @es\",\"Casa de Campo Living\",\"comunidad de casa de campo\",\"desfile de modas\",\"Fundacion MIR\",\"Gala Esplendor M\u00e1gico\",\"MIR @es\",\"moda\",\"resort casa de campo\"],\"articleSection\":[\"Arte y cultura\",\"Casa de Campo Living @es\",\"CCL presenta\",\"Destacados\",\"Estilo de Vida\",\"Eventos\",\"Fundaci\u00f3n MIR @es\",\"Fundaciones\",\"Moda\",\"Noticias Locales\",\"Proximamente\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/\",\"name\":\"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1\",\"datePublished\":\"2016-01-07T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:03:23+00:00\",\"description\":\"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1\",\"width\":650,\"height\":400,\"caption\":\"Fundaci\u00f3n MIR Magical Splendor Gala 2015\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/gala-esplendor-magicofundacion-mir-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/0d45cfc6e376a2f15ac9a92421bd4451\",\"name\":\"Felix Guerrero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"caption\":\"Felix Guerrero\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/fguerrero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living","description":"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living","og_description":"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de","og_url":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2016-01-07T04:00:00+00:00","article_modified_time":"2022-10-21T23:03:23+00:00","og_image":[{"width":650,"height":400,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","type":"image\/jpeg"}],"author":"Felix Guerrero","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Felix Guerrero","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/"},"author":{"name":"Felix Guerrero","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/0d45cfc6e376a2f15ac9a92421bd4451"},"headline":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!","datePublished":"2016-01-07T04:00:00+00:00","dateModified":"2022-10-21T23:03:23+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/"},"wordCount":423,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","keywords":["casa de campo @es","Casa de Campo Living","comunidad de casa de campo","desfile de modas","Fundacion MIR","Gala Esplendor M\u00e1gico","MIR @es","moda","resort casa de campo"],"articleSection":["Arte y cultura","Casa de Campo Living @es","CCL presenta","Destacados","Estilo de Vida","Eventos","Fundaci\u00f3n MIR @es","Fundaciones","Moda","Noticias Locales","Proximamente","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","url":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","name":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR! | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","datePublished":"2016-01-07T04:00:00+00:00","dateModified":"2022-10-21T23:03:23+00:00","description":"Este pr\u00f3ximo s\u00e1bado&nbsp;23 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 28vo aniversario con su&nbsp;Gala Esplendor M\u00e1gico y Desfile de","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","width":650,"height":400,"caption":"Fundaci\u00f3n MIR Magical Splendor Gala 2015"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/0d45cfc6e376a2f15ac9a92421bd4451","name":"Felix Guerrero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","caption":"Felix Guerrero"},"url":"https:\/\/casadecampoliving.com\/es\/author\/fguerrero\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!","url":"http:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1"},"articleSection":"Arte y cultura","author":[{"@type":"Person","name":"Felix Guerrero"}],"creator":["Felix Guerrero"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo @es","casa de campo living","comunidad de casa de campo","desfile de modas","fundacion mir","gala esplendor m\u00e1gico","mir @es","moda","resort casa de campo"],"dateCreated":"2016-01-07T04:00:00Z","datePublished":"2016-01-07T04:00:00Z","dateModified":"2022-10-21T23:03:23Z"},"rendered":"<meta name=\"parsely-title\" content=\"\u00a1Aqu\u00ed viene la Gala Esplendor M\u00e1gico y Desfile de Modas de la Fundaci\u00f3n MIR!\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/gala-esplendor-magicofundacion-mir-2016\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2016-01-07T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Arte y cultura\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo @es,casa de campo living,comunidad de casa de campo,desfile de modas,fundacion mir,gala esplendor m\u00e1gico,mir @es,moda,resort casa de campo\" \/>\n<meta name=\"parsely-author\" content=\"Felix Guerrero\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":346423,"url":"https:\/\/casadecampoliving.com\/es\/entrevista-con-raysa-fanjul-anfitriona-de-la-gala-esplendor-magico-y-fashion-show-de-la-fundacion-mir\/","url_meta":{"origin":348965,"position":0},"title":"Entrevista con Raysa Fanjul, anfitriona de Gala y Desfile de Modas Esplendor M\u00e1gico de la Fundaci\u00f3n MIR","author":"Rebecca Hughes","date":"1 Ene, 2015","format":false,"excerpt":"El pr\u00f3ximo gran evento de Casa de Campo es... Gala y Desfile de Modas Esplendor M\u00e1gico de la Fundaci\u00f3n MIR, \u00a1que este a\u00f1o celebra su 25 aniversario! Gala y Desfile de Modas Esplendor M\u00e1gico de la Fundaci\u00f3n MIR\u00a0este a\u00f1o ser\u00e1 realizado el s\u00e1bado 17 de enero\u00a0en Casa Grande y es\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/casadecampoliving.com\/es\/category\/eventos-es\/"},"img":{"alt_text":"Raysa Fanjul, Fundacion MIR","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Fanjul-Fundacion_MIR1-1.jpg?fit=650%2C437&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Fanjul-Fundacion_MIR1-1.jpg?fit=650%2C437&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Fanjul-Fundacion_MIR1-1.jpg?fit=650%2C437&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":350808,"url":"https:\/\/casadecampoliving.com\/es\/gala-esplendor-magico-de-la-fundacion-mir-en-enero\/","url_meta":{"origin":348965,"position":1},"title":"\u00a1Marquen la fecha en su calendario para la Gala Esplendor M\u00e1gico de la Fundaci\u00f3n MIR en enero!","author":"Heather Lincoln","date":"14 Nov, 2016","format":false,"excerpt":"El evento anual de recaudaci\u00f3n de fondos Gala Esplendor M\u00e1gico por la Vida, organizado por Alfy y Raysa Fanjul, atrae a un sin n\u00famero de personas de la comunidad y de las areas cercanas al\u00a0resort de Casa de Campo. Entre las actividades de ese d\u00eda, est\u00e1n\u00a0un torneo de golf que\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"Magical Splendor for Life Gala 2016","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Alfy_Lian_Fanjul-e1479155290644.jpg?fit=1000%2C666&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Alfy_Lian_Fanjul-e1479155290644.jpg?fit=1000%2C666&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Alfy_Lian_Fanjul-e1479155290644.jpg?fit=1000%2C666&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Raysa_Alfy_Lian_Fanjul-e1479155290644.jpg?fit=1000%2C666&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354300,"url":"https:\/\/casadecampoliving.com\/es\/este-mes-gala-esplendor-magico-fundacion-mir-por-la-vida-2022\/","url_meta":{"origin":348965,"position":2},"title":"\u00a1Este mes! Fundaci\u00f3n MIR Gala Esplendor M\u00e1gico por la Vida 2022","author":"Casa de Campo Living","date":"2 Mar, 2022","format":false,"excerpt":"La 31ra edicion la Gala Esplendor M\u00e1gico por la Vida de la Fundaci\u00f3n MIR est\u00e1 programado para el s\u00e1bado 26 de marzo de 2022. El evento anual de recaudaci\u00f3n de fondos organizado por Alfy y Raysa Fanjul es uno de los eventos m\u00e1s esperados por la comunidad de Casa de\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_4178-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_4178-1-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_4178-1-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_4178-1-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":346485,"url":"https:\/\/casadecampoliving.com\/es\/junior-tickets-para-esplendor-magico-por-mir-solo-us150\/","url_meta":{"origin":348965,"position":3},"title":"Junior Tickets para Esplendor M\u00e1gico por MIR  a solo US$150","author":"Esther Dariet Cazanova","date":"10 Ene, 2015","format":false,"excerpt":"El s\u00e1bado 17 de enero, la Fundaci\u00f3n MIR estar\u00e1 celebrando su 25 anniversario con su anual gala y desfile de modas Esplendor M\u00e1gico, con Raysa y Alfy Fanjul como los anfitriones, y si eres menor de 40 estas cordialmente invitado a unirte a la fiesta por solo\u00a0US$150 por persona. Estos\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"badgley mischka fashion show","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/badgley_mischka_fashion_show-3.jpg?fit=650%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/badgley_mischka_fashion_show-3.jpg?fit=650%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/badgley_mischka_fashion_show-3.jpg?fit=650%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":354317,"url":"https:\/\/casadecampoliving.com\/es\/este-sabado-fundacion-mir-gala-esplendor-magico-por-la-vida-2022-con-naeem-khan\/","url_meta":{"origin":348965,"position":4},"title":"\u00a1Este s\u00e1bado! Fundaci\u00f3n MIR Gala Esplendor M\u00e1gico por la Vida 2022 con Naeem Khan","author":"Casa de Campo Living","date":"21 Mar, 2022","format":false,"excerpt":"\u00a1Ya casi es hora del evento anual de recaudaci\u00f3n de fondos de la Fundaci\u00f3n MIR, la \u201cGala Esplendor M\u00e1gico para la Vida\u201d! Este a\u00f1o el glamuroso evento que recauda fondos para la organizaci\u00f3n ben\u00e9fica MIR se llevar\u00e1 a cabo este s\u00e1bado 26 de marzo en Casa Grande y La Romana\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3814-scaled-e1647869387374-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3814-scaled-e1647869387374-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3814-scaled-e1647869387374-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3814-scaled-e1647869387374-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":354184,"url":"https:\/\/casadecampoliving.com\/es\/reserve-la-fecha-31a-gala-esplendor-magico-por-la-vida-de-la-fundacion-mir-en-enero-de-2022\/","url_meta":{"origin":348965,"position":5},"title":"POSPUESTO: 31a Gala Esplendor M\u00e1gico por la Vida de la Fundaci\u00f3n MIR 2022","author":"Casa de Campo Living","date":"28 Oct, 2021","format":false,"excerpt":"ACTUALIZACI\u00d3N: Desafortunadamente, debido a la \u00faltima ola de Covid, la Gala se pospone hasta que el evento pueda llevarse a cabo de manera segura. Le informaremos tan pronto como tengamos una nueva fecha. \u00a1Reserva la fecha! El 31\u00ba Gala Esplendor M\u00e1gico por la Vida de la Fundaci\u00f3n MIR est\u00e1 programado\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3686-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3686-1.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3686-1.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/BDC_3686-1.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-MIR-Magical-Splendor-Gala-2015-1.jpg?fit=650%2C400&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/34707"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=348965"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348965\/revisions"}],"predecessor-version":[{"id":348968,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348965\/revisions\/348968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/277791"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=348965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=348965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=348965"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=348965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}