{"id":348683,"date":"2015-11-26T00:00:00","date_gmt":"2015-11-26T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/"},"modified":"2022-10-21T19:02:37","modified_gmt":"2022-10-21T23:02:37","slug":"marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","title":{"rendered":"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016.jpg?resize=800%2C348&amp;ssl=1\" alt=\"Cartelera 26 de Noviembre 2016\" class=\"wp-image-115117\" height=\"348\" width=\"800\"\/><\/figure>\n<\/div>\n\n\n<p>Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: <strong>\u201cUn Gran Dinosaurio\u201d<\/strong>&nbsp;y&nbsp;<strong>\u201cD\u00e9jate Querer\u201d<\/strong>.&nbsp;Mientras todav\u00eda en sala tenemos: <strong>\u201cLos juegos del hambre: Sinsajo. Parte 2\u201d<\/strong>,<strong>&nbsp;<\/strong><strong>\u201cSpectre\u201d<\/strong>&nbsp;y&nbsp;<strong>\u201cPeanuts La Pel\u00edcula\u201d<\/strong>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<blockquote><h3><strong>\u201cLos juegos del hambre: Sinsajo. Parte 2\u201d<\/strong><\/h3><p><strong>Proyecciones:<\/strong><\/p><ul>\n<li>Lunes&nbsp;\u2013 Vieres,&nbsp;6:30pm &amp; 9:25pm<\/li>\n<li>S\u00e1bado \u2013 Domingo, 4:00pm, 6:30pm &amp; 9:25pm<\/li>\n<\/ul><p><strong>Sinopsis: <\/strong><em>Esta&nbsp;es la impactante conclusi\u00f3n de la franquicia, en la que Katniss Everdeen se da cuenta de que ya no s\u00f3lo est\u00e1 en juego su supervivencia, sino tambi\u00e9n el futuro.<\/em><\/p><p style=\"text-align: left;\"><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/suSI9gZ7G14\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3><strong>\u201cUn Gran Dinosaurio\u201d<\/strong><\/h3><p><strong>Proyecciones:<\/strong><\/p><ul>\n<li>Lunes&nbsp;\u2013 Viernes, 700pm &amp; 9:10pm<\/li>\n<li>S\u00e1bado \u2013 Domingo, 4:50pm, 700pm &amp; 9:10pm<\/li>\n<\/ul><p><strong>Sinopsis: <\/strong><em>Un \u00e9picoviaje en el mundo de los dinosaurios donde&nbsp;un Apatosaurus llamado Arlo hace un amigo humano.<\/em><\/p><p style=\"text-align: left;\"><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/6CQs9AGEjlU\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3><strong>\u201cPeanuts La Pel\u00edcula\u201d<\/strong><\/h3><p><strong>Proyecciones:<\/strong><\/p><ul>\n<li>S\u00e1bado \u2013 Domingo, 4:50pm<\/li>\n<\/ul><p style=\"text-align: left;\"><strong><strong><strong><strong>Sinopsis:<\/strong><\/strong><\/strong><\/strong> <em>La pel\u00edcula narra c\u00f3mo Snoopy se embarca en una gran misi\u00f3n por los cielos junto con su equipo para perseguir a su archienemigo, al tiempo que su mejor amigo, Charlie Brown, comienza su propia b\u00fasqueda \u00e9pica de vuelta a casa.<\/em><\/p><p style=\"text-align: left;\"><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/7mB-F9Bq39k\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3><strong>\u201cD\u00e9jate Querer\u201d<\/strong><\/h3><p><strong>Proyecciones:<\/strong><\/p><ul>\n<li>Lunes&nbsp;\u2013&nbsp;Domingo, 7:05pm<\/li>\n<\/ul><p><strong>Sinopsis:&nbsp;<\/strong>Un amor no correspondido motiva a un hombre a&nbsp;escribir sobre sus experiencias.<\/p><p style=\"text-align: left;\"><strong>Trailer:<\/strong><\/p><p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lNPQ2sUD7YU\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><\/blockquote>\n\n\n\n<blockquote><h3><strong>\u201cSpectre\u201d<\/strong><\/h3><p><strong>Proyecciones:<\/strong><\/p><ul>\n<li>Lunes \u2013&nbsp;Domingo, 9:15pm<\/li>\n<\/ul><p style=\"text-align: left;\"><strong><strong><strong><strong>Sinopsis:<\/strong><\/strong><\/strong><\/strong> <em>Un mensaje cr\u00edptico del pasado env\u00eda a James Bond a una misi\u00f3n secreta a la Ciudad de M\u00e9xico y finalmente a Roma, donde conoce a Luc\u00eda Sciarra (Monica Bellucci), la hermosa y prohibida viuda de un infame criminal. Bond se infiltra en una reuni\u00f3n secreta y descubre la existencia de una siniestra organizaci\u00f3n conocida como SPECTRE.<\/em><\/p><p style=\"text-align: left;\"><strong>Trailer:<\/strong><\/p><p style=\"text-align: left;\"><strong><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ycih-sGr9js\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/strong><\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>NOTA:<\/strong>&nbsp;Publicamos los nuevos horarios de pel\u00edculas tan pronto como las recibimos \u2013 normalmente los mi\u00e9rcoles por la tarde.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras todav\u00eda en sala tenemos: \u201cLos juegos del hambre: Sinsajo. Parte 2\u201d,&nbsp;\u201cSpectre\u201d&nbsp;y&nbsp;\u201cPeanuts La Pel\u00edcula\u201d.<\/p>\n","protected":false},"author":34707,"featured_media":304519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26823,3126,26581,14625],"tags":[2780,3626,3573,2558],"newspack_spnsrs_tax":[],"class_list":["post-348683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-cultura","category-cine-3","category-la-marina-casa-de-campo","category-noticias-locales","tag-cartelera","tag-casa-de-campo-es","tag-marina-casa-de-campo-es","tag-peliculas","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-26T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:02:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felix Guerrero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felix Guerrero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\"},\"author\":{\"name\":\"Felix Guerrero\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/0d45cfc6e376a2f15ac9a92421bd4451\"},\"headline\":\"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre\",\"datePublished\":\"2015-11-26T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:02:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\",\"keywords\":[\"cartelera\",\"casa de campo @es\",\"Marina Casa de Campo @es\",\"peliculas\"],\"articleSection\":[\"Arte y cultura\",\"Cine @es\",\"La Marina Casa de Campo\",\"Noticias Locales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\",\"name\":\"Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\",\"datePublished\":\"2015-11-26T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:02:37+00:00\",\"description\":\"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\",\"width\":800,\"height\":348,\"caption\":\"Cartelera 26 de Noviembre 2016\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/0d45cfc6e376a2f15ac9a92421bd4451\",\"name\":\"Felix Guerrero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g\",\"caption\":\"Felix Guerrero\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/fguerrero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living","description":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","og_locale":"es_ES","og_type":"article","og_title":"Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living","og_description":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras","og_url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2015-11-26T04:00:00+00:00","article_modified_time":"2022-10-21T23:02:37+00:00","og_image":[{"width":800,"height":348,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","type":"image\/jpeg"}],"author":"Felix Guerrero","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Felix Guerrero","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/"},"author":{"name":"Felix Guerrero","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/0d45cfc6e376a2f15ac9a92421bd4451"},"headline":"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre","datePublished":"2015-11-26T04:00:00+00:00","dateModified":"2022-10-21T23:02:37+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/"},"wordCount":328,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","keywords":["cartelera","casa de campo @es","Marina Casa de Campo @es","peliculas"],"articleSection":["Arte y cultura","Cine @es","La Marina Casa de Campo","Noticias Locales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","name":"Marina Casa de Campo cartelera de cine: 26 de noviembre - 2 de diciembre | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","datePublished":"2015-11-26T04:00:00+00:00","dateModified":"2022-10-21T23:02:37+00:00","description":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos&nbsp;nuevas pel\u00edculas: \u201cUn Gran Dinosaurio\u201d&nbsp;y&nbsp;\u201cD\u00e9jate Querer\u201d.&nbsp;Mientras","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","width":800,"height":348,"caption":"Cartelera 26 de Noviembre 2016"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/0d45cfc6e376a2f15ac9a92421bd4451","name":"Felix Guerrero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14a8050b9491854cab6ae2240dcb42ad0fad787b7fa453ad0991fd1262157df3?s=96&d=mm&r=g","caption":"Felix Guerrero"},"url":"https:\/\/casadecampoliving.com\/es\/author\/fguerrero\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre","url":"http:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1"},"articleSection":"Arte y cultura","author":[{"@type":"Person","name":"Felix Guerrero"}],"creator":["Felix Guerrero"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["cartelera","casa de campo @es","marina casa de campo @es","peliculas"],"dateCreated":"2015-11-26T04:00:00Z","datePublished":"2015-11-26T04:00:00Z","dateModified":"2022-10-21T23:02:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Marina Casa de Campo cartelera de cine: 26 de noviembre &#8211; 2 de diciembre\",\"url\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/marina-casa-de-campo-cartelera-de-cine-26-de-noviembre-2-de-diciembre\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?resize=150%2C150&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1\"},\"articleSection\":\"Arte y cultura\",\"author\":[{\"@type\":\"Person\",\"name\":\"Felix Guerrero\"}],\"creator\":[\"Felix Guerrero\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Casa de Campo Living\",\"logo\":\"https:\\\/\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png\"},\"keywords\":[\"cartelera\",\"casa de campo @es\",\"marina casa de campo @es\",\"peliculas\"],\"dateCreated\":\"2015-11-26T04:00:00Z\",\"datePublished\":\"2015-11-26T04:00:00Z\",\"dateModified\":\"2022-10-21T23:02:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-26-de-Noviembre-2016-1.jpg?fit=800%2C348&ssl=1","jetpack-related-posts":[{"id":348725,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-3-9-de-diciembre\/","url_meta":{"origin":348683,"position":0},"title":"Marina Casa de Campo cartelera de cine: 3 &#8211; 9 de diciembre","author":"Felix Guerrero","date":"3 Dic, 2015","format":false,"excerpt":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos\u00a0nuevas pel\u00edculas: \u201cCreed: Coraz\u00f3n de Campe\u00f3n\u201d y\u00a0\u201cVictor Frankenstein\u201d.\u00a0Mientras todav\u00eda en sala tenemos: \u201cUn Gran Dinosaurio\u201d y\u00a0\u201cLos juegos del hambre: Sinsajo. Parte 2\u201d. \u201cCreed: Coraz\u00f3n de Campe\u00f3n\u201dProyecciones: Lunes \u2013 Viernes, 6:40pm & 9:25pm S\u00e1bado \u2013 Domingo, 4:15pm,\u00a06:40pm &\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"Cartelera 3 de Diciembre 2015","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Diciembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Diciembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Diciembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-3-de-Diciembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":348634,"url":"https:\/\/casadecampoliving.com\/es\/marina-casa-de-campo-cartelera-de-cine-19-25-de-noviembre\/","url_meta":{"origin":348683,"position":1},"title":"Marina Casa de Campo cartelera de cine: 19 &#8211; 25 de noviembre","author":"Felix Guerrero","date":"19 Nov, 2015","format":false,"excerpt":"Para esta semana, el cine de la Marina Casa de Campo nos trae dos\u00a0nuevas pel\u00edculas: \u201cLos juegos del hambre: Sinsajo. Parte 2\u201d y\u00a0\u201cLa Cumbre Escarlata\u201d.\u00a0Mientras todav\u00eda en sala tenemos: \u201cSpectre\u201d\u00a0y\u00a0\u201cPeanuts La Pel\u00edcula\u201d. \u201cLos juegos del hambre: Sinsajo. Parte 2\u201dProyecciones: Lunes\u00a0\u2013 Vieres,\u00a06:30pm & 9:25pm S\u00e1bado \u2013 Domingo, 4:00pm, 6:30pm & 9:25pm\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"Cartelera 19 de Noviembre 2015","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-19-de-Noviembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-19-de-Noviembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-19-de-Noviembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Cartelera-19-de-Noviembre-2015-1.jpg?fit=800%2C348&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":346027,"url":"https:\/\/casadecampoliving.com\/es\/cartelera-de-cine-del-20-al-26-de-noviembre\/","url_meta":{"origin":348683,"position":2},"title":"Cartelera de Cine: del 20 al 26 de noviembre","author":"Maria Isabel B\u00e1ez","date":"20 Nov, 2014","format":false,"excerpt":"Para esta semana el cine de la Marina Casa de Campo nos trae en cartelera 2 pel\u00edculas nuevas:\u00a0\u201cLos Juegos del Hambre: Sinsajo\u201d\u00a0y\u00a0\u201cDos tontos todav\u00eda m\u00e1s tontos\u201d,\u00a0mientras todav\u00eda en sala tenemos\u00a0\u00a0\u00a0\u201cInterstellar\u201d.\u00a0Salvedad:\u00a0A partir de ahora el cine de la Marina Casa de Campo estar\u00e1 abierto\u00a0todos los d\u00edas hasta nuevo aviso. IsnterstellarProyecciones: Lunes\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-20-1.png?fit=800%2C346&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-20-1.png?fit=800%2C346&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-20-1.png?fit=800%2C346&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-20-1.png?fit=800%2C346&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":346089,"url":"https:\/\/casadecampoliving.com\/es\/cartelera-de-cine-del-27-de-nov-al-3-de-dic\/","url_meta":{"origin":348683,"position":3},"title":"Cartelera de Cine: del 27 de Nov. al 3 de Dic.","author":"Maria Isabel B\u00e1ez","date":"27 Nov, 2014","format":false,"excerpt":"Para esta semana el cine de la Marina Casa de Campo nos trae en cartelera 2 pel\u00edculas nuevas:\u00a0\u201cThe Lunchbox\u201d\u00a0y\u00a0\u201cLos ping\u00fcinos de Madagascar\u201d,\u00a0mientras todav\u00eda en sala tenemos\u00a0\u00a0\u00a0\u201cLos Juegos del Hambre: Sinsajo\u201d\u00a0y\u00a0\u201cDos tontos todav\u00eda m\u00e1s tontos\u201d.\u00a0Salvedad:\u00a0A partir de ahora el cine de la Marina Casa de Campo estar\u00e1 abierto\u00a0todos los d\u00edas hasta\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-27-1.png?fit=800%2C346&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-27-1.png?fit=800%2C346&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-27-1.png?fit=800%2C346&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-NOV-27-1.png?fit=800%2C346&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":346162,"url":"https:\/\/casadecampoliving.com\/es\/cartelera-de-cine-del-4-al-10-de-dic\/","url_meta":{"origin":348683,"position":4},"title":"Cartelera de Cine: del 4 al 10 de Dic.","author":"Maria Isabel B\u00e1ez","date":"4 Dic, 2014","format":false,"excerpt":"Para esta semana el cine de la Marina Casa de Campo nos trae en cartelera 3 pel\u00edculas nuevas: \u201cAs\u00ed nos va\u201d,\u201cLa Entrega\u201d\u00a0y\u00a0\u201cComo acabar sin tu Jefe 2\u201d,\u00a0mientras todav\u00eda en sala tenemos\u00a0\u00a0\u00a0\u201cLos Juegos del Hambre: Sinsajo\u201d\u00a0y\u00a0\u201cLos ping\u00fcinos de Madagascar\u201d.\u00a0Salvedad:\u00a0A partir de ahora el cine de la Marina Casa de Campo estar\u00e1\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-DEC-4-1.png?fit=800%2C347&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-DEC-4-1.png?fit=800%2C347&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-DEC-4-1.png?fit=800%2C347&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/CDCAMP-DEC-4-1.png?fit=800%2C347&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":343398,"url":"https:\/\/casadecampoliving.com\/es\/cartelera-de-cine-marina-casa-de-campo-dic5\/","url_meta":{"origin":348683,"position":5},"title":"Cartelera de Cine: desde el jueves 5 de dic. al domingo 8 de dic.","author":"Perkin Agramonte","date":"4 Dic, 2013","format":false,"excerpt":"Para esta semana el cine de La Marina Casa de Campo nos trae 1 pel\u00edcula nueva: \u201cLos Juegos del Hambre \u2013 En Llamas\u201d. A\u00fan en cartelera: \u201cLluvia de\u00a0alb\u00f3ndigas\u00a02\u2033 y \u201cUna\u00a0Cuesti\u00f3n\u00a0de Tiempo\u201d.\u00a0Salvedad: A partir de ahora el cine de La Marina Casa de Campo estar\u00e1 abierto de jueves a domingo. \u00a0Los\u2026","rel":"","context":"En \u00abArte y cultura\u00bb","block_context":{"text":"Arte y cultura","link":"https:\/\/casadecampoliving.com\/category\/arte-y-cultura\/"},"img":{"alt_text":"Movies Marina Casa de Campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Movies-Marina-Casa-de-Campo-1.jpg?fit=650%2C282&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Movies-Marina-Casa-de-Campo-1.jpg?fit=650%2C282&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Movies-Marina-Casa-de-Campo-1.jpg?fit=650%2C282&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/34707"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=348683"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348683\/revisions"}],"predecessor-version":[{"id":348684,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/348683\/revisions\/348684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/304519"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=348683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=348683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=348683"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=348683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}