{"id":346603,"date":"2015-01-23T00:00:00","date_gmt":"2015-01-23T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/presentando-la-fundacion-lirio-del-valle\/"},"modified":"2022-10-21T19:00:16","modified_gmt":"2022-10-21T23:00:16","slug":"presentando-la-fundacion-lirio-del-valle","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","title":{"rendered":"Presentando la Fundaci\u00f3n Lirio del Valle"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6.jpg?resize=650%2C432&amp;ssl=1\" alt=\"Fundaci\u00f3n Lirio del Valle 6\" class=\"wp-image-106937\" height=\"432\" width=\"650\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido continuar con esta practica brindando sonrisas y alegr\u00eda a los 120 ni\u00f1os de la Fundaci\u00f3n Lirio del Valle.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, este grupo de damas nos cuentan un poco m\u00e1s de esta fundaci\u00f3n, la cual tiene m\u00e1s de cinco a\u00f1os en funcionamiento y ha contribuido al bienestar de aquellos sumidos en la pobreza.<\/p>\n\n\n\n<blockquote><figure><img decoding=\"async\" loading=\"lazy\" class=\"alignright wp-image-106927\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-267x300-1.jpg?resize=312%2C350&amp;ssl=1\" alt=\"Fundaci\u00f3n Lirio del Valle\" width=\"312\" height=\"350\"><\/figure><p>Perm\u00edtanme presentarles la Fundaci\u00f3n Lirio del Valle, una organizaci\u00f3n sin fines de lucro dirigida por voluntarios y las madres de algunos de los 120 ni\u00f1os que integran esta fundaci\u00f3n. La fundaci\u00f3n se inici\u00f3 en 2009 por Anna Maria Pla, en ese momento propietaria de villa procedente de Barcelona. El enfoque de la fundaci\u00f3n es la atenci\u00f3n educativa a los ni\u00f1os de Villa Caoba, uno de los sectores m\u00e1s pobres de La Romana. Nuestro objetivo es proporcionar la mejor educaci\u00f3n posible a estos ni\u00f1os. Para esto buscamos patrocinadores dispuestos a ayudar a proporcionar una oportunidad de una vida mejor para uno o m\u00e1s de nuestros hijos. Estamos contentos de decir que tenemos varios patrocinadores que apoyan el programa y, por supuesto, siempre est\u00e1n dispuestos a dar la bienvenida m\u00e1s<\/p><p>Como apoyo adicional a los ni\u00f1os, actualmente ofrecemos una comida a la semana, el s\u00e1bado. La edad de los ni\u00f1os var\u00eda de 3 a 13. Algunos de los mayores de 13 a\u00f1os se les pide que ayuden a los voluntarios en la gesti\u00f3n de las actividades sabatinas. En estos s\u00e1bados se encuentra una feliz y siempre sonriente Dolly Esteban, el alma de la fundaci\u00f3n; con el apoyo de Anne Heffelfinger y, Evangelina Uckert. Tenemos, por supuesto, la coordinadora y maestra de escuela, Aracelis \u00c1vila, el coraz\u00f3n de la fundaci\u00f3n, que sorprende a todos con su proverbial memoria conociendo los nombres, familias y direcciones de todos los ni\u00f1os.<\/p><figure><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-106926\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-4.jpg?resize=650%2C540&amp;ssl=1\" alt=\"Fundaci\u00f3n Lirio del Valle 4\" width=\"650\" height=\"540\"><\/figure><p><em>Si desea saber m\u00e1s acerca de la Fundaci\u00f3n Lirio del Valle, por favor, p\u00f3ngase en contacto con cualquiera de nosotros ayudando como voluntarios:<\/em><\/p><ul>\n<li>Dolly Esteban: Casa de Campo (809) 523-8354, cel (809) 330-7644<\/li>\n<li>Anne Heffelfinger: Casa de Campo<\/li>\n<li>Evangelina Uckert: (809) 523-8015, Casa de Campo.<\/li>\n<li>Aracelis Avila, Coordinator: (829) 752-9335.<\/li>\n<\/ul><p><em>Tambi\u00e9n nos gustar\u00eda mencionar que estaremos encantados de recibir cualquier ayuda, de cualquier tipo, que se nos da, ya sea para el uso de los ni\u00f1os o para sus familias. No hace falta decir que todos est\u00e1n en necesidad.<\/em><\/p><p><em>Muchas gracias por su amable atenci\u00f3n.<\/em><\/p><p>Fundacion Lirio del Valle \u2013 R.N.C.: 430104337.<br>\n<a href=\"http:\/\/www.villacaoba.com\/eng\/index.htm\" target=\"_blank\" rel=\"noopener\">www.villacaoba.com<\/a><\/p><figure><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-106924\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-1.jpg?resize=650%2C448&amp;ssl=1\" alt=\"Fundaci\u00f3n Lirio del Valle\" width=\"650\" height=\"448\"><\/figure><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido continuar con esta practica brindando sonrisas y alegr\u00eda a los 120 ni\u00f1os de la Fundaci\u00f3n Lirio del Valle.<\/p>\n","protected":false},"author":1097,"featured_media":275377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","newspack_content_restriction_is_exempt":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,26951,2524,14631,2522,2514,2507,2506,14625,14627,2521,26822],"tags":[3626,8094,24387,6371,11927,11928],"newspack_spnsrs_tax":[],"class_list":["post-346603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-ccl-presenta","category-destacados","category-estilo-de-vida","category-eventos-es","category-fundaciones-es","category-la-romana-es","category-mas-alla-de-casa-es","category-noticias-locales","category-proximamente","category-republica-dominicana-2","category-resort-casa-de-campo","tag-casa-de-campo-es","tag-casa-de-campo-community-es","tag-casa-de-campo-living-es","tag-casa-de-campo-resort-es","tag-fundacion-lirio-del-valle-es","tag-villa-caoba-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-23T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T23:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Perkin Agramonte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Perkin Agramonte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/\"},\"author\":{\"name\":\"Perkin Agramonte\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/c8efa6049510554b7d5fea078d728f72\"},\"headline\":\"Presentando la Fundaci\u00f3n Lirio del Valle\",\"datePublished\":\"2015-01-23T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/\"},\"wordCount\":459,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1\",\"keywords\":[\"casa de campo @es\",\"Casa de Campo Community @es\",\"Casa de Campo Living\",\"casa de campo resort @es\",\"Fundaci\u00f3n Lirio del Valle @es\",\"Villa Caoba @es\"],\"articleSection\":[\"Casa de Campo Living @es\",\"CCL presenta\",\"Destacados\",\"Estilo de Vida\",\"Eventos\",\"Fundaciones\",\"La Romana @es\",\"M\u00e1s all\u00e1 de Casa\",\"Noticias Locales\",\"Proximamente\",\"Rep\u00fablica Dominicana @es\",\"Resort Casa de Campo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/\",\"name\":\"Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1\",\"datePublished\":\"2015-01-23T04:00:00+00:00\",\"dateModified\":\"2022-10-21T23:00:16+00:00\",\"description\":\"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1\",\"width\":650,\"height\":432,\"caption\":\"Fundaci\u00f3n Lirio del Valle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/presentando-la-fundacion-lirio-del-valle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentando la Fundaci\u00f3n Lirio del Valle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/c8efa6049510554b7d5fea078d728f72\",\"name\":\"Perkin Agramonte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g\",\"caption\":\"Perkin Agramonte\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/cagramonte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living","description":"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","og_locale":"es_ES","og_type":"article","og_title":"Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living","og_description":"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido","og_url":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2015-01-23T04:00:00+00:00","article_modified_time":"2022-10-21T23:00:16+00:00","og_image":[{"width":650,"height":432,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","type":"image\/jpeg"}],"author":"Perkin Agramonte","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Perkin Agramonte","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/"},"author":{"name":"Perkin Agramonte","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/c8efa6049510554b7d5fea078d728f72"},"headline":"Presentando la Fundaci\u00f3n Lirio del Valle","datePublished":"2015-01-23T04:00:00+00:00","dateModified":"2022-10-21T23:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/"},"wordCount":459,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","keywords":["casa de campo @es","Casa de Campo Community @es","Casa de Campo Living","casa de campo resort @es","Fundaci\u00f3n Lirio del Valle @es","Villa Caoba @es"],"articleSection":["Casa de Campo Living @es","CCL presenta","Destacados","Estilo de Vida","Eventos","Fundaciones","La Romana @es","M\u00e1s all\u00e1 de Casa","Noticias Locales","Proximamente","Rep\u00fablica Dominicana @es","Resort Casa de Campo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","url":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","name":"Presentando la Fundaci\u00f3n Lirio del Valle | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","datePublished":"2015-01-23T04:00:00+00:00","dateModified":"2022-10-21T23:00:16+00:00","description":"La comunidad Casa de Campo siempre se caracteriza por la solidaridad y apoyo que brinda a los m\u00e1s necesitados. Algunas damas de Casa de Campo han decido","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","width":650,"height":432,"caption":"Fundaci\u00f3n Lirio del Valle"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Presentando la Fundaci\u00f3n Lirio del Valle"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/c8efa6049510554b7d5fea078d728f72","name":"Perkin Agramonte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57bfdafcae55fb83dbb79a1585a9eab7f269b7720fb0b64cb9a4e0cd2962fa10?s=96&d=mm&r=g","caption":"Perkin Agramonte"},"url":"https:\/\/casadecampoliving.com\/es\/author\/cagramonte\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Presentando la Fundaci\u00f3n Lirio del Valle","url":"http:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1"},"articleSection":"CCL presenta","author":[{"@type":"Person","name":"Perkin Agramonte"}],"creator":["Perkin Agramonte"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo @es","casa de campo community @es","casa de campo living","casa de campo resort @es","fundaci\u00f3n lirio del valle @es","villa caoba @es"],"dateCreated":"2015-01-23T04:00:00Z","datePublished":"2015-01-23T04:00:00Z","dateModified":"2022-10-21T23:00:16Z"},"rendered":"<meta name=\"parsely-title\" content=\"Presentando la Fundaci\u00f3n Lirio del Valle\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/presentando-la-fundacion-lirio-del-valle\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2015-01-23T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"CCL presenta\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo @es,casa de campo community @es,casa de campo living,casa de campo resort @es,fundaci\u00f3n lirio del valle @es,villa caoba @es\" \/>\n<meta name=\"parsely-author\" content=\"Perkin Agramonte\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1","jetpack-related-posts":[{"id":320266,"url":"https:\/\/casadecampoliving.com\/es\/the-fundacion-lirio-del-valle-celebrates-the-end-of-the-school-year\/","url_meta":{"origin":346603,"position":0},"title":"The Fundaci\u00f3n Lirio del Valle celebrates the end of the school year!","author":"Rebecca Silvestri","date":"20 Jul, 2011","format":false,"excerpt":"The end of the school year at the Fundacion Lirio del Valle was a party celebrated with cake, ice cream, presents and even clowns \u00a0- during which the children, helpers as well as the volunteers and sponsors from the Casa de Campo community has a wonderful time! The Fundacion Lirio\u2026","rel":"","context":"En \u00abBeyond Casa\u00bb","block_context":{"text":"Beyond Casa","link":"https:\/\/casadecampoliving.com\/category\/beyond-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fundacion_lirio_del_valle_casa_de_campo-1.jpg?fit=489%2C380&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":325107,"url":"https:\/\/casadecampoliving.com\/fundacion-lirio-del-valle\/","url_meta":{"origin":346603,"position":1},"title":"Introducing Fundaci\u00f3n Lirio del Valle","author":"Perkin Agramonte","date":"23 Ene, 2015","format":false,"excerpt":"The Casa de Campo community has long since been characterized by the solidarity and support provided to the neediest. Some ladies from Casa de Campo decided to continue with this practice bringing smiles and joy to 120 children\u00a0of the Fundaci\u00f3n Lirio del Valle. Below, this group of ladies tell us\u2026","rel":"","context":"En \u00abBeyond Casa\u00bb","block_context":{"text":"Beyond Casa","link":"https:\/\/casadecampoliving.com\/category\/beyond-casa\/"},"img":{"alt_text":"Fundaci\u00f3n Lirio del Valle","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":349412,"url":"https:\/\/casadecampoliving.com\/es\/fundacion-lirio-del-valle-los-invita-un-evento-beneficio-de-los-ninos-de-villa-caoba\/","url_meta":{"origin":346603,"position":2},"title":"Fundaci\u00f3n Lirio del Valle los invita a un evento a beneficio de los ni\u00f1os de Villa Caoba","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"14 Mar, 2016","format":false,"excerpt":"Fundaci\u00f3n Lirio del Valle le invita a una peque\u00f1a merienda en nombre de los hijos de Villa Caoba este viernes 18 de marzo de 5-7 pm en Toronjas # 7 en Casa de Campo, villa de nuestra querida Inge Demyttenaere. La comunidad de Casa de Campo se caracteriza por la\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/casadecampoliving.com\/es\/category\/destacados\/"},"img":{"alt_text":"Fundaci\u00f3n Lirio del Valle","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Fundacion-Lirio-del-Valle-6-e1458051306961.jpg?fit=650%2C432&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":350919,"url":"https:\/\/casadecampoliving.com\/es\/un-mensaje-navideno-de-la-fundacion-lirio-del-valle\/","url_meta":{"origin":346603,"position":3},"title":"Un mensaje navide\u00f1o de la Fundaci\u00f3n Lirio del Valle","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"15 Dic, 2016","format":false,"excerpt":"La Fundaci\u00f3n Lirio del Valle es un proyecto de caridad que se inici\u00f3 hace siete a\u00f1os y que ha trabajado arduamente\u00a0para mejorar la vida de muchos ni\u00f1os pobres en La Romana. La fundaci\u00f3n fue fundada por Anna Maria Pla y Rosario Volquez, quienes con un grupo de voluntarios dominicanos y\u2026","rel":"","context":"En \u00abFundaciones\u00bb","block_context":{"text":"Fundaciones","link":"https:\/\/casadecampoliving.com\/es\/category\/fundaciones-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Villa-caoba-group.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":349581,"url":"https:\/\/casadecampoliving.com\/es\/bingo-por-los-ninos-de-villa-caoba\/","url_meta":{"origin":346603,"position":4},"title":"\u00a1Un Juego de BINGO por los ni\u00f1os de Villa Caoba!","author":"Marlenys Guzm\u00e1n Casta\u00f1os","date":"11 Abr, 2016","format":false,"excerpt":"El pasado lunes 4 de abril varias damas de Casa de Campo se reunieron para disfrutar de uno de los juegos m\u00e1s divertidos de todos los tiempos... \u00a1BINGO! Y lo que fue a\u00fan mejor era que la actividad reuni\u00f3 fondos para los ni\u00f1os de Villa Caoba, La Romana. La Fundaci\u00f3n\u2026","rel":"","context":"En \u00abRep\u00fablica Dominicana @es\u00bb","block_context":{"text":"Rep\u00fablica Dominicana @es","link":"https:\/\/casadecampoliving.com\/es\/category\/republica-dominicana-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0025-e1460381516666.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0025-e1460381516666.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0025-e1460381516666.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/DSC_0025-e1460381516666.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":353285,"url":"https:\/\/casadecampoliving.com\/es\/fundacion-lirio-del-valle-te-invita-una-tarde-de-paella-sangria-y-flamenco-beneficio-de-los-ninos-de-villa-caoba\/","url_meta":{"origin":346603,"position":5},"title":"Fundaci\u00f3n Lirio del Valle te invita a una tarde de paella, sangr\u00eda y flamenco a beneficio de los ni\u00f1os de Villa Caoba.","author":"Casa de Campo Living","date":"11 Mar, 2019","format":false,"excerpt":"La Fundaci\u00f3n Lirio del Valle le invita este viernes 15 de marzo a compartir una picadera, paella, sangr\u00eda espa\u00f1ola y una presentaci\u00f3n de flamenco en nombre de los ni\u00f1os de Villa Caoba. Esta iniciativa de recaudaci\u00f3n de fondos, auspiciada por Inge Demyttenaere, se llevar\u00e1 a cabo en la villa Tornojas\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/IMG_8955-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/1097"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=346603"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346603\/revisions"}],"predecessor-version":[{"id":346604,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346603\/revisions\/346604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/275377"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=346603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=346603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=346603"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=346603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}