{"id":346521,"date":"2015-01-16T00:00:00","date_gmt":"2015-01-16T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/vin-diesel-casa-de-campo-2\/"},"modified":"2022-10-21T18:56:46","modified_gmt":"2022-10-21T22:56:46","slug":"vin-diesel-casa-de-campo-2","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","title":{"rendered":"Vin Diesel disfruta de \u00abLa Temporada\u00bb en Casa de Campo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach.jpg?resize=650%2C433&amp;ssl=1\" alt=\"Vin Diesel Minitas Beach\" class=\"wp-image-106222\" height=\"433\" width=\"650\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach.jpg?ssl=1\"><br>\n<\/a>El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus actividades diarias, gracias al milagro moderno que es \u201csocial media\u201d, tenemos un buena idea \u2013 !y maravillosas fotos para mostrarlo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n\u00bfEntonces qu\u00e9 hizo Vin Diesel en Casa de Campo?<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">1. Pas\u00f3 un buen rato en la playa con hermosas mujeres<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach_3.jpg?ssl=1\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106221\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach_3.jpg?resize=650%2C433&amp;ssl=1\" alt=\"Vin Diesel Minitas Beach 3\" width=\"650\" height=\"433\"><\/a><br>\n(Imagen de&nbsp;<a href=\"https:\/\/www.facebook.com\/VinDiesel?ref=br_tf\">Vin Diesel en&nbsp;Facebook<\/a>)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Pos\u00f3 para fotos con fans<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo.jpg?ssl=1\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106219\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo.jpg?resize=650%2C433&amp;ssl=1\" alt=\"Vin Diesel Casa de Campo\" width=\"650\" height=\"433\"><\/a><br>\n(Imagen de&nbsp;<a href=\"https:\/\/www.facebook.com\/VinDiesel?ref=br_tf\">Vin Diesel en&nbsp;Facebook<\/a>)<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">3. Jug\u00f3 con su jetski y&nbsp;kayak en la playa Minitas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_Minitas_Beach_2.jpg?ssl=1\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106217\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_Minitas_Beach_2.jpg?resize=650%2C433&amp;ssl=1\" alt=\"Vin Diesel Casa de Campo Minitas Beach\" width=\"650\" height=\"433\"><\/a><br>\n(Imagen de&nbsp;<a href=\"https:\/\/www.facebook.com\/VinDiesel?ref=br_tf\">Vin Diesel en&nbsp;Facebook<\/a>)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Celebr\u00f3 junto &nbsp;la comunidad en algunos de los eventos m\u00e1s grandes de las festividades<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_2.jpg?ssl=1\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106215\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_2.jpg?resize=650%2C596&amp;ssl=1\" alt=\"Vin Diesel Casa de Campo 2\" width=\"650\" height=\"596\"><\/a><br>\n(Imagen de&nbsp;<a href=\"http:\/\/instagram.com\/heidinesbakken\">@heidinesbakken&nbsp;en Instagram<\/a>)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Festej\u00f3 en Palmilla<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106218\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_palmilla.jpg?resize=650%2C584&amp;ssl=1\" alt=\"Vin_Diesel_Casa_de_Campo_palmilla\" width=\"650\" height=\"584\"><br>\n(Imagen de by<a href=\"http:\/\/instagram.com\/michelaliagi\">@michelaliagi en Instagram<\/a>)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Asisti\u00f3 a una fiesta de blanco y dorado de lujo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-106216\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo_3.jpg?resize=650%2C505&amp;ssl=1\" alt=\"Vin_Diesel_Casa_de_Campo_3\" width=\"650\" height=\"505\"><br>\n(Imagen de&nbsp;<a href=\"http:\/\/instagram.com\/dbunster1\">@dbunster1 en Instagram<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, bueno, bueno\u2026 definitivamento no se puede negar que Vin Diesel tuvo una estad\u00eda maravillosa en Casa de Campo durante las festividades \u2013&nbsp;!esperamos verte otra vez pronto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus actividades diarias, gracias al milagro moderno que es \u201csocial media\u201d, tenemos un buena idea \u2013 !y maravillosas fotos para mostrarlo! \u00bfEntonces qu\u00e9 hizo Vin Diesel en Casa [&hellip;]<\/p>\n","protected":false},"author":33461,"featured_media":274649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","newspack_content_restriction_is_exempt":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2513,14631,14625,26822,2526],"tags":[23815,2624,18932,502,1289],"newspack_spnsrs_tax":[],"class_list":["post-346521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades-es","category-estilo-de-vida","category-noticias-locales","category-resort-casa-de-campo","category-titulares-es","tag-casa-de-campo-es-17","tag-celebridades","tag-la-romana-es-4","tag-playa-minitas","tag-vin-diesel","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vin Diesel disfruta de &quot;La Temporada&quot; en Casa de Campo | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vin Diesel disfruta de &quot;La Temporada&quot; en Casa de Campo | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-16T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T22:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Esther Dariet Cazanova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esther Dariet Cazanova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/\"},\"author\":{\"name\":\"Esther Dariet Cazanova\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/2ca7e4a1f56a8ac8eef9eca15a995d24\"},\"headline\":\"Vin Diesel disfruta de \u00abLa Temporada\u00bb en Casa de Campo\",\"datePublished\":\"2015-01-16T04:00:00+00:00\",\"dateModified\":\"2022-10-21T22:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/\"},\"wordCount\":195,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1\",\"keywords\":[\"Casa de Campo\",\"celebridades\",\"La Romana\",\"playa minitas\",\"vin diesel\"],\"articleSection\":[\"Celebridades\",\"Estilo de Vida\",\"Noticias Locales\",\"Resort Casa de Campo\",\"Titulares\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/\",\"name\":\"Vin Diesel disfruta de \\\"La Temporada\\\" en Casa de Campo | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1\",\"datePublished\":\"2015-01-16T04:00:00+00:00\",\"dateModified\":\"2022-10-21T22:56:46+00:00\",\"description\":\"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1\",\"width\":650,\"height\":433,\"caption\":\"Vin Diesel Minitas Beach\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/vin-diesel-casa-de-campo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vin Diesel disfruta de &#8220;La Temporada&#8221; en Casa de Campo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/2ca7e4a1f56a8ac8eef9eca15a995d24\",\"name\":\"Esther Dariet Cazanova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g\",\"caption\":\"Esther Dariet Cazanova\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/ecazanova\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vin Diesel disfruta de \"La Temporada\" en Casa de Campo | Casa de Campo Living","description":"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","og_locale":"es_ES","og_type":"article","og_title":"Vin Diesel disfruta de \"La Temporada\" en Casa de Campo | Casa de Campo Living","og_description":"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus","og_url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2015-01-16T04:00:00+00:00","article_modified_time":"2022-10-21T22:56:46+00:00","og_image":[{"width":650,"height":433,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","type":"image\/jpeg"}],"author":"Esther Dariet Cazanova","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Esther Dariet Cazanova","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/"},"author":{"name":"Esther Dariet Cazanova","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/2ca7e4a1f56a8ac8eef9eca15a995d24"},"headline":"Vin Diesel disfruta de \u00abLa Temporada\u00bb en Casa de Campo","datePublished":"2015-01-16T04:00:00+00:00","dateModified":"2022-10-21T22:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/"},"wordCount":195,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","keywords":["Casa de Campo","celebridades","La Romana","playa minitas","vin diesel"],"articleSection":["Celebridades","Estilo de Vida","Noticias Locales","Resort Casa de Campo","Titulares"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","name":"Vin Diesel disfruta de \"La Temporada\" en Casa de Campo | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","datePublished":"2015-01-16T04:00:00+00:00","dateModified":"2022-10-21T22:56:46+00:00","description":"El famoso actor y cineasta americano acaba de durar m\u00e1s de un mes en Casa de Campo\u2026 \u00bfEntonces qu\u00e9 hizo? Y mientras no tenemos mucha informaci\u00f3n sobre sus","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","width":650,"height":433,"caption":"Vin Diesel Minitas Beach"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vin Diesel disfruta de &#8220;La Temporada&#8221; en Casa de Campo"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/2ca7e4a1f56a8ac8eef9eca15a995d24","name":"Esther Dariet Cazanova","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72b7b72b3d3cb7950e2004fb83ef2e9e40177b9f1cb00226aee65904879073b6?s=96&d=mm&r=g","caption":"Esther Dariet Cazanova"},"url":"https:\/\/casadecampoliving.com\/es\/author\/ecazanova\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Vin Diesel disfruta de \u00abLa Temporada\u00bb en Casa de Campo","url":"http:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1"},"articleSection":"Celebridades","author":[{"@type":"Person","name":"Esther Dariet Cazanova"}],"creator":["Esther Dariet Cazanova"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo","celebridades","la romana","playa minitas","vin diesel"],"dateCreated":"2015-01-16T04:00:00Z","datePublished":"2015-01-16T04:00:00Z","dateModified":"2022-10-21T22:56:46Z"},"rendered":"<meta name=\"parsely-title\" content=\"Vin Diesel disfruta de \u00abLa Temporada\u00bb en Casa de Campo\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/vin-diesel-casa-de-campo-2\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2015-01-16T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Celebridades\" \/>\n<meta name=\"parsely-tags\" content=\"casa de campo,celebridades,la romana,playa minitas,vin diesel\" \/>\n<meta name=\"parsely-author\" content=\"Esther Dariet Cazanova\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Minitas_Beach-1.jpg?fit=650%2C433&ssl=1","jetpack-related-posts":[{"id":353850,"url":"https:\/\/casadecampoliving.com\/es\/celebridades-en-casa-vin-diesel-y-raul-de-molina-vienen-a-casa-de-campo-para-un-merecido-descanso\/","url_meta":{"origin":346521,"position":0},"title":"Celebridades en Casa: Vin Diesel y Ra\u00fal de Molina vienen a Casa de Campo para un merecido descanso","author":"Casa de Campo Living","date":"8 Sep, 2020","format":false,"excerpt":"Todo el mundo ama a Casa de Campo: las personas que viven aqu\u00ed, los \u2018capitale\u00f1os\u2019 que pasan el fin de semana aqu\u00ed, los turistas que vacacionan aqu\u00ed y las numerosas celebridades que vienen aqu\u00ed para descansar. \u00bfComo no amarlo? Tenemos campos de golf de renombre mundial dise\u00f1ados por el legendario\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Untitled-design-5.jpg?fit=1000%2C592&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Untitled-design-5.jpg?fit=1000%2C592&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Untitled-design-5.jpg?fit=1000%2C592&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Untitled-design-5.jpg?fit=1000%2C592&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":346373,"url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-luce-musculoso-en-la-playa-en-casa-de-campo\/","url_meta":{"origin":346521,"position":1},"title":"Vin Diesel luce musculoso en la playa en Casa de Campo","author":"Rebecca Hughes","date":"23 Dic, 2014","format":false,"excerpt":"\u00a1Apuesto a que usted desea haber estado en Playa Minitas en Casa de Campo, cuando esta sexy foto fue\u00a0tomada! Actor\/director, Vin Diesel se encuentra entre una de las muchas celebridades que frecuentan Casa de Campo, y como puede ver en esta foto publicada ayer en su cuenta oficial de Facebook,\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"Vin Diesel Casa de Campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo-3.jpg?fit=650%2C402&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo-3.jpg?fit=650%2C402&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin_Diesel_Casa_de_Campo-3.jpg?fit=650%2C402&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":349063,"url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-entrenando-en-casa\/","url_meta":{"origin":346521,"position":2},"title":"Vin Diesel entrenando para Xander en Casa","author":"Heather Lincoln","date":"26 Ene, 2016","format":false,"excerpt":"\u00a1Una de nuestras celebridades favoritas est\u00e9 de vuelta en Casa de Campo! Por lo que pudimos ver en su cuenta de Instagram, el actor de R\u00e1pido y Furioso est\u00e1 entrenado arduamente para \u201cxXx: The Return of Xanger Cage\u201d, la cual est\u00e1 actualmente en etapa de pre-producci\u00f3n. \u00bfSer\u00e1 que Vin Diesel\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"Vin Diesel in Casa 2016","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-in-Casa-2016-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-in-Casa-2016-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-in-Casa-2016-1.jpg?fit=650%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":338011,"url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-entrena-para-riddick-en-el-country-club-de-la-romana-casa-de-campo\/","url_meta":{"origin":346521,"position":3},"title":"Vin Diesel entrena para \u00abRiddick\u00bb en el Country Club de La Romana, Casa de Campo!","author":"","date":"5 Ene, 2012","format":false,"excerpt":"A qu\u00e9 lugar de Casa de Campo van las celebridades para pasar un buen rato? Realmente en cualquier lugar, pero Vin Diesel se est\u00e1 convirtiendo en una de las figuras m\u00e1s vistas en Casa de Campo, dada las m\u00faltiples veces en que se le ha encontrado en el Onno\u2019s Bar\u2026","rel":"","context":"En \u00abCelebs\u00bb","block_context":{"text":"Celebs","link":"https:\/\/casadecampoliving.com\/category\/celebs\/"},"img":{"alt_text":"vin diesel casa de campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo-5.jpg?fit=650%2C433&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo-5.jpg?fit=650%2C433&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo-5.jpg?fit=650%2C433&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":337565,"url":"https:\/\/casadecampoliving.com\/es\/celebridades-en-casa-de-campo-vin-diesel-nos-acompano-en-el-joli-day-beach-en-minitas\/","url_meta":{"origin":346521,"position":4},"title":"Celebridades en Casa de Campo: Vin Diesel nos acompa\u00f1\u00f3 en el Joli-Day Beach en Minitas!","author":"","date":"30 Nov, 2011","format":false,"excerpt":"El pasado\u00a0s\u00e1bado\u00a026 de noviembre fue celebrado el evento de Joli-Day Beach y el famoso actor, Vin Diesel,\u00a0tambi\u00e9n\u00a0nos\u00a0acompa\u00f1\u00f3\u00a0en un\u00a0d\u00eda\u00a0repleto de\u00a0diversi\u00f3n! Joli-Day Beach celebrado por segundo a\u00f1o consecutivo, fue auspiciado por Coors Light y Ketel One Vodka en Playa Minitas. Este evento atrajo a mas de 1,000 due\u00f1os de villa, residentes y\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo.jpg?fit=650%2C432&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo.jpg?fit=650%2C432&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/vin_diesel_casa_de_campo.jpg?fit=650%2C432&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":349092,"url":"https:\/\/casadecampoliving.com\/es\/vin-diesel-hace-su-aparicion-en-la-gala-esplendor-magico\/","url_meta":{"origin":346521,"position":5},"title":"Vin Diesel hace su aparici\u00f3n en la Gala Esplendor M\u00e1gico","author":"Heather Lincoln","date":"28 Ene, 2016","format":false,"excerpt":"Vin Diesel pas\u00f3 a saludarnos\u00a0en\u00a0la Gala Esplendor M\u00e1gico. El encantador actor y productor pos\u00f3 para fotos con los ni\u00f1os de la Fundaci\u00f3n MIR, Lyanne Fanjul, e invitados que asistieron a la cena y desfile de moda. Nuestra afortunada fot\u00f3grafa, Mariana Heredia, esta vez decidi\u00f3 ponerse frente al lente para\u00a0tomarse una\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-Magical-Splendor-Gala.jpg?fit=650%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-Magical-Splendor-Gala.jpg?fit=650%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Vin-Diesel-Magical-Splendor-Gala.jpg?fit=650%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/33461"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=346521"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346521\/revisions"}],"predecessor-version":[{"id":346522,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/346521\/revisions\/346522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/274649"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=346521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=346521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=346521"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=346521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}