{"id":344604,"date":"2014-06-18T00:00:00","date_gmt":"2014-06-18T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/"},"modified":"2022-10-21T18:50:07","modified_gmt":"2022-10-21T22:50:07","slug":"30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","title":{"rendered":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO.jpg?resize=646%2C377&amp;ssl=1\" alt=\"\" class=\"wp-image-91601\" height=\"377\" width=\"646\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual estamos seguros todos se sentir\u00e1n identificados. Aqu\u00ed las 30 razones por las cuales nadie puede evitar enamorarse de Casa de Campo, vistas a trav\u00e9s de fotos de Instagram.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Casa es literalmente la definici\u00f3n de vivir donde ustedes vacacionan.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/pPV966rpJS\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Algunos hasta le llaman el para\u00edso.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/miPieQGC98\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Los descansos para el caf\u00e9 se ven as\u00ed\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/pGr0z6g2YF\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. \u2026y el brunch siempre va en estilo.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/naja8RKhdA\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. El clima de playa es nuestro clima de todos los d\u00edas\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/nTLoU-L3Wh\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6. \u2026y la playa nunca est\u00e1 a m\u00e1s de 5 minutos.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/nHWoOeLTOR\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7. Las modelos colombianas vacacionan aqu\u00ed\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/imTHGlRYsc\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8. \u2026\u00a1Y hasta Fernando de Prison Break!<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/im0e18Caiz\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9. Vin Diesel hasta tiene una casa aqu\u00ed.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/kUK5OLGghH\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10. Los bartenders de Chav\u00f3n son nuestros amigos\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/cTHMoArShc\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11. \u2026Y todos compartimos el lazo&nbsp;de tener por lo menos una memoria vergonzosa&nbsp;sobre estas piedras.<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/lXsUZnLShf\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12. \u00bfD\u00f3nde m\u00e1s encuentras vistas as\u00ed?<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/pEuM_IDvGQ\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>13. \u2026\u00bfo atardeceres as\u00ed?<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/pW8CqiEwiy\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>14. \u00bf\u00a1Y comida AS\u00cd!?<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/mQk9ibgBKE\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>15. Nunca falta el buen ron\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/mpz-JAGguh\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>16. \u2026Y la mascota de la comunidad es la m\u00e1s \u00fanica que podr\u00edas encontrar<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/iy3TT8LSs6\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>17. \u00a1De hecho somos tan especiales que Grecia se mud\u00f3 aqu\u00ed!<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/f72b-YQVk5\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>18. CDC sabe hacer una buena fiesta\u2026.<\/b><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/ipaYApRYo2\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>19. \u2026En la playa hasta el amanecer<\/b><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/io_7A9xYoP\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>20. \u2026O en botes hasta el anochecer<br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/T65cVuv7zj\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>21. Y para relajarse luego de la fiesta\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/nS_fL0g2Vj\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>22. Los campos de golf son tan buenos que hasta los no golfistas quieren jugar en ellos\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/hE6---N6sE\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>23. \u2026\u00bfpues qui\u00e9n puede resistirse a como el Teeth te hace ver como todo un pro?<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/ndgp2ekocJ\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>24. Aqu\u00ed todo el mundo est\u00e1 en forma\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/c1rOASmuYC\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>25. \u2026Y le encantan los deportes<br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/Jf6wasGUuO\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>26. Tanto que hacemos paddleboard hasta en la piscina<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/njZhcXSxev\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>27. No necesitamos de Paris Fashion Week\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/oFctPMgU8-\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>28. \u2026Y las leyendas vienen a cantar para nosotros<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/k_VqfjrYiD\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>29. Nuestras condolencias para&nbsp;los que no pueden quedarse, porque es que bueno\u2026<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/kaEn1FA2Q6\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>30:&nbsp;Ustedes le llaman un momento\u2026 nosotros le llamamos VIDA<\/strong><br>\n<iframe loading=\"lazy\" src=\"\/\/instagram.com\/p\/mNP4GcSxWe\/embed\/\" width=\"612\" height=\"710\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual estamos seguros todos se sentir\u00e1n identificados. Aqu\u00ed las 30 razones por las cuales nadie puede evitar enamorarse de Casa de Campo, vistas a trav\u00e9s de fotos de Instagram.<\/p>\n","protected":false},"author":454,"featured_media":249841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,2524,14625,26822,2526],"tags":[15387,23815,9007,5718,502],"newspack_spnsrs_tax":[],"class_list":["post-344604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-destacados","category-noticias-locales","category-resort-casa-de-campo","category-titulares-es","tag-altos-de-chavon-es","tag-casa-de-campo-es-17","tag-instagram","tag-la-marina","tag-playa-minitas","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-18T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T22:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"646\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eliana Alba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliana Alba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/\"},\"author\":{\"name\":\"Eliana Alba\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/bd396a8f8ea621ed900f2d4a7407a3a2\"},\"headline\":\"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?\",\"datePublished\":\"2014-06-18T04:00:00+00:00\",\"dateModified\":\"2022-10-21T22:50:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1\",\"keywords\":[\"Altos de Chavon\",\"Casa de Campo\",\"instagram\",\"la marina\",\"playa minitas\"],\"articleSection\":[\"Casa de Campo Living @es\",\"Destacados\",\"Noticias Locales\",\"Resort Casa de Campo\",\"Titulares\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/\",\"name\":\"Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1\",\"datePublished\":\"2014-06-18T04:00:00+00:00\",\"dateModified\":\"2022-10-21T22:50:07+00:00\",\"description\":\"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1\",\"width\":646,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/bd396a8f8ea621ed900f2d4a7407a3a2\",\"name\":\"Eliana Alba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g\",\"caption\":\"Eliana Alba\"},\"sameAs\":[\"https:\\\/\\\/casadecampoliving.com\"],\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/ealba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living","description":"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","og_locale":"es_ES","og_type":"article","og_title":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living","og_description":"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual","og_url":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2014-06-18T04:00:00+00:00","article_modified_time":"2022-10-21T22:50:07+00:00","og_image":[{"width":646,"height":377,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","type":"image\/jpeg"}],"author":"Eliana Alba","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Eliana Alba","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/"},"author":{"name":"Eliana Alba","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/bd396a8f8ea621ed900f2d4a7407a3a2"},"headline":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?","datePublished":"2014-06-18T04:00:00+00:00","dateModified":"2022-10-21T22:50:07+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/"},"wordCount":318,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","keywords":["Altos de Chavon","Casa de Campo","instagram","la marina","playa minitas"],"articleSection":["Casa de Campo Living @es","Destacados","Noticias Locales","Resort Casa de Campo","Titulares"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","url":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","name":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte? | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","datePublished":"2014-06-18T04:00:00+00:00","dateModified":"2022-10-21T22:50:07+00:00","description":"Viendo que buzzfeed tiene a todos obsesionados con diferentes listas, pensamos ser\u00eda una buena idea hacer nuestra propia lista divertida, una con la cual","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","width":646,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/bd396a8f8ea621ed900f2d4a7407a3a2","name":"Eliana Alba","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9855856e733abb59c5985d70cc9f36d1c83420173446a782077af61c55fb0a9c?s=96&d=mm&r=g","caption":"Eliana Alba"},"sameAs":["https:\/\/casadecampoliving.com"],"url":"https:\/\/casadecampoliving.com\/es\/author\/ealba\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?","url":"http:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1"},"articleSection":"Casa de Campo Living @es","author":[{"@type":"Person","name":"Eliana Alba"}],"creator":["Eliana Alba"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["altos de chavon","casa de campo","instagram","la marina","playa minitas"],"dateCreated":"2014-06-18T04:00:00Z","datePublished":"2014-06-18T04:00:00Z","dateModified":"2022-10-21T22:50:07Z"},"rendered":"<meta name=\"parsely-title\" content=\"Oh Casa de Campo, \u00bfc\u00f3mo no amarte?\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/30-razones-por-la-que-amamos-casa-de-campo-vistas-traves-de-instagram\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2014-06-18T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Casa de Campo Living @es\" \/>\n<meta name=\"parsely-tags\" content=\"altos de chavon,casa de campo,instagram,la marina,playa minitas\" \/>\n<meta name=\"parsely-author\" content=\"Eliana Alba\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":344777,"url":"https:\/\/casadecampoliving.com\/es\/top-ten-tuesdays-mejores-sitios-para-disfrutar-de-un-atardecer\/","url_meta":{"origin":344604,"position":0},"title":"\u00abTop Ten Tuesdays\u00bb &#8211; mejores sitios para disfrutar de un atardecer","author":"Emil Mella","date":"8 Jul, 2014","format":false,"excerpt":"Para nuestro tercer Top Ten Tuesday, les estaremos dando tres sitios en Casa de Campo (o en su alrededor) en los cuales pueden disfrutar de un bello atardecer, por medio de fant\u00e1sticas fotos de Instagram. \u00a1Vengan a ver! Los atardeceres son una belleza, no cabe duda ah\u00ed. Casa de Campo\u2026","rel":"","context":"En \u00abEstilo de Vida\u00bb","block_context":{"text":"Estilo de Vida","link":"https:\/\/casadecampoliving.com\/es\/category\/estilo-de-vida\/"},"img":{"alt_text":"sunset palmilla","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/sunset_palmilla.jpg?fit=650%2C455&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/sunset_palmilla.jpg?fit=650%2C455&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/sunset_palmilla.jpg?fit=650%2C455&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":344696,"url":"https:\/\/casadecampoliving.com\/es\/92376\/","url_meta":{"origin":344604,"position":1},"title":"Casa de Campo, \u00a1un resort siempre premiado!","author":"Emil Mella","date":"27 Jun, 2014","format":false,"excerpt":"Ya que nos estamos acercando al 40\u00ba aniversario de Casa de Campo, acord\u00e9monos de todos los premios que este ha recibido.Nosotros adoramos Casa de Campo, y creo que esto es algo obvio, mira hacia arriba, al nombre del sitio web\u2026 Si\u2026 Como se pueden imaginar, tenemos una opini\u00f3n clara sobre\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/casadecampoliving.com\/es\/category\/eventos-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa-de-Campo_9-1.jpg?fit=650%2C320&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa-de-Campo_9-1.jpg?fit=650%2C320&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa-de-Campo_9-1.jpg?fit=650%2C320&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":343173,"url":"https:\/\/casadecampoliving.com\/es\/la-revista-todo-casa-de-campo-ahora-es-mas-util-con-su-guia-de-restaurantes\/","url_meta":{"origin":344604,"position":2},"title":"TODO Casa de Campo ahora incluye una Gu\u00eda de Restaurantes","author":"Lenny Castillo","date":"29 Oct, 2013","format":false,"excerpt":"TODO Casa de Campo, la gu\u00eda oficial del Resort Casa de Campo ahora es m\u00e1s \u00fatil que nunca - con una Gu\u00eda de Restaurantes. Con tanto que hacer en Casa de Campo desde golf, paseos a caballo, y relajarse en la playa o en el Spa de Casa de Campo,\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TODO_casa_de_campo_restaurant_guide.jpg?fit=650%2C520&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TODO_casa_de_campo_restaurant_guide.jpg?fit=650%2C520&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/TODO_casa_de_campo_restaurant_guide.jpg?fit=650%2C520&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":354090,"url":"https:\/\/casadecampoliving.com\/es\/celebridades-en-casa-dwyane-wade-organiza-viaje-de-golf-del-dia-del-padre-en-casa-de-campo\/","url_meta":{"origin":344604,"position":3},"title":"Celebridades en Casa: \u00a1Dwyane Wade organiza \u00abViaje de golf del D\u00eda del padre\u00bb en Casa de Campo!","author":"Casa de Campo Living","date":"25 Jun, 2021","format":false,"excerpt":"Casa de Campo no es ajena a las celebridades, a lo largo de los a\u00f1os se ha visto una larga lista de otros actores, atletas, cantantes y modelos para tomar el sol en nuestra isla caribe\u00f1a. La semana pasada no fue una excepci\u00f3n, ya que el jugador de baloncesto y\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/207200992_572824027422411_7850248583155485463_n-1.jpg?fit=800%2C596&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/207200992_572824027422411_7850248583155485463_n-1.jpg?fit=800%2C596&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/207200992_572824027422411_7850248583155485463_n-1.jpg?fit=800%2C596&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/207200992_572824027422411_7850248583155485463_n-1.jpg?fit=800%2C596&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":345852,"url":"https:\/\/casadecampoliving.com\/es\/hanley-ramirez-de-vacaciones-en-casa-de-campo\/","url_meta":{"origin":344604,"position":4},"title":"Hanley Ram\u00edrez de vacaciones en Casa de Campo","author":"Perkin Agramonte","date":"30 Oct, 2014","format":false,"excerpt":"\u00bfRecuerda nuestra lista de las 10 principales estrellas del deporte en Casa de Campo? Bueno, \u00bfadivine que? \u00a1Esa lista contin\u00faa creciendo! Por ejemplo el famoso\u00a0beisbolista dominicano Hanley Ram\u00edrez estuvo recientemente en Casa de Campo disfrutando de unas cortas vacaciones. Hanley Ram\u00edrez es oriundo de Saman\u00e1 una provincia localizada al Noroeste\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Hanley_Ramirez_3-1.png?fit=650%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Hanley_Ramirez_3-1.png?fit=650%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Hanley_Ramirez_3-1.png?fit=650%2C450&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":351360,"url":"https:\/\/casadecampoliving.com\/es\/la-revista-casa-de-campo-living-llega-justo-tiempo-para-semana-santa\/","url_meta":{"origin":344604,"position":5},"title":"\u00a1La revista Casa de Campo Living llega justo a tiempo para Semana Santa!","author":"Heather Lincoln","date":"10 Abr, 2017","format":false,"excerpt":"Mientras que la edici\u00f3n de primavera 2017 de nuestra publicaci\u00f3n hermana CasaLife\u00a0nos muestra un poco de la historia y el futuro de Casa de Campo, nuestra revista Casa de Campo Living muestra todo lo que ocurre dentro del resort en todo momento. Con un enfoque en las vacaciones de primavera,\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"Casa de Campo Living","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_Living-e1491845109598.jpg?fit=1000%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_Living-e1491845109598.jpg?fit=1000%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_Living-e1491845109598.jpg?fit=1000%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_Living-e1491845109598.jpg?fit=1000%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/ILOVECASADECAMPO-1.jpg?fit=646%2C377&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/344604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/454"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=344604"}],"version-history":[{"count":1,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/344604\/revisions"}],"predecessor-version":[{"id":344605,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/344604\/revisions\/344605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/249841"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=344604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=344604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=344604"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=344604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}