{"id":340309,"date":"2012-12-13T00:00:00","date_gmt":"2012-12-13T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/"},"modified":"2022-11-10T10:34:34","modified_gmt":"2022-11-10T14:34:34","slug":"review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","title":{"rendered":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill"},"content":{"rendered":"<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62206\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch.jpg?resize=650%2C520&#038;ssl=1\" alt=\"rum punch\" width=\"650\" height=\"520\" \/>Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes &#8211; realizando Noches Dominicanas! El pasado viernes nosotros (Casa de Campo Living) junto con otros \u00abcatadores\u00bb\u00a0probamos para un resumen &#8211; y descubrimos una grandiosa comida, buenos precios y la pasamos de maravilla!<!--more-->\n\nPhilip y yo (Rebecca Hughes) fuimos acompa\u00f1ados por Tere Garcia de Miami, Bijai Singh, quien ha vivido en la Rep\u00fablica Dominicana la mayor parte de su vida, tambien como Valeria Singh y Yana Myuller, ambas de Russia y viviendo tiempo completo en Casa de Campo. As\u00ed que sin m\u00e1s que agregar aqu\u00ed le traemos nuestro resumen del nuevo \u00abMenu Dominicano\u00bb, disponible todas las noches desde las 6pm en el Lago Grill de Casa de Campo.\n<p style=\"text-align: center;\"><strong>\u00a0El grupo de cata! Yana, Tere, Bijai, Valeria y Philip.<\/strong>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62251\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_living-2.jpg?resize=650%2C236&#038;ssl=1\" alt=\"casa de campo living\" width=\"650\" height=\"236\" \/><\/p>\n<strong>Ambiente<\/strong>\n\nUbicado en la hermosa palapa con vista al hoyo 18 de el campo de golf \u00a0Teeth of the Dog, el Lago Grill esta especialmente fresco durante la noche, gracias a la refrescante brisa del mar \u00a0y al mismo tiempo la atm\u00f3sfera elegante y sencilla \u00a0que lo vuelve sin lugar a dudas el restaurante con el ambiente m\u00e1s casual de Casa de Campo- con una \u00a0atm\u00f3sfera que te hace sentir relajado y c\u00f3modo.\n\nY todos los viernes y s\u00e1bados por la noche el menu Dominicano estar\u00e1 acompa\u00f1ado por m\u00fasica en vivo &#8211; una tradici\u00f3n folkl\u00f3rica Dominicana llamada \u00abPerico Ripiao\u00bb.\n\n\u00ab<em>Es un gran lugar para traer a los ni\u00f1os.<\/em>\u00bb &#8212;Bijai Singh (Bijai y Valeria tienen dos ni\u00f1os peque\u00f1os)\n<p style=\"text-align: center;\"><strong>Bienvenidos! Empieza tu noche Dominicana con ron y ponche!<\/strong>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62250\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch1.jpg?resize=650%2C420&#038;ssl=1\" alt=\"rum punch\" width=\"650\" height=\"420\" \/><\/p>\n<p style=\"text-align: left;\"><strong>Bebidas<\/strong><\/p>\n<p style=\"text-align: left;\">Para contagiarnos del esp\u00edritu de la Noche Dominicana todos optamos por cocteles basados en ron &#8211; las chicas optaron por el \u00abCasa de Campo\u00bb (US$12) con chinola, naranja, pi\u00f1a y \u00a0ron atl\u00e1ntico, mientras los caballeros eligieron el tradicional \u00abRum Punch\u00bb &#8211; fue un poco m\u00e1s potente y todos los jueves hay un 2&#215;1 para due\u00f1os de villa de Casa de Campo!<\/p>\n<p style=\"text-align: left;\">Tambi\u00e9n durante el transcurso de la noche disfrutamos de sus vinos de la casa &#8211; el tinto as\u00ed como el blanco (fue un viernes&#8230;) los 2 muy ricos y ambos vendidos a US$26 por botella sentimos que el precio fue razonable.<\/p>\nY as\u00ed luego del coctel y la conversaci\u00f3n pasamos a la comida! \u00a0Buen provecho &#8211; aqu\u00ed esta lo que devoramos&#8230;\n<blockquote><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Empanadas de yuca con salsa t\u00e1rtara y cilantro\u00a0<strong>\u00a0(US$6)<\/strong><\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62253\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/empanadas.jpg?resize=620%2C461&#038;ssl=1\" alt=\"empanadas\" width=\"620\" height=\"461\" \/>\n\nUn verdadero plato tradicional Dominicano, las empanadas son peque\u00f1os pasteles salados rellenos de carne o queso frito. Existen muchas variedades, pero estas fueron hechas de harina de yuca (la cual yo creo que es la m\u00e1s aunt\u00e9ntica) y rellenas de dos rellenos diferentes; carne molida y queso. Servidas con una deliciosa salsa t\u00e1rtara con un toque de cilantro, estas empanadas recibieron la buena aprobaci\u00f3n de todos nosotros &#8211; especialmente porque no eran grasientas como era de esperarse.<\/blockquote>\n<blockquote><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Quesadillas de pollo servidas con pico de gallo y guacamole (US$14)<\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62252\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/quesadilla.jpg?resize=620%2C331&#038;ssl=1\" alt=\"quesadilla\" width=\"620\" height=\"331\" \/>\n\nUn plato simple, las quesadillas de pollo, fueron tortillas rellenas de queso y pollo, cortados en peque\u00f1os pedazos y servidos con guacamole fresco y pico de gallo. Mientras que es grandioso para compartir todos estuvimos de acuerdo en que seria una excelente opci\u00f3n para ni\u00f1os (aunque para los peque\u00f1os ser\u00eda bueno no incluir el pico de gallo &#8211; es bastante picante!)<\/blockquote>\n<blockquote><strong>\u00a0Sancocho tradicional Dominicano (US$17)<\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62254\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/sancocho.jpg?resize=620%2C421&#038;ssl=1\" alt=\"sancocho\" width=\"620\" height=\"421\" \/>\n\nEl sancocho es posiblemente el m\u00e1s aunt\u00e9ntico, tradicional y popular de todas las opciones de la cocina Dominicana. Carne estofada con variedad de viveres (papa, yuca, casabe, zanahoria, etc), este delicioso, carnoso y suculento plato es servido con arroz blanco y aguacate, perfecto con una pizca de salsa picante o unas gotas de lim\u00f3n. Y mientras todos disfrut\u00e1bamos de nuestro delicioso y aut\u00e9ntico plato Dominicano &#8211; nos sorprendimos bastante al descubrir que se parece mucho al \u00a0\u00abGoulash Ruso\u00bb (un plato Ruso).\n\n\u00ab<em>Esto es verdadera comida rusa!<\/em>\u00bb &#8212;Valeria Singh\n\n\u00ab<em>Esta muy bueno &#8211; justo como en Russia<\/em>\u00bb &#8212;Yana Myuller<\/blockquote>\n<blockquote><strong>Chivo a la Higueyana (US$17)<\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62255\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/chivo.jpg?resize=620%2C428&#038;ssl=1\" alt=\"chivo\" width=\"620\" height=\"428\" \/>\n\nLo primero que te deleitar\u00e1 sobre este hermoso plato ser\u00e1 el fantastico aroma que emerge de este plato. Servido acompa\u00f1ado de arroz con tocineta y \u00a0frijoles negros, es sorprendentemente un plato refinado, lleno de sabor y cocinado a la perfecci\u00f3n.\n\n\u00ab<em>Nunca hab\u00eda probado chivo antes y esta estuvo realmente buena. Tuvo sabor a una verdadera comida casera.<\/em>\u00bb &#8212;Tere Garcia\n\n\u00ab<em>Super<\/em>\u00bb &#8212; Bijai Singh\n\n\u00ab<em>Esto estuvo delicioso<\/em>\u00bb &#8212;Valeria Singh<\/blockquote>\n<blockquote><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Asopao de camarones con mamajuana y coco (US$17)<\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62257\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/asopao.jpg?resize=620%2C430&#038;ssl=1\" alt=\"asopao\" width=\"620\" height=\"430\" \/>\n\nEl asopao es parecido al risotto, pero de hecho un poco m\u00e1s liquido. T\u00edpicamente el asopao es hecho con camarones, pero en esta versi\u00f3n los camarones fueron salteados con vegetales y licor mamajuana antes de ser agregados al asopao &#8211; algo que le agrego un distintivo sabor diferente. Aparte de todo esto nos impresion\u00f3 el sabor fresco de este plato.\n\n\u00ab<em>El sabor es realmente bueno!<\/em>\u00bb &#8212; Tere Garcia<strong><\/strong><\/blockquote>\n<blockquote><strong>Pescado al Coco (US$17)<\/strong>\n\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62258\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/pescado_al_coco.jpg?resize=620%2C355&#038;ssl=1\" alt=\"pescado al coco\" width=\"620\" height=\"355\" \/>\n\nLuego de los otros 5 platos, nuestro grupo estaba un poco lleno y por lo tanto vacilante al sabor de otro plato, pero ya que el Pescado al Coco es un cl\u00e1sico plato Dominicano no pudimos rehusarnos a probarlo &#8211; y yo personalmente me alegro de haberlo probado &#8211; estuvo delicioso! Yo dir\u00eda que definitivamente el mejor Pescado al Coco que he probado. Estuvo ligero y sabroso.\n\n\u00ab<em>El plato fue una rica receta caribe\u00f1a, con una sabrosa salsa de coco y vegetales que complementa el sabor del delicioso pescado.\u00a0Todo un lujo para aquellos que buscan disfrutar de una comida ligera.<\/em>\u00bb &#8212;Philip Silvestri<\/blockquote>\n<blockquote><strong>Majarete (US$6)<\/strong>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62259\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/majarete.jpg?resize=620%2C398&#038;ssl=1\" alt=\"majarete\" width=\"620\" height=\"398\" \/>\n\nEste cl\u00e1sico postre dominicano tiene una hermosa presentaci\u00f3n y un maravilloso sabor. El majarete esta hecho de maiz y es como un \u00abpudin de arroz\u00bb, delicioso y cremoso, con un maravilloso sabor y toques de canela. Servido dentro de un coco fresco, \u00a0hay mucho para compartir y una vez usted haya terminado con el majarete &#8211; le recomendamos pedir que saquen la masa de la concha de el coco, estuvo muy delicioso!\n\n\u00ab<em>Un delicioso majarete cl\u00e1sico. Su sabor unico y textura te hace volver a una feliz\u00a0infancia \u00a0creciendo en la Rep\u00fablica Dominicana &#8211; incluso si creciste all\u00ed o no.<\/em>\u00bb &#8212;Philip Silvestri<\/blockquote>\n<blockquote><strong>Mamajuana (US$5.50)<\/strong>\n\nNinguna noche Dominicana puede llegar a su final sin un shot de mamajuana, una potente mezcla de ron, vino tinto y miel fermentada con trozos de madera y otras hierbas. Aunque fue un poco fuerte al principio, notamos que despues de uno o dos empez\u00f3 a tener mejor sabor.<\/blockquote>\nUna super noche! Te recomendamos que tu, tu familia y amigos prueben el menu Dominicano de el Lago Grill &#8211; no te decepcionar\u00e1s. La comida es grandiosa y adem\u00e1s con precios razonables y una atm\u00f3sfera casual, es una gran opci\u00f3n para cuando quieras estar tranquilo.\n\nHaz click en las imagens de abajo para ver el menu completo:\u00a0<strong>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1652\" data-id=\"488438\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=800%2C1652&#038;ssl=1\" alt=\"\" class=\"wp-image-488438\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=145%2C300&amp;ssl=1 145w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=496%2C1024&amp;ssl=1 496w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=768%2C1586&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=744%2C1536&amp;ssl=1 744w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=400%2C826&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=706%2C1458&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?resize=150%2C310&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-1.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1142\" data-id=\"488444\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=800%2C1142&#038;ssl=1\" alt=\"\" class=\"wp-image-488444\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=210%2C300&amp;ssl=1 210w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=717%2C1024&amp;ssl=1 717w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=768%2C1096&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=400%2C571&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=706%2C1008&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?resize=150%2C214&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill-6.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1652\" data-id=\"488450\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=800%2C1652&#038;ssl=1\" alt=\"\" class=\"wp-image-488450\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=145%2C300&amp;ssl=1 145w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=496%2C1024&amp;ssl=1 496w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=768%2C1586&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=744%2C1536&amp;ssl=1 744w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=400%2C826&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=706%2C1458&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?resize=150%2C310&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill2-2.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1142\" data-id=\"488456\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=800%2C1142&#038;ssl=1\" alt=\"\" class=\"wp-image-488456\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=210%2C300&amp;ssl=1 210w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=717%2C1024&amp;ssl=1 717w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=768%2C1096&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=400%2C571&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=706%2C1008&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?resize=150%2C214&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill3-2.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1142\" data-id=\"488462\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=800%2C1142&#038;ssl=1\" alt=\"\" class=\"wp-image-488462\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=210%2C300&amp;ssl=1 210w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=717%2C1024&amp;ssl=1 717w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=768%2C1096&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=400%2C571&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=706%2C1008&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?resize=150%2C214&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago-grill4.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n<\/strong>\n<blockquote><strong>SPECIALES para los Due\u00f1os de Villa de Casa de Campo!<\/strong>\n\nSi eres un due\u00f1o de villa de Casa de Campo recibibes un 15% de descuento en todos los restaurantes de Casa de Campo y \u00a0todos los jueves en el Lago Grill, los due\u00f1os de villa reciben otro especial de 2&#215;1 en c\u00f3cteles de \u00abrum punch\u00bb!\n\nRecuerda mostrar tu pase de due\u00f1o de villa de Casa de Campo para aprovechar estas ofertas!<\/blockquote>\nNota: Estos precios no incluyen impuestos.","protected":false},"excerpt":{"rendered":"<p>Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes &#8211; realizando Noches Dominicanas! El pasado viernes nosotros (Casa de Campo Living) junto con otros \u00abcatadores\u00bb\u00a0probamos para un resumen &#8211; y descubrimos una grandiosa comida, buenos precios y la pasamos de maravilla!<\/p>\n","protected":false},"author":388,"featured_media":243315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[26936,26952,2521,14629,2526,14631,14625,26822,14627],"tags":[23815,3626,5738,5739,1110],"newspack_spnsrs_tax":[],"class_list":["post-340309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-de-campo-living-es","category-ccl-recomienda","category-republica-dominicana-2","category-comidas-bebidas","category-titulares-es","category-estilo-de-vida","category-noticias-locales","category-resort-casa-de-campo","category-proximamente","tag-casa-de-campo-es-17","tag-casa-de-campo-es","tag-comida-dominicana","tag-lago-grill-es","tag-noche-dominicana","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-13T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:34:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lperdomo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lperdomo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\"},\"author\":{\"name\":\"lperdomo\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/4505bf6f082fd862dd65dffed828158b\"},\"headline\":\"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill\",\"datePublished\":\"2012-12-13T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:34:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\"},\"wordCount\":1261,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?fit=650%2C520&ssl=1\",\"keywords\":[\"Casa de Campo\",\"casa de campo @es\",\"comida dominicana\",\"lago grill @es\",\"noche dominicana\"],\"articleSection\":[\"Casa de Campo Living @es\",\"CCL recomienda\",\"Rep\u00fablica Dominicana @es\",\"Comidas &amp; Bebidas\",\"Titulares\",\"Estilo de Vida\",\"Noticias Locales\",\"Resort Casa de Campo\",\"Proximamente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\",\"name\":\"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?fit=650%2C520&ssl=1\",\"datePublished\":\"2012-12-13T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:34:34+00:00\",\"description\":\"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?fit=650%2C520&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?fit=650%2C520&ssl=1\",\"width\":650,\"height\":520,\"caption\":\"rum punch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/4505bf6f082fd862dd65dffed828158b\",\"name\":\"lperdomo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g\",\"caption\":\"lperdomo\"},\"sameAs\":[\"http:\\\/\\\/www.silgon.net\"],\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/lperdomo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living","description":"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","og_locale":"es_ES","og_type":"article","og_title":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living","og_description":"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El","og_url":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2012-12-13T04:00:00+00:00","article_modified_time":"2022-11-10T14:34:34+00:00","og_image":[{"width":650,"height":520,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","type":"image\/jpeg"}],"author":"lperdomo","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"lperdomo","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/"},"author":{"name":"lperdomo","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/4505bf6f082fd862dd65dffed828158b"},"headline":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill","datePublished":"2012-12-13T04:00:00+00:00","dateModified":"2022-11-10T14:34:34+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/"},"wordCount":1261,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","keywords":["Casa de Campo","casa de campo @es","comida dominicana","lago grill @es","noche dominicana"],"articleSection":["Casa de Campo Living @es","CCL recomienda","Rep\u00fablica Dominicana @es","Comidas &amp; Bebidas","Titulares","Estilo de Vida","Noticias Locales","Resort Casa de Campo","Proximamente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","url":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","name":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","datePublished":"2012-12-13T04:00:00+00:00","dateModified":"2022-11-10T14:34:34+00:00","description":"Lago Grill de Casa de Campo, m\u00e1s conocido por su legendario buffet de desayunos, esta ahora abierto todas las tardes - realizando Noches Dominicanas! El","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","width":650,"height":520,"caption":"rum punch"},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/4505bf6f082fd862dd65dffed828158b","name":"lperdomo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f4e35901d52b8d648d82e11c9c54217bc500bbf5793d4f5e15d23fd2d5a1af4?s=96&d=mm&r=g","caption":"lperdomo"},"sameAs":["http:\/\/www.silgon.net"],"url":"https:\/\/casadecampoliving.com\/es\/author\/lperdomo\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill","url":"http:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1"},"articleSection":"CCL recomienda","author":[{"@type":"Person","name":"lperdomo"}],"creator":["lperdomo"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["casa de campo","casa de campo @es","comida dominicana","lago grill @es","noche dominicana"],"dateCreated":"2012-12-13T04:00:00Z","datePublished":"2012-12-13T04:00:00Z","dateModified":"2022-11-10T14:34:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Review de Casa de Campo Living: Noches Dominicanas en el Lago Grill\",\"url\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/casadecampoliving.com\\\/es\\\/review-de-casa-de-campo-living-noches-dominicanas-en-el-lago-grill\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?resize=150%2C150&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/rum_punch-1.jpg?fit=650%2C520&ssl=1\"},\"articleSection\":\"CCL recomienda\",\"author\":[{\"@type\":\"Person\",\"name\":\"lperdomo\"}],\"creator\":[\"lperdomo\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Casa de Campo Living\",\"logo\":\"https:\\\/\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png\"},\"keywords\":[\"casa de campo\",\"casa de campo @es\",\"comida dominicana\",\"lago grill @es\",\"noche dominicana\"],\"dateCreated\":\"2012-12-13T04:00:00Z\",\"datePublished\":\"2012-12-13T04:00:00Z\",\"dateModified\":\"2022-11-10T14:34:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch-1.jpg?fit=650%2C520&ssl=1","jetpack-related-posts":[{"id":433460,"url":"https:\/\/casadecampoliving.com\/es\/no-se-pierdan-el-increible-tributo-a-frank-sinatra-para-celebrar-el-40-aniversario-del-anfiteatro-altos-de-chavon\/","url_meta":{"origin":340309,"position":0},"title":"No se pierdan el incre\u00edble tributo a Frank Sinatra para celebrar el 40 aniversario del\u00a0Anfiteatro Altos de Chav\u00f3n","author":"Casa de Campo Living","date":"20 Oct, 2022","format":false,"excerpt":"Siendo uno de los escenarios m\u00e1s emblem\u00e1ticos del pa\u00eds, Casa de Campo Resort\u00ae & Villas celebra las cuatro d\u00e9cadas de aniversario de Altos de Chav\u00f3n con un tributo al gran Frank Sinatra, protagonizado por artistas invitados y una big band tal cual la que acompa\u00f1\u00f3 al artista hace 40 a\u00f1os\u2026","rel":"","context":"En \u00abUncategorized @es\u00bb","block_context":{"text":"Uncategorized @es","link":"https:\/\/casadecampoliving.com\/es\/category\/uncategorized-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Tributo-Frank-Sinatra-Foto-Principal-Amaury-Sanchez-Danilo-Ginebra-Andres-Pichardo-y-Jose-Gabriel-Perez-.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":343236,"url":"https:\/\/casadecampoliving.com\/es\/la-comida-dominicana-regresa-lago-grill\/","url_meta":{"origin":340309,"position":1},"title":"La comida dominicana regresa a Lago Grill","author":"Genesis Perdomo","date":"11 Nov, 2013","format":false,"excerpt":"\u00a1Muy buenas noticias para todos esos amantes de la comida! el delicioso men\u00fa Dominicano regresa a Lago Grill en Casa de Campo. Empezando desde el Jueves 20 de noviembre, el tan adorado men\u00fa servido en la pasada temporada en el Lago Grill ha sido reincorporado y ser\u00e1 servido cada noche.\u2026","rel":"","context":"En \u00abComidas &amp; Bebidas\u00bb","block_context":{"text":"Comidas &amp; Bebidas","link":"https:\/\/casadecampoliving.com\/es\/category\/comidas-bebidas\/"},"img":{"alt_text":"Chivo Dominicano","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/chivo_dominicano-1.jpg?fit=650%2C449&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/chivo_dominicano-1.jpg?fit=650%2C449&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/chivo_dominicano-1.jpg?fit=650%2C449&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":340398,"url":"https:\/\/casadecampoliving.com\/es\/menu-de-ano-nuevo-en-el-lago-grill-ideal-para-las-familias-solo-us40-para-adultos-y-us30-para-ninos\/","url_meta":{"origin":340309,"position":2},"title":"Men\u00fa de A\u00f1o Nuevo en el Lago Grill &#8211; ideal para las familias, s\u00f3lo US$40 para adultos y US$30 para ni\u00f1os!","author":"lperdomo","date":"24 Dic, 2012","format":false,"excerpt":"Este fin de a\u00f1o Casa de Campo tiene la opci\u00f3n perfecta para la familia \u2013 un buffet en el Lago Grill el cual estar\u00e1 abierto desde las 6pm. Con m\u00fasica t\u00edpica folkl\u00f3rica Dominicana \u2013 con una banda de Perico Ripiao en vivo, el Lago Grill ser\u00e1 un lugar perfecto para\u2026","rel":"","context":"En \u00abComidas &amp; Bebidas\u00bb","block_context":{"text":"Comidas &amp; Bebidas","link":"https:\/\/casadecampoliving.com\/es\/category\/comidas-bebidas\/"},"img":{"alt_text":"rum punch","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch1-1.jpg?fit=650%2C420&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch1-1.jpg?fit=650%2C420&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/rum_punch1-1.jpg?fit=650%2C420&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":340642,"url":"https:\/\/casadecampoliving.com\/es\/casa-de-campo-abre-un-nuevo-mercado-artesanal-en-el-lago-grill-cada-viernes\/","url_meta":{"origin":340309,"position":3},"title":"Casa de Campo abre un nuevo \u00abMercado Artesanal\u00bb en el Lago Grill &#8211; cada viernes!","author":"","date":"14 Feb, 2013","format":false,"excerpt":"Cada viernes,d esde las 6am hasta las 3pm, Casa de Campo tendr\u00e1 un \u201cMercado Artesanal\u201d, en el Lago Grill, ofreciendo a turistas y due\u00f1os de villas en Casa de Campo, la oportunidad de comprar algunos souvenirs genuinos dominicanos. El grupo de 6 a 8 artesanos, en su mayor\u00eda son procedentes\u2026","rel":"","context":"En \u00abNoticias Locales\u00bb","block_context":{"text":"Noticias Locales","link":"https:\/\/casadecampoliving.com\/es\/category\/noticias-locales\/"},"img":{"alt_text":"mercado artesanal","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/web-mercado-artesanal-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/web-mercado-artesanal-1.jpg?fit=650%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/web-mercado-artesanal-1.jpg?fit=650%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":340400,"url":"https:\/\/casadecampoliving.com\/es\/menus-de-ano-nuevo-en-el-lago-grill-beach-club-la-casita-la-cana-chinois-y-la-piazzetta\/","url_meta":{"origin":340309,"position":4},"title":"Men\u00fas de A\u00f1o Nuevo en el Lago Grill, Beach Club, La Casita, La Ca\u00f1a, Chinois y La Piazzetta!","author":"lperdomo","date":"26 Dic, 2012","format":false,"excerpt":"Es casi el tiempo de darle la bienvenida al A\u00f1o Nuevo \u2013 2013, y si estar\u00e1s celebrando en Casa de Campo les recomendamos que realices r\u00e1pido sus reservaciones para evitar inconvenientes! Este a\u00f1o los restaurantes de Casa de Campo; La Piazzeta en Altos de Chav\u00f3n, La Ca\u00f1a en el Hotel\u2026","rel":"","context":"En \u00abComidas &amp; Bebidas\u00bb","block_context":{"text":"Comidas &amp; Bebidas","link":"https:\/\/casadecampoliving.com\/es\/category\/comidas-bebidas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lamb-1.jpg?fit=620%2C465&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lamb-1.jpg?fit=620%2C465&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lamb-1.jpg?fit=620%2C465&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":341507,"url":"https:\/\/casadecampoliving.com\/es\/buffet-especial-en-las-noches-dominicanas-del-restaurante-lago-grill-por-solo-us28\/","url_meta":{"origin":340309,"position":5},"title":"Buffet especial en las \u00abNoches Dominicanas\u00bb del restaurante Lago Grill, por solo US$28","author":"Mairobi Herrera","date":"23 May, 2013","format":false,"excerpt":"\u00a1Las noches del pr\u00f3ximo jueves 30 de mayo y del s\u00e1bado 15 de junio ser\u00e1n dominicanas! El resturante Lago Grill complacer\u00e1 a los due\u00f1os de villas e invitados con un buffet especial preparado solo con comidas tradicionales de la cultura dominicana. El Lago Grill tiene todo un ambiente preparado para\u2026","rel":"","context":"En \u00abComidas &amp; Bebidas\u00bb","block_context":{"text":"Comidas &amp; Bebidas","link":"https:\/\/casadecampoliving.com\/es\/category\/comidas-bebidas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago_gril_dominican_nights.jpg?fit=650%2C587&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago_gril_dominican_nights.jpg?fit=650%2C587&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/lago_gril_dominican_nights.jpg?fit=650%2C587&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/340309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/388"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=340309"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/340309\/revisions"}],"predecessor-version":[{"id":507532,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/340309\/revisions\/507532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/243315"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=340309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=340309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=340309"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=340309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}