{"id":338085,"date":"2011-02-26T00:00:00","date_gmt":"2011-02-26T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/"},"modified":"2022-11-10T10:31:10","modified_gmt":"2022-11-10T14:31:10","slug":"fin-de-semana-del-hogar-del-nino-el-torneo-de-polo","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","title":{"rendered":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo"},"content":{"rendered":"<a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogardelnino_polo_casadecampo1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-26004\" title=\"hogardelnino_polo_casadecampo\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogardelnino_polo_casadecampo1.jpg?resize=565%2C318&#038;ssl=1\" alt=\"\" width=\"565\" height=\"318\" \/><\/a>\n\nEl pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0<!--more-->\n\n<a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-25920\" style=\"margin-left: 15px; margin-right: 15px;\" title=\"casadecampo_polo_\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_.jpg?resize=200%2C204&#038;ssl=1\" alt=\"\" width=\"200\" height=\"204\" \/><\/a>El viernes 18 de febrero, los jugadores del torneo de polo del Hogar del Ni\u00f1o, despertaron con una emoci\u00f3n incre\u00edble, anticipando lo que ser\u00eda la final del torneo. No obstante, la lluvia hizo que tanto los jugadores como espectadores esperaran varias horas de retraso para dar inicio a la actividad.\n\nA continuaci\u00f3n podr\u00e1 disfrutar de una selecci\u00f3n de fotograf\u00edas tomadas durante la \u00a0ceremonia de premiaci\u00f3n dirigida por Calixto Garc\u00eda-Velez:\n\n<strong>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"536\" data-id=\"376224\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=800%2C536&#038;ssl=1\" alt=\"\" class=\"wp-image-376224\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=768%2C515&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=400%2C268&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=706%2C473&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?resize=150%2C101&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1090997.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"376226\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-376226\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100002.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1179\" data-id=\"376228\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=800%2C1179&#038;ssl=1\" alt=\"\" class=\"wp-image-376228\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=204%2C300&amp;ssl=1 204w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=695%2C1024&amp;ssl=1 695w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=768%2C1132&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=400%2C590&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=706%2C1040&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?resize=150%2C221&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100015.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"376230\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-376230\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100016.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"426\" data-id=\"376232\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=800%2C426&#038;ssl=1\" alt=\"\" class=\"wp-image-376232\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=300%2C160&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=768%2C409&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=400%2C213&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=706%2C376&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?resize=150%2C80&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100033.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n<\/strong>\n<p style=\"text-align: center;\"><strong>El equipo del Central Romana recibe trofeos como campeones del torneo del Hogar del Ni\u00f1o!<\/strong><a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_1.jpg?ssl=1\">\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-25922\" title=\"casadecampo_polo_\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_1.jpg?resize=565%2C289&#038;ssl=1\" alt=\"\" width=\"565\" height=\"289\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><strong>[nggallery id=718]<\/strong><\/p>\n\n<blockquote>&nbsp;<\/blockquote>\n<p style=\"text-align: center;\"><\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0<\/p>\n","protected":false},"author":21,"featured_media":232955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2498,14627],"tags":[4484,3521],"newspack_spnsrs_tax":[],"class_list":["post-338085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-es","category-proximamente","tag-el-hogar-del-nino","tag-fin-de-semana-del-hogar-del-nino","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-26T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/7e3b975d584a5f6ac0fd7128a81b0bc5\"},\"headline\":\"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo\",\"datePublished\":\"2011-02-26T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1\",\"keywords\":[\"el hogar del nino\",\"fin de semana del hogar del nino\"],\"articleSection\":[\"Uncategorized @es\",\"Proximamente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/\",\"name\":\"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1\",\"datePublished\":\"2011-02-26T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:31:10+00:00\",\"description\":\"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1\",\"width\":250,\"height\":255},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/7e3b975d584a5f6ac0fd7128a81b0bc5\",\"name\":\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/ \\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living","description":"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","og_locale":"es_ES","og_type":"article","og_title":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living","og_description":"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El","og_url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2011-02-26T04:00:00+00:00","article_modified_time":"2022-11-10T14:31:10+00:00","og_image":[{"width":250,"height":255,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/"},"author":{"name":"","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/7e3b975d584a5f6ac0fd7128a81b0bc5"},"headline":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo","datePublished":"2011-02-26T04:00:00+00:00","dateModified":"2022-11-10T14:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/"},"wordCount":137,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","keywords":["el hogar del nino","fin de semana del hogar del nino"],"articleSection":["Uncategorized @es","Proximamente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","name":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","datePublished":"2011-02-26T04:00:00+00:00","dateModified":"2022-11-10T14:31:10+00:00","description":"El pasado fin de semana, Casa de Campo celebr\u00f3 el evento ben\u00e9fico anual del Fin de Semana del Hogar del Ni\u00f1o, con una serie de actividades deportivas.\u00a0 El","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","width":250,"height":255},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/7e3b975d584a5f6ac0fd7128a81b0bc5","name":"","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g"},"url":"https:\/\/casadecampoliving.com\/es\/author\/ \/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo","url":"http:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1"},"articleSection":"Uncategorized @es","author":[{"@type":"Person","name":"FB_515917546"}],"creator":["FB_515917546"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["el hogar del nino","fin de semana del hogar del nino"],"dateCreated":"2011-02-26T04:00:00Z","datePublished":"2011-02-26T04:00:00Z","dateModified":"2022-11-10T14:31:10Z"},"rendered":"<meta name=\"parsely-title\" content=\"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Polo\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-polo\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2011-02-26T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Uncategorized @es\" \/>\n<meta name=\"parsely-tags\" content=\"el hogar del nino,fin de semana del hogar del nino\" \/>\n<meta name=\"parsely-author\" content=\"FB_515917546\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":338314,"url":"https:\/\/casadecampoliving.com\/es\/el-torneo-de-polo-del-hogar-del-nino-se-realizara-del-8-al-17-febrero\/","url_meta":{"origin":338085,"position":0},"title":"El Torneo de Polo del Hogar del Ni\u00f1o se realizar\u00e1 del 8 al 17 febrero!","author":"","date":"8 Feb, 2012","format":false,"excerpt":"Hoy, mi\u00e9rcoles 8 de febrero, el torneo de polo del Hogar del Ni\u00f1o, parte del XV Fin de Semana Ben\u00e9fico, dar\u00e1 comienzo al primer round del torneo en los campos de polo de Casa de Campo a las 4pm. El fin de semana ben\u00e9fico que cada a\u00f1o realiza el Hogar\u2026","rel":"","context":"En \u00abSports\u00bb","block_context":{"text":"Sports","link":"https:\/\/casadecampoliving.com\/category\/sports\/"},"img":{"alt_text":"torneo polo casa de campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/toreno_polo-1.jpg?fit=650%2C361&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/toreno_polo-1.jpg?fit=650%2C361&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/toreno_polo-1.jpg?fit=650%2C361&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":338077,"url":"https:\/\/casadecampoliving.com\/es\/recordando-el-fin-de-semana-del-hogar-del-nino-2011\/","url_meta":{"origin":338085,"position":1},"title":"Recordando el Fin de Semana del Hogar del Ni\u00f1o 2011!","author":"","date":"12 Ene, 2012","format":false,"excerpt":"El viernes 18 y s\u00e1bado 19 de febrero de 2011, el Hogar del Ni\u00f1o y la comunidad de Casa de Campo se unieron en la celebraci\u00f3n de un exitoso Fin de Semana Anual del Hogar del Ni\u00f1o, evento en el que se desarrollan una serie de actividades deportivas; golf, tenis,\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogardelnino_casadecampo1-1.jpg?fit=565%2C318&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogardelnino_casadecampo1-1.jpg?fit=565%2C318&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogardelnino_casadecampo1-1.jpg?fit=565%2C318&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":340668,"url":"https:\/\/casadecampoliving.com\/es\/y-el-ganador-de-la-copa-hogar-del-nino-es-pitirri\/","url_meta":{"origin":338085,"position":2},"title":"Y el ganador de la Copa Hogar del Ni\u00f1o es&#8230; Pitirri!","author":"Maria Batlle","date":"21 Feb, 2013","format":false,"excerpt":"El pasado viernes 15 de febrero de 2013, el fin de semana del Hogar del Ni\u00f1o empez\u00f3 con mucho entusiasmo\u00a0en el tour del centro educativo en La Romana, el Homes and Gardens Tour y\u2026 el final del torneo de polo. Despu\u00e9s de una batalla de polo excelente y bien jugada,\u2026","rel":"","context":"En \u00abDeportes\u00bb","block_context":{"text":"Deportes","link":"https:\/\/casadecampoliving.com\/es\/category\/golf-deportes-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Screen-Shot-2013-02-20-at-10.50.50-AM1.png?fit=811%2C608&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Screen-Shot-2013-02-20-at-10.50.50-AM1.png?fit=811%2C608&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Screen-Shot-2013-02-20-at-10.50.50-AM1.png?fit=811%2C608&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Screen-Shot-2013-02-20-at-10.50.50-AM1.png?fit=811%2C608&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":338089,"url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-el-torneo-de-golf\/","url_meta":{"origin":338085,"position":3},"title":"Fin de Semana del Hogar del Ni\u00f1o: El Torneo de Golf","author":"","date":"25 Feb, 2011","format":false,"excerpt":"A pesar de la lluvia de \"buena suerte\", el s\u00e1bado 19 de febrero fue una ocasi\u00f3n perfecta para disfrutar del golf, con m\u00e1s de 100 jugadores que participaron el el Torneo de Golf del Hogar del Ni\u00f1o en el Country Club de La Romana. Los resultados del torneo de golf\u2026","rel":"","context":"En \u00abUpcoming\u00bb","block_context":{"text":"Upcoming","link":"https:\/\/casadecampoliving.com\/category\/upcoming\/"},"img":{"alt_text":"p1100100","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100100.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100100.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100100.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/p1100100.jpg?resize=700%2C400 2x"},"classes":[]},{"id":346781,"url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-increible-video-aereo-2\/","url_meta":{"origin":338085,"position":4},"title":"Fin de Semana del Hogar del Ni\u00f1o &#8211; incre\u00edble v\u00eddeo a\u00e9reo","author":"Rebecca Silvestri","date":"21 Feb, 2015","format":false,"excerpt":"\u00a1Hola, amigos! Aunque ya publicamos nuestra cobertura general del Fin de Semana del Hogar del Ni\u00f1o (click aqu\u00ed), como tambi\u00e9 muchas fotos y los resultados del torneo de golf (click aqu\u00ed), acabamos de encontrar este incre\u00edble v\u00eddeo a\u00e9reo del evento \u2013\u00a0\u00a1Y\u00a0no pudimos resistirnos a compartirlo con ustedes! El v\u00eddeo de\u2026","rel":"","context":"En \u00abEvents and Activities\u00bb","block_context":{"text":"Events and Activities","link":"https:\/\/casadecampoliving.com\/category\/events-and-activities\/"},"img":{"alt_text":"Casa de Campo aerial","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_aerial1.jpg?fit=650%2C322&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_aerial1.jpg?fit=650%2C322&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/Casa_de_Campo_aerial1.jpg?fit=650%2C322&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":346661,"url":"https:\/\/casadecampoliving.com\/es\/fin-de-semana-del-hogar-del-nino-inicia-con-la-copa-de-polo\/","url_meta":{"origin":338085,"position":5},"title":"\u00a1Fin de semana del Hogar del Ni\u00f1o inicia con la copa de polo!","author":"Perkin Agramonte","date":"3 Feb, 2015","format":false,"excerpt":"El 13 y 14 de febrero, el Hogar del Ni\u00f1o junto a la comunidad de Casa de Campo celebrar\u00e1 su 18vo fin de semana anual de recaudaci\u00f3n de fondos del Hogar del Ni\u00f1o y ma\u00f1ana, mi\u00e9rcoles 4 de febrero, las celebraciones comienzan temprano con el partido inaugural de la Copa\u2026","rel":"","context":"En \u00abCasa de Campo Living @es\u00bb","block_context":{"text":"Casa de Campo Living @es","link":"https:\/\/casadecampoliving.com\/category\/casa-de-campo-living-es\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_polo-5.jpg?fit=650%2C300&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_polo-5.jpg?fit=650%2C300&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casa_de_campo_polo-5.jpg?fit=650%2C300&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/casadecampo_polo_-1.jpg?fit=250%2C255&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/338085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=338085"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/338085\/revisions"}],"predecessor-version":[{"id":506778,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/338085\/revisions\/506778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/232955"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=338085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=338085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=338085"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=338085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}