{"id":337594,"date":"2011-12-02T00:00:00","date_gmt":"2011-12-02T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/"},"modified":"2022-11-10T10:45:01","modified_gmt":"2022-11-10T14:45:01","slug":"al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","title":{"rendered":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!"},"content":{"rendered":"<a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-73032 aligncenter\" title=\"jpg\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1.jpg?resize=632%2C305&#038;ssl=1\" alt=\"\" width=\"632\" height=\"305\" \/><\/a>\n\nEl pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que se unieron a la divertida actividad de \u00abZumbathon\u00bb por una buena causa!<!--more-->El s\u00e1bado fue un d\u00eda repleto de diversi\u00f3n para los visitantes y residentes de Casa de Campo, ya que pudieron de disfrutar de dos eventos; el <a href=\"https:\/\/casadecampoliving.com\/es\/2011\/11\/%C2%A1casa-de-campo-celebra-el-joli-day-beach-2011\/\">Joli-Day Beach<\/a> en Playa Minitas y el Zumbathon ben\u00e9fico en La Marina de Casa de Campo!\n\n<a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_marina_casa_de_campo.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-39294\" title=\"zumbathon_marina_casa_de_campo\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_marina_casa_de_campo.jpg?resize=650%2C330&#038;ssl=1\" alt=\"zumbathon marina casa de campo\" width=\"650\" height=\"330\" \/><\/a>\n\nEl Zumbathon logr\u00f3 su cometido y fue todo un \u00e9xito! Y es que con el recibimiento de 200 nobles integrantes, el Patronato Ben\u00e9fico Oriental, instituci\u00f3n organizadora de este vento, logr\u00f3 recaudar fondos para el Hogar del Ni\u00f1o.\n\n<a href=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_marina_casa_de_campo1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-39295\" title=\"zumbathon_marina_casa_de_campo\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_marina_casa_de_campo1.jpg?resize=650%2C397&#038;ssl=1\" alt=\"zumbathon marina casa de campo\" width=\"650\" height=\"397\" \/><\/a>\n\nEl reloj marcaba las 4:30 de la tarde cuando los siete instructores,\u00a0nacionales e internacionales como Fefi Salvaterra (quien tuvo la iniciativa de hacer el Zumbathon), Mar\u00eda Alicia Piantini, Dafne De Frias, Siria Mieses, Carlos Torres y Betsy Dopico quien vino desde Miami para ser parte de la actividad, dieron inicio al Zumbathon que se llev\u00f3 a cabo hasta un poco m\u00e1s de las 7:30 de la noche en La Marina de Casa de Campo!\n\nExcelente noticia! Felicidades a todos los que participaron por esta noble causa!\n\n<strong>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387640\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387640\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/308987_10150382564666975_662691974_8606697_366554770_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387642\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387642\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/310551_10150382682066975_662691974_8606928_2033199619_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387644\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387644\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/312999_10150382561476975_662691974_8606674_1604281802_n-1.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387646\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387646\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/313672_10150382561696975_662691974_8606680_546219605_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387648\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387648\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/377092_10150382609721975_662691974_8606796_98514553_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387650\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387650\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/379384_10150382681531975_662691974_8606925_44656350_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387652\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387652\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380823_10150382561736975_662691974_8606682_183473769_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387654\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387654\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/380860_10150382587361975_662691974_8606742_247275910_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387656\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387656\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/385783_10150382577656975_662691974_8606725_1847099929_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387658\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387658\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387011_10150382554176975_662691974_8606579_2017195400_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387660\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387660\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/387696_10150382609481975_662691974_8606791_1202544154_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387662\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387662\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388648_10150382591706975_662691974_8606763_225346328_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387664\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387664\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388753_10150382553861975_662691974_8606574_381589115_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387666\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387666\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/388812_10150382674266975_662691974_8606918_1869916705_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387668\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387668\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390620_10150382564576975_662691974_8606695_1252018133_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"387670\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-387670\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/390789_10150382560981975_662691974_8606663_677526659_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387672\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387672\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/391134_10150382561366975_662691974_8606671_83099549_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"406\" data-id=\"387674\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=800%2C406&#038;ssl=1\" alt=\"\" class=\"wp-image-387674\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=300%2C152&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=768%2C390&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=400%2C203&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=706%2C358&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?resize=150%2C76&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392278_10150382564776975_662691974_8606699_945684905_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"387676\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=720%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-387676\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=706%2C941&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?resize=640%2C853&amp;ssl=1 640w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392791_10150382272826975_662691974_8605275_1700457579_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"354\" data-id=\"387678\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=800%2C354&#038;ssl=1\" alt=\"\" class=\"wp-image-387678\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=300%2C133&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=768%2C340&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=400%2C177&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=706%2C312&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?resize=150%2C66&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/392823_10150382644536975_662691974_8606832_1742174478_n.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n<\/strong>\n\n<a href=\"https:\/\/casadecampoliving.com\/es\/2011\/11\/%C2%A1casa-de-campo-celebra-el-joli-day-beach-2011\/\">Para enterarse de todo lo ocurrido durante el s\u00e1bado 26 de noviembre, haga click aqu\u00ed!\u00a0<\/a>","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que se unieron a la divertida actividad de \u00abZumbathon\u00bb por una buena causa!<\/p>\n","protected":false},"author":21,"featured_media":224730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[2522,2526,2516,26581,14625,2514,14627],"tags":[23828],"newspack_spnsrs_tax":[],"class_list":["post-337594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-es","category-titulares-es","category-hogar-del-nino-es","category-la-marina-casa-de-campo","category-noticias-locales","category-fundaciones-es","category-proximamente","tag-patronato-benefico-oriental-es-2","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-02T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:45:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"305\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/7e3b975d584a5f6ac0fd7128a81b0bc5\"},\"headline\":\"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!\",\"datePublished\":\"2011-12-02T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:45:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jpg1-1.jpg?fit=632%2C305&ssl=1\",\"keywords\":[\"patronato ben\u00e9fico oriental\"],\"articleSection\":[\"Eventos\",\"Titulares\",\"Hogar del Ni\u00f1o @es\",\"La Marina Casa de Campo\",\"Noticias Locales\",\"Fundaciones\",\"Proximamente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/\",\"name\":\"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jpg1-1.jpg?fit=632%2C305&ssl=1\",\"datePublished\":\"2011-12-02T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:45:01+00:00\",\"description\":\"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jpg1-1.jpg?fit=632%2C305&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jpg1-1.jpg?fit=632%2C305&ssl=1\",\"width\":632,\"height\":305},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/7e3b975d584a5f6ac0fd7128a81b0bc5\",\"name\":\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/ \\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living","description":"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","og_locale":"es_ES","og_type":"article","og_title":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living","og_description":"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que","og_url":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2011-12-02T04:00:00+00:00","article_modified_time":"2022-11-10T14:45:01+00:00","og_image":[{"width":632,"height":305,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/"},"author":{"name":"","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/7e3b975d584a5f6ac0fd7128a81b0bc5"},"headline":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!","datePublished":"2011-12-02T04:00:00+00:00","dateModified":"2022-11-10T14:45:01+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/"},"wordCount":246,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","keywords":["patronato ben\u00e9fico oriental"],"articleSection":["Eventos","Titulares","Hogar del Ni\u00f1o @es","La Marina Casa de Campo","Noticias Locales","Fundaciones","Proximamente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","url":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","name":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o! | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","datePublished":"2011-12-02T04:00:00+00:00","dateModified":"2022-11-10T14:45:01+00:00","description":"El pasado s\u00e1bado 26 de noviembre, el Paseo del Mar de La Marina Casa de Campo vibr\u00f3 ante la asistencia de 200 residentes y visitantes de Casa de Campo que","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","width":632,"height":305},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/7e3b975d584a5f6ac0fd7128a81b0bc5","name":"","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g"},"url":"https:\/\/casadecampoliving.com\/es\/author\/ \/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!","url":"http:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1"},"articleSection":"Eventos","author":[{"@type":"Person","name":"FB_515917546"}],"creator":["FB_515917546"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["patronato ben\u00e9fico oriental"],"dateCreated":"2011-12-02T04:00:00Z","datePublished":"2011-12-02T04:00:00Z","dateModified":"2022-11-10T14:45:01Z"},"rendered":"<meta name=\"parsely-title\" content=\"Al ritmo de Zumba, las mujeres de Casa de Campo recaudan fondos para el Hogar del Ni\u00f1o!\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/al-ritmo-de-zumba-las-mujeres-de-casa-de-campo-recaudan-fondos-para-el-hogar-del-nino\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2011-12-02T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Eventos\" \/>\n<meta name=\"parsely-tags\" content=\"patronato ben\u00e9fico oriental\" \/>\n<meta name=\"parsely-author\" content=\"FB_515917546\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":320761,"url":"https:\/\/casadecampoliving.com\/shake-it-ladies-zumbathon-in-the-marina-casa-de-campo-raises-money-for-the-hogar-del-nino\/","url_meta":{"origin":337594,"position":0},"title":"Shake it ladies! Zumbathon in the Marina Casa de Campo raises money for the Hogar del Ni\u00f1o!","author":"Rebecca Silvestri","date":"2 Dic, 2011","format":false,"excerpt":"Last Saturday the 26th of November, Casa de Campo's female villa owners and visitors came together to raise money for the Hogar del Ni\u00f1o - dancing the night away at the Zumbathon Charity event held on the Paseo del Mar in the Marina Casa de Campo.\u00a0 Casa de Campo villa\u2026","rel":"","context":"En \u00abEvents and Activities\u00bb","block_context":{"text":"Events and Activities","link":"https:\/\/casadecampoliving.com\/category\/events-and-activities\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":337394,"url":"https:\/\/casadecampoliving.com\/es\/26-de-noviembre-sabado-de-zumba-y-diversion-2\/","url_meta":{"origin":337594,"position":1},"title":"26 de noviembre: S\u00e1bado de Zumba y diversi\u00f3n!","author":"","date":"20 Nov, 2011","format":false,"excerpt":"\u00bfEst\u00e1n\u00a0listos para un fin de semana de baile y\u00a0diversi\u00f3n? Al igual que la segunda\u00a0edici\u00f3n\u00a0del evento anual de Joli-Day Beach 2011\u00a0que se realizar\u00e1 en la Playa Minitas, el\u00a0pr\u00f3ximo\u00a0s\u00e1bado\u00a026 de noviembre\u00a0tambi\u00e9n se llevar\u00e1 a cabo la actividad\u00a0ben\u00e9fica\u00a0\u201cZumbathon\u201d. El evento organizado por el Patronato Benefico Oriental, se llevara a cabo el sabado 26\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/casadecampoliving.com\/es\/category\/destacados\/"},"img":{"alt_text":"zumba casa de campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":338372,"url":"https:\/\/casadecampoliving.com\/es\/novedad-zumba-master-class-se-une-a-las-actividades-del-fin-de-semana-benefico-del-hogar-del-nino\/","url_meta":{"origin":337594,"position":2},"title":"NOVEDAD! \u00abZumba Master Class\u00bb se une a las actividades del Fin de Semana Ben\u00e9fico del Hogar del Ni\u00f1o!","author":"","date":"10 Feb, 2012","format":false,"excerpt":"Luego del gran \u00e9xito obtenido con la actividad ben\u00e9fica del \u201cZumbathon\u201d, realizado en noviembre por el Hogar del Ni\u00f1o en La Marina Casa de Campo, la clase \u201cZumba Master Class\u201d se ha agregado a la lista de eventos y actividades que se llevar\u00e1n a cabo durante el Fin de Semana\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/casadecampoliving.com\/es\/category\/destacados\/"},"img":{"alt_text":"zumbathon marina casa de campo","src":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2011\/12\/jpg","width":350,"height":200,"srcset":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2011\/12\/jpg 1x, https:\/\/casadecampoliving.com\/wp-content\/uploads\/2011\/12\/jpg 1.5x"},"classes":[]},{"id":320694,"url":"https:\/\/casadecampoliving.com\/saturday-26-perfect-day-for-some-fun-and-zumba\/","url_meta":{"origin":337594,"position":3},"title":"Zumbathon Charity Event by the Patronato Ben\u00e9fico Oriental: Saturday Nov. 26!","author":"","date":"20 Nov, 2011","format":false,"excerpt":"Are you ready for some high energy fun and dancing? Saturday the 26th of November is going to be a day filled with fun for Casa de Campo villa owners, visitors and guest of all ages \u2013 with the second annual \u201cJoli-Day Beach\u201d event taking place on Minitas beach from\u2026","rel":"","context":"En \u00abEvents and Activities\u00bb","block_context":{"text":"Events and Activities","link":"https:\/\/casadecampoliving.com\/category\/events-and-activities\/"},"img":{"alt_text":"zumba casa de campo","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumba_casa_de_campo-1.jpg?fit=600%2C424&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":338172,"url":"https:\/\/casadecampoliving.com\/es\/lo-mejor-del-2011-la-celebracion-de-un-ano-de-diversion-y-logros-en-el-hogar-del-nino\/","url_meta":{"origin":337594,"position":4},"title":"Lo mejor del 2011: La celebraci\u00f3n de un a\u00f1o de diversi\u00f3n y logros en el Hogar del Ni\u00f1o","author":"","date":"22 Ene, 2012","format":false,"excerpt":"Ya que comenzamos el nuevo a\u00f1o 2012, tom\u00e9monos un segundo para recordar todos los mejores momentos y logros del a\u00f1o 2011! Con la aproximaci\u00f3n del mayor esfuerzo que se realiza anualmente para la recaudaci\u00f3n de fondos (haga click para m\u00e1s detalles), aqu\u00ed les traemos algunas memorias de todos aquellos buenos\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/casadecampoliving.com\/es\/category\/destacados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/hogar_del_nino_la_romana_casa_de_campo6-1.jpg?fit=500%2C307&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":343785,"url":"https:\/\/casadecampoliving.com\/es\/el-hogar-del-nino-anuncia-zumbathon-con-claudine-nannini\/","url_meta":{"origin":337594,"position":5},"title":"El Hogar del Ni\u00f1o anuncia Zumbathon con Claudine Nannini","author":"Genesis Perdomo","date":"2 Feb, 2014","format":false,"excerpt":"Con el decimos\u00e9ptimo fin de semana anual de Hogar del Ni\u00f1o para recaudar fondos,\u00a0en pocas semana (febrero 14 & 15), ya se escuchan los detalles de los emocionantes eventos y actividades que har\u00e1n que la reuni\u00f3n de este a\u00f1o sea legendaria como es de esperarse. Fue anunciado que tendremos a\u2026","rel":"","context":"En \u00abAltos de Chavon @es\u00bb","block_context":{"text":"Altos de Chavon @es","link":"https:\/\/casadecampoliving.com\/category\/altos-de-chavon-es\/"},"img":{"alt_text":"Zumbathon Claudine Naninni","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_claudine_Naninni-1.jpg?fit=650%2C514&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_claudine_Naninni-1.jpg?fit=650%2C514&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/zumbathon_claudine_Naninni-1.jpg?fit=650%2C514&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/jpg1-1.jpg?fit=632%2C305&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/337594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=337594"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/337594\/revisions"}],"predecessor-version":[{"id":509874,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/337594\/revisions\/509874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/224730"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=337594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=337594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=337594"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=337594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}