{"id":318162,"date":"2009-12-26T00:00:00","date_gmt":"2009-12-26T04:00:00","guid":{"rendered":"https:\/\/casadecampoliving.com\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/"},"modified":"2022-11-10T10:38:52","modified_gmt":"2022-11-10T14:38:52","slug":"varelli-contemporary-art-gallery-celebrates-its-6th-anniversary","status":"publish","type":"post","link":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","title":{"rendered":"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!"},"content":{"rendered":"<p style=\"text-align: center;\"><a rel=\"attachment wp-att-10718\" href=\"https:\/\/casadecampoliving.com\/2009\/12\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/art-4\/\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-10718\" title=\"art\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-1024x640-2.jpg?resize=553%2C346&#038;ssl=1\" alt=\"art\" width=\"553\" height=\"346\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their 6th anniversary! <!--more--><\/p>\n<p style=\"text-align: left;\">The gallery in the Marina Casa de Campo celebrated this very special occasion with a Grey Goose bar, which served up a nice variety of vodka cocktails in rather nice cocktail glasses and some lovely wine. Throughout the evening the event was attended by a number of different Casa de Campo villa owners who stopped by for a cheeky drink and to admire the impressive art work on display.<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360526\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360526\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07983.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360528\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360528\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07985.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360530\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360530\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07986.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360532\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360532\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07987.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360534\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360534\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07988.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360536\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360536\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07990.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360538\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360538\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07992.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360540\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360540\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07993.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360542\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360542\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07995.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360544\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360544\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07996.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360546\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360546\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc07998.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360548\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360548\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08000.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360550\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360550\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08002.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360552\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360552\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08003.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360554\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360554\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08004.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360556\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360556\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08005.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360558\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360558\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08006.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360560\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360560\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08007.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360562\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360562\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08008.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360564\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360564\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08009.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360566\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360566\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08010.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360568\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360568\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08012.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360570\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360570\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08013.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360572\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360572\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08015.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360574\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360574\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08018.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360576\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360576\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08019.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360578\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360578\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08021.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360580\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360580\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08022.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" data-id=\"360582\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-360582\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?resize=400%2C533&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08025.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-id=\"360584\" src=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-360584\" srcset=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=706%2C530&amp;ssl=1 706w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/dsc08029.jpg?w=370&amp;ssl=1 370w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their 6th anniversary!<\/p>\n","protected":false},"author":31,"featured_media":215947,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[45,2501,2522,2524,14629,14631,14625,47,2530,14627],"tags":[13831,3573],"newspack_spnsrs_tax":[],"class_list":["post-318162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-and-culture","category-vida-nocturna-es","category-eventos-es","category-destacados","category-comidas-bebidas","category-estilo-de-vida","category-noticias-locales","category-marina-casa-de-campo","category-compras-es","category-proximamente","tag-art-gallery","tag-marina-casa-de-campo-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varelli Contemporary art gallery celebrates it&#039;s 6th Anniversary! | Casa de Campo Living<\/title>\n<meta name=\"description\" content=\"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varelli Contemporary art gallery celebrates it&#039;s 6th Anniversary! | Casa de Campo Living\" \/>\n<meta property=\"og:description\" content=\"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa de Campo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casadecampoliving\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-26T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:38:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rebecca Silvestri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:site\" content=\"@cdcliving\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rebecca Silvestri\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/\"},\"author\":{\"name\":\"Rebecca Silvestri\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/2b2208f3175fa8761e25b272e096d718\"},\"headline\":\"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!\",\"datePublished\":\"2009-12-26T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:38:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1\",\"keywords\":[\"art gallery\",\"Marina Casa de Campo @es\"],\"articleSection\":[\"Art and Culture\",\"Vida Nocturna\",\"Eventos\",\"Destacados\",\"Comidas &amp; Bebidas\",\"Estilo de Vida\",\"Noticias Locales\",\"Marina Casa de Campo\",\"Compras\",\"Proximamente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/\",\"name\":\"Varelli Contemporary art gallery celebrates it's 6th Anniversary! | Casa de Campo Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1\",\"datePublished\":\"2009-12-26T04:00:00+00:00\",\"dateModified\":\"2022-11-10T14:38:52+00:00\",\"description\":\"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1\",\"width\":2560,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"name\":\"Casa de Campo Living\",\"description\":\"Resort community news and resources.\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#organization\",\"name\":\"Casa de Campo Living\",\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/casadecampoliving.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1\",\"width\":800,\"height\":214,\"caption\":\"Casa de Campo Living\"},\"image\":{\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casadecampoliving\",\"https:\\\/\\\/x.com\\\/cdcliving\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/#\\\/schema\\\/person\\\/2b2208f3175fa8761e25b272e096d718\",\"name\":\"Rebecca Silvestri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g\",\"caption\":\"Rebecca Silvestri\"},\"url\":\"https:\\\/\\\/casadecampoliving.com\\\/es\\\/author\\\/madamehuge\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varelli Contemporary art gallery celebrates it's 6th Anniversary! | Casa de Campo Living","description":"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","og_locale":"es_ES","og_type":"article","og_title":"Varelli Contemporary art gallery celebrates it's 6th Anniversary! | Casa de Campo Living","og_description":"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their","og_url":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","og_site_name":"Casa de Campo Living","article_publisher":"https:\/\/www.facebook.com\/casadecampoliving","article_published_time":"2009-12-26T04:00:00+00:00","article_modified_time":"2022-11-10T14:38:52+00:00","og_image":[{"width":2560,"height":1600,"url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","type":"image\/jpeg"}],"author":"Rebecca Silvestri","twitter_card":"summary_large_image","twitter_creator":"@cdcliving","twitter_site":"@cdcliving","twitter_misc":{"Escrito por":"Rebecca Silvestri"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#article","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/"},"author":{"name":"Rebecca Silvestri","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/2b2208f3175fa8761e25b272e096d718"},"headline":"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!","datePublished":"2009-12-26T04:00:00+00:00","dateModified":"2022-11-10T14:38:52+00:00","mainEntityOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/"},"wordCount":105,"publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","keywords":["art gallery","Marina Casa de Campo @es"],"articleSection":["Art and Culture","Vida Nocturna","Eventos","Destacados","Comidas &amp; Bebidas","Estilo de Vida","Noticias Locales","Marina Casa de Campo","Compras","Proximamente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","url":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","name":"Varelli Contemporary art gallery celebrates it's 6th Anniversary! | Casa de Campo Living","isPartOf":{"@id":"https:\/\/casadecampoliving.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#primaryimage"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","datePublished":"2009-12-26T04:00:00+00:00","dateModified":"2022-11-10T14:38:52+00:00","description":"Last Saturday the 19th of December, Varelli contemporary art gallery invited Casa de Campo villa owners and hotel guests to join them in celebrating their","breadcrumb":{"@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#primaryimage","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","width":2560,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadecampoliving.com\/es\/"},{"@type":"ListItem","position":2,"name":"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!"}]},{"@type":"WebSite","@id":"https:\/\/casadecampoliving.com\/es\/#website","url":"https:\/\/casadecampoliving.com\/es\/","name":"Casa de Campo Living","description":"Resort community news and resources.","publisher":{"@id":"https:\/\/casadecampoliving.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadecampoliving.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casadecampoliving.com\/es\/#organization","name":"Casa de Campo Living","url":"https:\/\/casadecampoliving.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","contentUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png?fit=800%2C214&ssl=1","width":800,"height":214,"caption":"Casa de Campo Living"},"image":{"@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casadecampoliving","https:\/\/x.com\/cdcliving"]},{"@type":"Person","@id":"https:\/\/casadecampoliving.com\/es\/#\/schema\/person\/2b2208f3175fa8761e25b272e096d718","name":"Rebecca Silvestri","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d937fd6c1769fb718dbf8dce9e82bf5f89e97bd028f9b3ea10b931dc7df95c6?s=96&d=mm&r=g","caption":"Rebecca Silvestri"},"url":"https:\/\/casadecampoliving.com\/es\/author\/madamehuge\/"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!","url":"http:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?resize=150%2C150&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1"},"articleSection":"Art and Culture","author":[{"@type":"Person","name":"Rebecca Silvestri"}],"creator":["Rebecca Silvestri"],"publisher":{"@type":"Organization","name":"Casa de Campo Living","logo":"https:\/\/casadecampoliving.com\/wp-content\/uploads\/2022\/07\/CDCLivingLogo_V1-white-sized.png"},"keywords":["art gallery","marina casa de campo @es"],"dateCreated":"2009-12-26T04:00:00Z","datePublished":"2009-12-26T04:00:00Z","dateModified":"2022-11-10T14:38:52Z"},"rendered":"<meta name=\"parsely-title\" content=\"Varelli Contemporary art gallery celebrates it&#8217;s 6th Anniversary!\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/casadecampoliving.com\/es\/varelli-contemporary-art-gallery-celebrates-its-6th-anniversary\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?resize=150%2C150&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2009-12-26T04:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Art and Culture\" \/>\n<meta name=\"parsely-tags\" content=\"art gallery,marina casa de campo @es\" \/>\n<meta name=\"parsely-author\" content=\"Rebecca Silvestri\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/casadecampoliving.com\/p.js"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":318097,"url":"https:\/\/casadecampoliving.com\/es\/sexto-anniversario-of-varelli-contemporary-art-saturday-19th-dec\/","url_meta":{"origin":318162,"position":0},"title":"SEXTO ANNIVERSARIO of Varelli, contemporary art &#8211; Saturday 19th Dec","author":"Rebecca Silvestri","date":"16 Dic, 2009","format":false,"excerpt":"This Saturday the 19th of December Varelli, contemporary art showroom is celebrating is 6th anniversary. The event will be held at the Varelli showroom which is located in the Marina Casa de Campo and begins at 7pm. Having attended this 5th anniversary event last year and I can attest that\u2026","rel":"","context":"En \u00abArt and Culture\u00bb","block_context":{"text":"Art and Culture","link":"https:\/\/casadecampoliving.com\/category\/art-and-culture\/"},"img":{"alt_text":"sexto","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/sexto.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":315869,"url":"https:\/\/casadecampoliving.com\/es\/varelli-celebrates-their-5th-anniversary\/","url_meta":{"origin":318162,"position":1},"title":"Varelli Celebrates their 5th Anniversary","author":"Mr B","date":"18 Oct, 2008","format":false,"excerpt":"Celebrating their 5th year bringing art and culture to Casa de Campo\u2019s Marina, Varelli Art Gallery brought out all the stops, showcasing a collection of some of the greatest masters in Dominican Art, including Jhonny Bonelly, Domingo Liz, Quisqueya Henriquez, Radhames Majia, Raquel Paiewonsky, Belkis Ramirez, Jorge Pineda and Fernando\u2026","rel":"","context":"En \u00abArt and Culture\u00bb","block_context":{"text":"Art and Culture","link":"https:\/\/casadecampoliving.com\/category\/art-and-culture\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":321846,"url":"https:\/\/casadecampoliving.com\/save-the-date-fernando-varela-recent-works-paintingsdrawings-cocktail-inauguration-thursday-december-13th\/","url_meta":{"origin":318162,"position":2},"title":"Save the date: \u00abFernando Varela Recent Works &#8211; Paintings\/Drawings\u00bb cocktail inauguration Thursday December 13th","author":"Rebecca Silvestri","date":"3 Dic, 2012","format":false,"excerpt":"Save the date! Internationally\u00a0renowned\u00a0artist and Casa de Campo villa owner Fernando Varela invites you to a cocktail in celebration of the opening of his latest artistic presentation \u201cFernando Varela Recent Works \u2013 Paintings\/Drawings\u201d to be held in the Marina Casa de Campo.\u00a0 Fernando Varela, who for 6 years welcomed Casa\u2026","rel":"","context":"En \u00abArt and Culture\u00bb","block_context":{"text":"Art and Culture","link":"https:\/\/casadecampoliving.com\/category\/art-and-culture\/"},"img":{"alt_text":"fernando varela","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela-1.jpg?fit=650%2C488&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela-1.jpg?fit=650%2C488&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela-1.jpg?fit=650%2C488&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":315866,"url":"https:\/\/casadecampoliving.com\/es\/5th-aniversary-of-varelli-art-gallery\/","url_meta":{"origin":318162,"position":3},"title":"5th Aniversary of Varelli Art Gallery","author":"Mr B","date":"8 Oct, 2008","format":false,"excerpt":"","rel":"","context":"En \u00abArt and Culture\u00bb","block_context":{"text":"Art and Culture","link":"https:\/\/casadecampoliving.com\/category\/art-and-culture\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":316013,"url":"https:\/\/casadecampoliving.com\/es\/art-exhibition-suenos-fragiles-by-fernando-varela\/","url_meta":{"origin":318162,"position":4},"title":"ART EXHIBITION &#8211; Sue\u00f1os Fragiles by Fernando Varela","author":"Mr B","date":"16 Dic, 2008","format":false,"excerpt":"You are hereby cordially invited to come and attend the new exhibition of the talented artist, Fernando Varela, as he showcases some of his works at the VARELLI \u2013 arte contempor\u00e1neo art gallery at the Casa de Campo Marina. The gallery will begin the exhibition, this Saturday 20th of December\u2026","rel":"","context":"En \u00abArt and Culture\u00bb","block_context":{"text":"Art and Culture","link":"https:\/\/casadecampoliving.com\/category\/art-and-culture\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":321903,"url":"https:\/\/casadecampoliving.com\/a-cocktail-to-celebrate-the-opening-of-fernando-varela-recent-works-paintingsdrawings\/","url_meta":{"origin":318162,"position":5},"title":"A cocktail to celebrate the opening of \u201cFernando Varela Recent Works \u2013 Paintings\/Drawings\u201d","author":"Tere Garcia","date":"20 Dic, 2012","format":false,"excerpt":"This past Thursday December 13th 2012, distinguished artist\u00a0Fernando Varela celebrated the\u00a0opening of his new exhibition \u201cFernando Varela Recent Works \u2013 Paintings\/Drawings\u201d at Paseo del Mar #7 at La Marina, Casa de Campo with the support of Silgon Inc. with Casa de Campo Living and Chivas Regal 18. To understand a\u2026","rel":"","context":"En \u00abEvents and Activities\u00bb","block_context":{"text":"Events and Activities","link":"https:\/\/casadecampoliving.com\/category\/events-and-activities\/"},"img":{"alt_text":"fernando varela","src":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela5-1.jpg?fit=650%2C378&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela5-1.jpg?fit=650%2C378&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/fernando_varela5-1.jpg?fit=650%2C378&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/casadecampoliving.com\/wp-content\/uploads\/2022\/10\/art-2-scaled.jpg?fit=2560%2C1600&ssl=1","_links":{"self":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/318162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/comments?post=318162"}],"version-history":[{"count":2,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/318162\/revisions"}],"predecessor-version":[{"id":508465,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/posts\/318162\/revisions\/508465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media\/215947"}],"wp:attachment":[{"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/media?parent=318162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/categories?post=318162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/tags?post=318162"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/casadecampoliving.com\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=318162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}